{"id":96509,"date":"2016-09-27T14:10:14","date_gmt":"2016-09-27T17:10:14","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=96509"},"modified":"2016-09-28T17:02:53","modified_gmt":"2016-09-28T20:02:53","slug":"preso-suspeito-de-estuprar-deficiente-fisico","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/preso-suspeito-de-estuprar-deficiente-fisico\/","title":{"rendered":"Preso suspeito de estuprar deficiente f\u00edsico"},"content":{"rendered":"<p style=\"text-align: justify;\">Agentes da Pol\u00edcia Civil lotados na Delegacia de Indiaroba cumpriram, na tarde da segunda-feira, 26, mandado de pris\u00e3o em desfavor de Cosme Santos Concei\u00e7\u00e3o, 32 anos, conhecido como Gaguinho, pelo crime de estupro. A pris\u00e3o ocorreu no munic\u00edpio de Cristin\u00e1polis.<\/p>\n<div id=\"attachment_96510\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-96510\" class=\"size-full wp-image-96510\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/09\/Presos-por-estuprar-deficiente-SE-Noticias.jpg\" alt=\"A pris\u00e3o ocorreu no munic\u00edpio de Cristin\u00e1polis.\" width=\"600\" height=\"378\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/09\/Presos-por-estuprar-deficiente-SE-Noticias.jpg 600w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/09\/Presos-por-estuprar-deficiente-SE-Noticias-300x189.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/09\/Presos-por-estuprar-deficiente-SE-Noticias-768x484.jpg 768w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/09\/Presos-por-estuprar-deficiente-SE-Noticias-120x76.jpg 120w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/09\/Presos-por-estuprar-deficiente-SE-Noticias-265x168.jpg 265w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/09\/Presos-por-estuprar-deficiente-SE-Noticias-284x180.jpg 284w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/09\/Presos-por-estuprar-deficiente-SE-Noticias-274x173.jpg 274w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/09\/Presos-por-estuprar-deficiente-SE-Noticias-220x140.jpg 220w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-96510\" class=\"wp-caption-text\">A pris\u00e3o ocorreu no munic\u00edpio de Cristin\u00e1polis. (Foto: SSP\/SE)<\/p><\/div>\n<p style=\"text-align: justify;\">\u201cCosme estava foragido da justi\u00e7a. Obtivemos informa\u00e7\u00f5es de seu paradeiro, ent\u00e3o ficamos em campana deste o in\u00edcio da manh\u00e3 e conseguimos efetuar a pris\u00e3o por volta das 17h, quando ele voltava para sua resid\u00eancia na zona rural de Cristin\u00e1polis\u201d, informou o delegado Wanderson Bastos.<\/p>\n<p><strong>O crime<\/strong><\/p>\n<p style=\"text-align: justify;\">O crime ocorreu no m\u00eas de outubro de 2011, quando Cosme Santos Concei\u00e7\u00e3o e o comparsa, Edmilson Concei\u00e7\u00e3o Oliveira, conhecido como Pitbull, estavam bebendo em companhia da v\u00edtima, um deficiente f\u00edsico, no Povoado Muru\u00e7oca, em Indiaroba.<\/p>\n<p style=\"text-align: justify;\">\u201cQuando estavam retornando para casa, Cosme deu uma rasteira e uma pedrada cabe\u00e7a na v\u00edtima e o imobilizou, enquanto Edmilson mantinha rela\u00e7\u00f5es sexuais for\u00e7adamente com a v\u00edtima. Eles se revezavam no ato, mordendo a v\u00edtima por todo corpo, enquanto ela se encontrava inconsciente\u201d, explica o delegado<\/p>\n<p style=\"text-align: justify;\"><strong>Estupradores<\/strong><\/p>\n<p style=\"text-align: justify;\">Segundo o delegado Wanderson Bastos, esta \u00e9 a d\u00e9cima pris\u00e3o de estupradores em sete meses \u2013 per\u00edodo em que ele est\u00e1 como respons\u00e1vel pelas delegacias de Indiaroba e Santa Luzia do Intanhy. Ainda segundo ele, h\u00e1 outros mandados para serem cumpridos relativos ao mesmo crime.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96429\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/09\/Logo-fone-1-4.jpg\" alt=\"logo-fone-1\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/09\/Logo-fone-1-4.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/09\/Logo-fone-1-4-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/p>\n<p style=\"text-align: justify;\"><em><strong>Acompanhe tamb\u00e9m o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\">Twitter<\/a>, <a href=\"https:\/\/www.facebook.com\/senoticias1\">Facebook<\/a> e no <a href=\"https:\/\/www.instagram.com\/senoticias\/\">Instagram<\/a><\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><strong><em>Informa\u00e7\u00f5es da SSP\/SE<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agentes da Pol\u00edcia Civil lotados na Delegacia de Indiaroba cumpriram, na tarde da segunda-feira, 26, mandado de pris\u00e3o em desfavor de Cosme Santos Concei\u00e7\u00e3o, 32 anos, conhecido como Gaguinho, pelo crime de estupro. A pris\u00e3o ocorreu no munic\u00edpio de Cristin\u00e1polis. \u201cCosme estava foragido da justi\u00e7a. Obtivemos informa\u00e7\u00f5es de seu paradeiro, ent\u00e3o ficamos em campana deste [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":96510,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-96509","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/96509"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=96509"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/96509\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/96510"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=96509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=96509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=96509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}