{"id":96450,"date":"2016-09-25T08:50:54","date_gmt":"2016-09-25T11:50:54","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=96450"},"modified":"2016-09-27T07:25:43","modified_gmt":"2016-09-27T10:25:43","slug":"decreto-com-mudancas-no-bolsa-familia-sera-publicado-ate-outubro-diz-ministro","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/decreto-com-mudancas-no-bolsa-familia-sera-publicado-ate-outubro-diz-ministro\/","title":{"rendered":"Decreto com mudan\u00e7as no Bolsa Fam\u00edlia ser\u00e1 publicado at\u00e9 outubro, diz ministro"},"content":{"rendered":"<p style=\"text-align: justify;\">O ministro do Desenvolvimento Social e Agr\u00e1rio, <strong>Osmar Terra<\/strong>, disse nesta sexta-feira (23\/09) que o governo vai publicar at\u00e9 o m\u00eas que vem o decreto que modifica as regras do <strong>Bolsa Fam\u00edlia<\/strong>. A principal mudan\u00e7a ser\u00e1 a manuten\u00e7\u00e3o do benef\u00edcio por dois anos para as pessoas que conseguirem emprego formal.<\/p>\n<div id=\"attachment_92524\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-92524\" class=\"size-full wp-image-92524\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/05\/Bolsa-Familia-SE-Noticias-e1464705858487.jpg\" alt=\"Principal mudan\u00e7a ser\u00e1 a manuten\u00e7\u00e3o do benef\u00edcio por dois anos para as pessoas que conseguirem emprego formal. (Foto: MDS)\" width=\"599\" height=\"403\" \/><p id=\"caption-attachment-92524\" class=\"wp-caption-text\">Principal mudan\u00e7a ser\u00e1 a manuten\u00e7\u00e3o do benef\u00edcio por dois anos para as pessoas que conseguirem emprego formal. (Foto: MDS)<\/p><\/div>\n<article class=\"conteudo\">\n<div>\n<p style=\"text-align: justify;\">Segundo Terra, o benefici\u00e1rio continuar\u00e1 recebendo a assist\u00eancia do programa, junto com o sal\u00e1rio. Ap\u00f3s esse per\u00edodo, seu cart\u00e3o ficar\u00e1 &#8220;hibernando&#8221; para que, no caso de perda do emprego, ele volte a receber o benef\u00edcio. O objetivo do Planalto \u00e9 induzir um salto na formaliza\u00e7\u00e3o do emprego, j\u00e1 que, para n\u00e3o perder o benef\u00edcio, parte dos beneficiados pelo Bolsa Fam\u00edlia se recusa a ter a carteira de trabalho assinada.<\/p>\n<p style=\"text-align: justify;\">Com a transfer\u00eancia de benefici\u00e1rios ao mercado de trabalho formal, o governo aposta que, no m\u00e9dio prazo, conseguir\u00e1 reduzir o n\u00famero de fam\u00edlias assistidas pelo programa, embora n\u00e3o tenha tra\u00e7ado uma meta para isso. Terra, por\u00e9m, pondera que essa diminui\u00e7\u00e3o depender\u00e1 da capacidade da economia de gerar mais empregos.<\/p>\n<p style=\"text-align: justify;\">O ministro disse ainda que o governo pretende premiar, com transfer\u00eancia de recursos a programas sociais, as prefeituras que conseguirem emancipar mais fam\u00edlias do programa. O valor do pr\u00eamio vai depender do tamanho do munic\u00edpio e da propor\u00e7\u00e3o de pessoas que passarem a n\u00e3o depender mais do Bolsa Fam\u00edlia.<\/p>\n<p style=\"text-align: justify;\">&#8220;O Bolsa Fam\u00edlia n\u00e3o vai sofrer nenhuma mudan\u00e7a em sua ess\u00eancia. O que procuramos \u00e9 fazer algumas altera\u00e7\u00f5es que permitam o processo em dire\u00e7\u00e3o \u00e0 autonomia das fam\u00edlias. \u00c9 mais no sentido de ensinar a pescar e n\u00e3o s\u00f3 ficar dando o peixe&#8221;, afirmou Terra, ap\u00f3s participar de debate promovido pelo Insper na capital paulista.<\/p>\n<p style=\"text-align: justify;\">Reda\u00e7\u00e3o, \u00c9poca<\/p>\n<\/div>\n<\/article>\n<div class=\"info-negocios\">\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96429\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/09\/Logo-fone-1-4.jpg\" alt=\"logo-fone-1\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/09\/Logo-fone-1-4.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/09\/Logo-fone-1-4-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/div>\n<div class=\"info-negocios\"><em><strong>\u00a0<\/strong><\/em><\/div>\n<div class=\"info-negocios\"><em><strong>Acompanhe tamb\u00e9m o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\">Twitter<\/a>, <a href=\"https:\/\/www.facebook.com\/senoticias1\">Facebook<\/a> e no <a href=\"https:\/\/www.instagram.com\/senoticias\/\">Instagram<\/a><\/strong><\/em><\/div>\n<div class=\"container-tags\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O ministro do Desenvolvimento Social e Agr\u00e1rio, Osmar Terra, disse nesta sexta-feira (23\/09) que o governo vai publicar at\u00e9 o m\u00eas que vem o decreto que modifica as regras do Bolsa Fam\u00edlia. A principal mudan\u00e7a ser\u00e1 a manuten\u00e7\u00e3o do benef\u00edcio por dois anos para as pessoas que conseguirem emprego formal. Segundo Terra, o benefici\u00e1rio continuar\u00e1 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":92524,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-96450","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/96450"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=96450"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/96450\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/92524"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=96450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=96450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=96450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}