{"id":95849,"date":"2016-09-01T10:40:27","date_gmt":"2016-09-01T13:40:27","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=95849"},"modified":"2016-09-01T10:40:27","modified_gmt":"2016-09-01T13:40:27","slug":"defesa-de-dilma-recorre-ao-supremo-contra-decisao-do-senado","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/defesa-de-dilma-recorre-ao-supremo-contra-decisao-do-senado\/","title":{"rendered":"Defesa de Dilma recorre ao Supremo contra decis\u00e3o do Senado"},"content":{"rendered":"<p style=\"text-align: justify\">A ex-presidente Dilma Rousseff apresentou nesta quinta-feira (1\u00ba) uma a\u00e7\u00e3o no Supremo Tribunal Federal (STF) para anular sua condena\u00e7\u00e3o no impeachment e determinar que o Senado realize uma nova vota\u00e7\u00e3o no processo.<\/p>\n<div id=\"attachment_92596\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/06\/SENot\u00edcias-cardozo-500x375.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-92596\" class=\"size-full wp-image-92596\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/06\/SENot\u00edcias-cardozo-500x375.jpg\" alt=\"Foto: Reprodu\u00e7\u00e3o \/ EBC\" width=\"599\" height=\"449\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/06\/SENot\u00edcias-cardozo-500x375.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/06\/SENot\u00edcias-cardozo-500x375-300x224.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/06\/SENot\u00edcias-cardozo-500x375-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/06\/SENot\u00edcias-cardozo-500x375-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/06\/SENot\u00edcias-cardozo-500x375-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/06\/SENot\u00edcias-cardozo-500x375-269x201.jpg 269w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/a><p id=\"caption-attachment-92596\" class=\"wp-caption-text\">Foto: Reprodu\u00e7\u00e3o \/ EBC<\/p><\/div>\n<p style=\"text-align: justify\">\nProtocolado \u00e0s 9h14 desta quinta, o mandado de seguran\u00e7a foi distribu\u00eddo por sorteio para o ministro Teori Zavascki, que ser\u00e1 o relator do caso. O pedido inclui um pedido de decis\u00e3o liminar (provis\u00f3ria) para suspeder os efeitos da decis\u00e3o desta ter\u00e7a, de modo que o presidente Michel Temer volte a ser interino at\u00e9 uma decis\u00e3o final do STF sobre a a\u00e7\u00e3o. O mandado de seguran\u00e7a \u00e9 um tipo de recurso judicial usado por algu\u00e9m que considera que tem os direitos violados.<\/p>\n<p style=\"text-align: justify\">O ex-ministro e advogado de Dilma, Jos\u00e9 Eduardo Cardozo, j\u00e1 havia informado nesta quarta-feira (31) que iria acionar o STF para contestar o impeachment. Na ocasi\u00e3o, ele disse que as a\u00e7\u00f5es iriam contestar &#8220;irregularidades formais no processo&#8221;.<br \/>\nO impeachment de Dilma foi aprovado pelo plen\u00e1rio do Senado por 61 votos a 20. Ela foi condenada sob a acusa\u00e7\u00e3o de ter cometido crimes de responsabilidade fiscal \u2013 as chamadas &#8220;pedaladas fiscais&#8221; no Plano Safra e os decretos que geraram gastos sem autoriza\u00e7\u00e3o do Congresso Nacional, mas n\u00e3o foi punida com a inabilita\u00e7\u00e3o para fun\u00e7\u00f5es p\u00fablicas. Com isso, ela poder\u00e1 se candidatar para cargos eletivos e tamb\u00e9m exercer outras fun\u00e7\u00f5es na administra\u00e7\u00e3o p\u00fablica.<\/p>\n<p style=\"text-align: justify\">\n<p><strong>Acompanhe tamb\u00e9m o SE Not\u00edcias no<\/strong><strong>\u00a0<\/strong><strong><a href=\"https:\/\/twitter.com\/Senoticias\">Twitter<\/a>,<\/strong><strong>\u00a0<\/strong><strong><a href=\"https:\/\/www.facebook.com\/senoticias1\">Facebook\u00a0<\/a>e no<\/strong><strong>\u00a0<\/strong><strong><a href=\"https:\/\/www.instagram.com\/senoticias\/\">Instagram<\/a><\/strong><\/p>\n<p><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/08\/Logo-fone-1-5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-95789\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/08\/Logo-fone-1-5.jpg\" alt=\"Logo-fone-1\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/08\/Logo-fone-1-5.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/08\/Logo-fone-1-5-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/a><\/p>\n<p>Informa\u00e7\u00f5es Da TV Globo, em Bras\u00edlia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A ex-presidente Dilma Rousseff apresentou nesta quinta-feira (1\u00ba) uma a\u00e7\u00e3o no Supremo Tribunal Federal (STF) para anular sua condena\u00e7\u00e3o no impeachment e determinar que o Senado realize uma nova vota\u00e7\u00e3o no processo. Protocolado \u00e0s 9h14 desta quinta, o mandado de seguran\u00e7a foi distribu\u00eddo por sorteio para o ministro Teori Zavascki, que ser\u00e1 o relator do [&hellip;]<\/p>\n","protected":false},"author":5618,"featured_media":92596,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[1394],"class_list":{"0":"post-95849","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica","8":"tag-defesa-de-dilma-recorre-ao-supremo-contra-decisao-do-senado"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/95849"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/5618"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=95849"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/95849\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/92596"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=95849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=95849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=95849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}