{"id":93480,"date":"2016-06-23T07:36:51","date_gmt":"2016-06-23T10:36:51","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=93480"},"modified":"2016-06-23T16:55:05","modified_gmt":"2016-06-23T19:55:05","slug":"policia-federal-prende-o-ex-ministro-paulo-bernardo-em-brasilia","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/policia-federal-prende-o-ex-ministro-paulo-bernardo-em-brasilia\/","title":{"rendered":"Pol\u00edcia Federal prende o ex-ministro Paulo Bernardo, em Bras\u00edlia"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Adriana Justi e Camila Bomfim, do <a href=\"http:\/\/g1.globo.com\/politica\/operacao-lava-jato\/noticia\/2016\/06\/ex-ministro-paulo-bernardo-e-preso.html\" target=\"_blank\">G1<\/a> PR e da TV Globo em Bras\u00edlia<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">O ex-ministro ministro do Planejamento do governo Lula e das Comunica\u00e7\u00f5es no primeiro governo Dilma Paulo Bernardo foi preso nesta quinta-feira (23) em um desmembramento da 18\u00aa fase da Opera\u00e7\u00e3o Lava Jato, em Bras\u00edlia. A opera\u00e7\u00e3o foi batizada de &#8220;Custo Brasil&#8221; e cumpre 65 mandados judiciais em S\u00e3o Paulo, Paran\u00e1, Rio Grande do Sul, Pernambuco e Distrito Federal.<\/p>\n<div id=\"attachment_93484\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/06\/Paulo-Bernardo-e-Gleisi-SE-Noticias-e1466678371459.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-93484\" class=\"size-full wp-image-93484\" alt=\"O ex-ministro Paulo Bernardo e a senadora Gleisi Hoffman, que s\u00e3o casados. PF cumpre mandado de busca na casa da senadora Gleisi e prendeu o marido dela (Foto: Valter Campanato\/Ag\u00eancia Brasil; Jefferson Rudy\/Ag\u00eancia Senado)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/06\/Paulo-Bernardo-e-Gleisi-SE-Noticias-e1466678371459.jpg\" width=\"599\" height=\"449\" \/><\/a><p id=\"caption-attachment-93484\" class=\"wp-caption-text\">O ex-ministro Paulo Bernardo e a senadora Gleisi Hoffman, que s\u00e3o casados. PF cumpre mandado de busca na casa da senadora Gleisi e prendeu o marido dela (Foto: Valter Campanato\/Ag\u00eancia Brasil; Jefferson Rudy\/Ag\u00eancia Senado)<\/p><\/div>\n<p style=\"text-align: justify;\">Do total de mandados, 11 s\u00e3o de pris\u00e3o preventiva, 40 de busca e apreens\u00e3o e 14\u00a0 de condu\u00e7\u00e3o coercitiva, quando a pessoa \u00e9 levada a prestar depoimento. Um dos mandados de busca est\u00e1 sendo cumprido na casa da da senadora\u00a0Gleisi Hoffmann, no bairro \u00c1gua Verde, em Curitiba.<\/p>\n<p>Policiais federais tamb\u00e9m est\u00e3o na sede do PT no Centro de S\u00e3o Paulo.<\/p>\n<p style=\"text-align: justify;\">A PF informou que a opera\u00e7\u00e3o foi deflagrada para apurar o pagamento de propina referente\u00a0 a contratos de presta\u00e7\u00e3o de servi\u00e7os de inform\u00e1tica no valor de R$ 100 milh\u00f5es entre os anos de 2010 e 2015, a pessoas ligadas a funcion\u00e1rios p\u00fablicos e agentes p\u00fablicos ligados ao Minist\u00e9rio do Planejamento, Or\u00e7amento e Gest\u00e3o (MPOG).<\/p>\n<p style=\"text-align: justify;\">H\u00e1 ind\u00edcios de que o MPOG direcionou a contrata\u00e7\u00e3o de uma empresa de presta\u00e7\u00e3o de servi\u00e7os de tecnologia e inform\u00e1tica para a gest\u00e3o do cr\u00e9dito consignado na folha de pagamento de funcion\u00e1rios p\u00fablicos federais com bancos privados, interessados na concess\u00e3o de cr\u00e9dito consignado, de acordo com as investiga\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">&#8220;Segundo apurou-se, 70% dos valores recebidos por essa empresa eram repassados a pessoas ligadas a funcion\u00e1rios p\u00fablicos ou agentes p\u00fablicos com influ\u00eancia no MPOG por meio de outros contratos &#8211; fict\u00edcios ou simulados&#8221;, diz a PF.<\/p>\n<p style=\"text-align: justify;\">A Pol\u00edcia Federal indiciou Gleisi Hoffmann (PT-PR) e o marido dela, o ex-ministro Paulo Bernardo, ao concluir o inqu\u00e9rito sobre as suspeitas de que dinheiro desviado da Petrobras abasteceu em 2010 a campanha ao Senado da parlamentar.<\/p>\n<p style=\"text-align: justify;\">A defesa do ex-ministro disse que desconhece as raz\u00f5es da pris\u00e3o, e que estranha porque Paulo Bernardo\u00a0sempre se colocou \u00e0 disposi\u00e7\u00e3o das autoridades.<\/p>\n<p style=\"text-align: justify;\">A PF afirma ter ind\u00edcios suficientes contra Gleisi e o marido, o ex-ministro Paulo Bernardo, por suposto envolvimento em crime de corrup\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">As conclus\u00f5es da Pol\u00edcia Federal foram anexadas ao inqu\u00e9rito 3979, que tramita no Supremo Tribunal Federal , na Opera\u00e7\u00e3o Lava Jato.<\/p>\n<p style=\"text-align: justify;\">A PF entendeu que h\u00e1 ind\u00edcios suficientes de que a campanha de Glesi recebeu R$ 1 milh\u00e3o em propina. Um novo delator , Antonio Carlos Pieruccini, informou que transportou o dinheiro, em esp\u00e9cie, de S\u00e3o Paulo para Curitiba em quatro viagens e que entregou a quantia para Ernesto Kugler,\u00a0 empres\u00e1rio que seria pr\u00f3ximo de Gleisi.<\/p>\n<p style=\"text-align: justify;\">Segundo a PF, as entregas ocorreram na casa de Kugler e em empresas das quais \u00e9 s\u00f3cio.<br \/>\nE que o empres\u00e1rio e o ent\u00e3o tesoureiro da campanha de Gleisi, Ronaldo da Silva Baltazar,\u00a0 se falaram por telefone pelo menos 25 vezes.<\/p>\n<p style=\"text-align: justify;\">Segundo o relat\u00f3rio da Pol\u00edcia Federal, ao qual a TV Globo teve acesso, o suposto pedido de dinheiro para a campanha de Gleisi teria sido feito ao ex-diretor da Petrobras Paulo Roberto Costa quando Paulo Bernardo era ministro do Planejamento do governo Lula e s\u00f3 porque o ex-ministro teria conhecimento do esquema de desvios na Petrobras.<\/p>\n<p style=\"text-align: justify;\"><strong>Assessoria contesta<\/strong><\/p>\n<p style=\"text-align: justify;\">A assessoria de imprensa da senadora Gleisi Hoffmann, que responde pelo casal, informou por meio de nota que as provas do inqu\u00e9rito demonstram que ela e o marido n\u00e3o receberam dinheiro<\/p>\n<p style=\"text-align: justify;\">&#8220;Todas as provas que constam no inqu\u00e9rito comprovam que n\u00e3o houve solicita\u00e7\u00e3o, entrega ou recebimento de nenhum valor pela senadora Gleisi Hoffmann ou pelo ex-ministro Paulo Bernardo&#8221;, afirma o texto da nota.<\/p>\n<p style=\"text-align: justify;\">Segundo a assessoria, &#8220;s\u00e3o in\u00fameras as contradi\u00e7\u00f5es nos depoimentos dos delatores, as quais tiram toda a credibilidade das supostas dela\u00e7\u00f5es. Um deles apresentou, nada mais, nada menos, do que cinco vers\u00f5es diferentes para esses fatos, o que comprova ainda mais que eles n\u00e3o existiram&#8221;.<\/p>\n<p style=\"text-align: justify;\"><strong>Indiciamento<\/strong><\/p>\n<p style=\"text-align: justify;\">O indiciamento \u2013 do qual a senadora foi objeto \u2013 \u00e9 previsto em lei somente para inqu\u00e9ritos conduzidos pela pol\u00edcia. O ato de indiciar torna uma pessoa oficialmente suspeita de ter cometido um crime.<\/p>\n<p style=\"text-align: justify;\">Em 2006, o Supremo Tribunal Federal firmou um entendimento pelo qual deputados e senadores n\u00e3o podem ser formalmente indiciados pela pol\u00edcia \u2013 somente podem ser acusados pela Procuradoria Geral da Rep\u00fablica.<\/p>\n<p style=\"text-align: justify;\">A defesa de Gleisi Hoffmann vai questionar o indiciamento da senadora no Supremo a fim de provocar a discuss\u00e3o sobre se a PF pode ou n\u00e3o indiciar.<\/p>\n<p style=\"text-align: justify;\">Atualmente, o Supremo tem uma composi\u00e7\u00e3o diferente da de 2006 e, por essa raz\u00e3o, ap\u00f3s o questionamento da defesa da senadora, h\u00e1 possibilidade de o entendimento vir a ser revisto.<\/p>\n<p style=\"text-align: justify;\"><strong>Dela\u00e7\u00e3o<\/strong><\/p>\n<p style=\"text-align: justify;\">A acusa\u00e7\u00e3o faz parte da dela\u00e7\u00e3o do doleiro Alberto Youssef, que afirmou ter recebido determina\u00e7\u00e3o do ex-diretor Paulo Roberto Costa para entregar R$ 1 milh\u00e3o para a campanha de Gleisi Hoffman do Paran\u00e1.<\/p>\n<p style=\"text-align: justify;\">Isso teria sido feito em um shopping de Curitiba. A quantia teria sido entregue pessoalmente por Yousseff a um homem. Youssef afirmou que Gleisi sabia de todo o esquema. E que\u00a0 Paulo Bernardo pediu um &#8220;aux\u00edlio&#8221; na campanha da mulher.<\/p>\n<p style=\"text-align: justify;\"><strong>Depoimentos<\/strong><\/p>\n<p style=\"text-align: justify;\">Em depoimentos \u00e0 Pol\u00edcia Federal em abril do ano passado, a senadora Gleisi Hoffmann e o marido dela e ex-ministro Paulo Bernardo negaram irregularidades na arrecada\u00e7\u00e3o para a campanha da petista ao Senado em 2010.<\/p>\n<p style=\"text-align: justify;\">Gleisi e Bernardo negaram, ainda, solicita\u00e7\u00f5es de doa\u00e7\u00f5es ao doleiro Alberto Youssef. \u00c0 PF, Paulo Bernardo disse que n\u00e3o fez qualquer pedido de &#8220;aux\u00edlio&#8221; a Costa para a campanha de Gleisi.<\/p>\n<p style=\"text-align: justify;\">Questionado sobre as anota\u00e7\u00f5es &#8220;PB&#8221; e &#8220;1,0&#8221;, encontradas na agenda de Paulo Roberto Costa apreendida pela Pol\u00edcia Federal, o ex-ministro disse n\u00e3o ter conhecimento das anota\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">Em depoimento \u00e0 Justi\u00e7a, Costa afirmou que as anota\u00e7\u00f5es diziam respeito ao valor de R$ 1 milh\u00e3o repassados a Paulo Bernardo para a campanha da petista ao Senado.<\/p>\n<p style=\"text-align: justify;\">Em seu depoimento, Gleisi Hoffmann tamb\u00e9m disse desconhecer as anota\u00e7\u00f5es na agenda de Costa. Ela afirmou ainda que o empres\u00e1rio Ernesto Kugler participou de alguns eventos da campanha de 2010, mas que n\u0103o atuou na capta\u00e7\u00e3o de recursos.<\/p>\n<p style=\"text-align: justify;\"><em><strong>Acompanhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a>,\u00a0<a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram<\/a><\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/06\/Logo-fone.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-93338\" alt=\"Logo fone\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/06\/Logo-fone.jpg\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/06\/Logo-fone.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/06\/Logo-fone-300x39.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/06\/Logo-fone-342x44.jpg 342w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adriana Justi e Camila Bomfim, do G1 PR e da TV Globo em Bras\u00edlia O ex-ministro ministro do Planejamento do governo Lula e das Comunica\u00e7\u00f5es no primeiro governo Dilma Paulo Bernardo foi preso nesta quinta-feira (23) em um desmembramento da 18\u00aa fase da Opera\u00e7\u00e3o Lava Jato, em Bras\u00edlia. A opera\u00e7\u00e3o foi batizada de &#8220;Custo Brasil&#8221; [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":93484,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-93480","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/93480"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=93480"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/93480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/93484"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=93480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=93480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=93480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}