{"id":91580,"date":"2016-05-09T19:01:12","date_gmt":"2016-05-09T22:01:12","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=91580"},"modified":"2016-05-09T20:27:16","modified_gmt":"2016-05-09T23:27:16","slug":"vendas-do-dia-das-maes-caem-84-e-registram-pior-desempenho-desde-2003","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/vendas-do-dia-das-maes-caem-84-e-registram-pior-desempenho-desde-2003\/","title":{"rendered":"Vendas do Dia das M\u00e3es caem 8,4% e registram pior desempenho desde 2003"},"content":{"rendered":"<div id=\"attachment_63119\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/04\/25820111616101.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-63119\" class=\"size-full wp-image-63119\" alt=\"Cal\u00e7ad\u00e3o no Centro de Aracaju (Foto: Reprodu\u00e7\u00e3o) \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/04\/25820111616101.jpg\" width=\"500\" height=\"332\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/04\/25820111616101.jpg 500w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/04\/25820111616101-300x199.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/04\/25820111616101-342x227.jpg 342w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><p id=\"caption-attachment-63119\" class=\"wp-caption-text\">Cal\u00e7ad\u00e3o no Centro de Aracaju (Foto: Reprodu\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">As vendas da semana do Dia das M\u00e3es (2 a 8 de maio) ca\u00edram 8,4% com rela\u00e7\u00e3o ao ano passado e tiveram o pior desempenho desde o in\u00edcio da s\u00e9rie do Indicador Serasa Experian de Atividade do Com\u00e9rcio, em 2003. De acordo com balan\u00e7o divulgado hoje (9), na compara\u00e7\u00e3o com o mesmo fim de semana de 2015o fim de semana da data (6 a 8 de maio) registrou queda de 9,5% em todo o pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">Na cidade de S\u00e3o Paulo, as vendas da semana do Dia das M\u00e3es ca\u00edram 8,2% ante a mesma semana do ano passado. No fim de semana da data, as vendas tiveram queda de 10,6% em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano anterior.<\/p>\n<p style=\"text-align: justify;\">De acordo com os economistas da Serasa Experian, \u201ca queda do poder de compra dos brasileiros, tendo em vista a escalada do desemprego, e a infla\u00e7\u00e3o ainda em patamar elevado, afetaram negativamente o movimento varejista do Dia das M\u00e3es deste ano\u201d. Al\u00e9m disso, eles destacam o cr\u00e9dito mais caro e escasso.<\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe tamb\u00e9m o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a>, <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\/\" target=\"_blank\">Facebook <\/a>e no <a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Fonte: Ag\u00eancia Brasil<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As vendas da semana do Dia das M\u00e3es (2 a 8 de maio) ca\u00edram 8,4% com rela\u00e7\u00e3o ao ano passado e tiveram o pior desempenho desde o in\u00edcio da s\u00e9rie do Indicador Serasa Experian de Atividade do Com\u00e9rcio, em 2003. De acordo com balan\u00e7o divulgado hoje (9), na compara\u00e7\u00e3o com o mesmo fim de semana [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":63119,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[310],"tags":[],"class_list":{"0":"post-91580","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques-da-semana"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/91580"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=91580"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/91580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/63119"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=91580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=91580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=91580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}