{"id":91401,"date":"2016-05-04T17:03:09","date_gmt":"2016-05-04T20:03:09","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=91401"},"modified":"2016-05-04T17:14:20","modified_gmt":"2016-05-04T20:14:20","slug":"juca-de-bala-visita-unidades-de-saude-e-assegura-melhorias-em-laranjeiras","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/juca-de-bala-visita-unidades-de-saude-e-assegura-melhorias-em-laranjeiras\/","title":{"rendered":"Juca de Bala visita unidades de sa\u00fade e assegura melhorias em Laranjeiras"},"content":{"rendered":"<p><b>\u00a0<\/b><\/p>\n<p style=\"text-align: justify;\">Na manh\u00e3 desta quarta-feira, 04, o prefeito Jos\u00e9 de Ara\u00fajo Leite Neto (Juca de Bala) acompanhado da secret\u00e1ria municipal de Sa\u00fade, Rosiane Gomes, visitou as Unidades B\u00e1sicas de Sa\u00fade Francisco Alberto Bragan\u00e7a e Ant\u00f4nio Menezes Leite. J\u00e1 na tarde da \u00faltima ter\u00e7a-feira, 03, o gestor esteve no conjunto Salinas com o objetivo de ver a situa\u00e7\u00e3o do local que est\u00e1 recebendo o mutir\u00e3o do programa \u201cMinha rua de cara nova\u201d.<\/p>\n<div id=\"attachment_91402\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/05\/Prefeito-visitaunidades-de-sa\u00fade-e1462392294370.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-91402\" class=\"size-full wp-image-91402\" alt=\"Prefeito conversa com pacientes e assegura que a sa\u00fade \u00e9 prioridade em Laranjeiras\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/05\/Prefeito-visitaunidades-de-sa\u00fade-e1462392294370.jpg\" width=\"599\" height=\"402\" \/><\/a><p id=\"caption-attachment-91402\" class=\"wp-caption-text\">Prefeito conversa com pacientes e assegura que a sa\u00fade \u00e9 prioridade em Laranjeiras. (Foto: Evaldo Moura\/Ascom\/Laranjeiras)<\/p><\/div>\n<p style=\"text-align: justify;\">Nas primeiras horas da manh\u00e3, Juca esteve na UBS do bairro Tramanda\u00ed, onde conversou com o m\u00e9dico Dr. Carlos Alberto Garcez e com a enfermeira M\u00e1rcia Medrado, al\u00e9m dos Agentes Comunit\u00e1rios de Sa\u00fade (ACS) e usu\u00e1rios da unidade. Durante a visita, o prefeito destacou que a sa\u00fade \u00e9 sua prioridade. \u201cA minha \u00e1rea de sa\u00fade eu preciso valorizar\u201d, disse o gestor.<\/p>\n<p style=\"text-align: justify;\">Logo ap\u00f3s, o gestor visitou a UBS Ant\u00f4nio Menezes Leite, no conjunto Manoel do Prado Franco, onde acompanhou os atendimentos que s\u00e3o realizados na unidade, conversou com usu\u00e1rios e profissionais de sa\u00fade. O objetivo da visita foi vistoriar a funcionalidade da sa\u00fade do munic\u00edpio. \u201cO objetivo \u00e9 ver o funcionamento dos postos, conversar com a popula\u00e7\u00e3o para ver o n\u00edvel de aceita\u00e7\u00e3o dos atendimentos. N\u00f3s temos aqui nos postos atendimentos odontol\u00f3gicos, auxiliar de enfermagem, m\u00e9dico, diversas especialidades e a gente vem verificar se o n\u00edvel de satisfa\u00e7\u00e3o da popula\u00e7\u00e3o est\u00e1 a contento\u201d, disse.<\/p>\n<div id=\"attachment_91404\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/05\/Prefeito-visita-unidades-de-sa\u00fade-e1462392549313.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-91404\" class=\"size-full wp-image-91404\" alt=\"Prefeito de Laranjeiras, Juca de Bala durante toda a tarde desta ter\u00e7a-feira, percorreu Unidades B\u00e1sicas com a inten\u00e7\u00e3o de ouvir os profissionais da sa\u00fade sobre suas necessidades di\u00e1rias necess\u00e1rios para promover um melhor atendimento aos pacientes.(Foto: Evaldo Moura\/Ascom\/Laranjeiras)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/05\/Prefeito-visita-unidades-de-sa\u00fade-e1462392549313.jpg\" width=\"599\" height=\"402\" \/><\/a><p id=\"caption-attachment-91404\" class=\"wp-caption-text\">Prefeito de Laranjeiras, Juca de Bala, percorreu Unidades B\u00e1sicas com a inten\u00e7\u00e3o de ouvir os profissionais da sa\u00fade sobre suas necessidades di\u00e1rias necess\u00e1rios para promover um melhor atendimento aos pacientes. (Foto: Evaldo Moura\/Ascom\/Laranjeiras)<\/p><\/div>\n<p style=\"text-align: justify;\">\u201cNa oportunidade fazemos visita as instala\u00e7\u00f5es f\u00edsicas e dos funcion\u00e1rios. Fiquei satisfeito com a visita de hoje, fomos primeiro a UBS Francisco Alberto Bragan\u00e7a e Ant\u00f4nio Menezes Leite. A gente nota que tem um grande fluxo de pessoas e com o mais importante, todos s\u00e3o atendidos. Sejam crian\u00e7as, adultos, gestantes, idosos, todos s\u00e3o atendidos, os atendimentos da sa\u00fade est\u00e3o a contento aqui na nossa cidade, isso \u00e9 gratificante\u201d, enfatizou o gestor, orgulhoso.<\/p>\n<p style=\"text-align: justify;\"><b>Visita a Salinas<\/b><\/p>\n<p style=\"text-align: justify;\">J\u00e1 na tarde desta ter\u00e7a-feira, 03, o prefeito Juca de Bala visitou o conjunto Salinas, que recebe esta semana o mutir\u00e3o do programa \u201cMinha rua de cara nova\u201d. O gestor explica o objetivo da visita a comunidade. \u201cN\u00f3s estamos com alguns mutir\u00f5es em todas as comunidades, a prefeitura n\u00e3o para, \u00e9 din\u00e2mica. Laranjeiras tem uma s\u00e9rie de demandas, de dificuldades, no tocante a esgoto, a saneamento, a drenagem, a limpeza, ent\u00e3o s\u00e3o nesses lugares mais perif\u00e9ricos que n\u00f3s temos que estar presentes\u201d, explica, Juca.<\/p>\n<p style=\"text-align: justify;\">\u201cEnt\u00e3o est\u00e1 sendo uma rotina e todas as semanas estamos com esses mutir\u00f5es, fazendo rod\u00edzios em toda cidade e l\u00e1 na Salinas foi o dia de ontem, especificamente, e na quinta-feira estaremos l\u00e1 tamb\u00e9m, tratando das quest\u00f5es de esgoto, saneamento, drenagem, limpeza urbana e conversando com a comunidade que \u00e9 o mais importante, escutar o povo e estar pr\u00f3ximo a eles levando as solu\u00e7\u00f5es para uma vida melhor\u201d, conclui o prefeito.<\/p>\n<p style=\"text-align: justify;\"><strong><em>Acompanhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a>,\u00a0<a href=\"https:\/\/www.facebook.com\/PortalSENoticias\/\" target=\"_blank\">Facebook\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram<\/a><\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><em>Da Ascom \/Laranjeiras<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Na manh\u00e3 desta quarta-feira, 04, o prefeito Jos\u00e9 de Ara\u00fajo Leite Neto (Juca de Bala) acompanhado da secret\u00e1ria municipal de Sa\u00fade, Rosiane Gomes, visitou as Unidades B\u00e1sicas de Sa\u00fade Francisco Alberto Bragan\u00e7a e Ant\u00f4nio Menezes Leite. J\u00e1 na tarde da \u00faltima ter\u00e7a-feira, 03, o gestor esteve no conjunto Salinas com o objetivo de ver [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":91402,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":{"0":"post-91401","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/91401"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=91401"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/91401\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/91402"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=91401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=91401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=91401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}