{"id":90884,"date":"2016-04-19T14:25:45","date_gmt":"2016-04-19T17:25:45","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=90884"},"modified":"2016-04-20T09:55:36","modified_gmt":"2016-04-20T12:55:36","slug":"mendonca-prado-assume-presidencia-da-agrese","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/mendonca-prado-assume-presidencia-da-agrese\/","title":{"rendered":"Mendon\u00e7a Prado assume presid\u00eancia da Agrese"},"content":{"rendered":"<p style=\"text-align: justify;\">O governador Jackson Barreto empossou no final da tarde desta segunda-feira, 18, no Pal\u00e1cio de Despachos, o ex-secret\u00e1rio de Estado da Seguran\u00e7a P\u00fablica, Mendon\u00e7a Prado, na presid\u00eancia da Ag\u00eancia Reguladora de Servi\u00e7os do Estado de Sergipe (Agrese), em substitui\u00e7\u00e3o ao ex-prefeito Edvaldo Nogueira, que entregou o cargo h\u00e1 15 dias. Compareceram ao ato, o vice-governador Belivaldo Chagas, o secret\u00e1rio de Estado da Comunica\u00e7\u00e3o, Jos\u00e9 Sales Neto e os assessores da Ag\u00eancia, Augusto Ferrari e Hamilton Santana.<\/p>\n<div id=\"attachment_90885\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/04\/Governador-empossa-Mendon\u00e7a-Prado-na-Agrese-e1461086690624.jpeg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-90885\" class=\"size-full wp-image-90885\" alt=\"Mendon\u00e7a Prado afirmou que pretende modernizar e ampliar as a\u00e7\u00f5es da Agrese com o intu\u00eddo de melhorar os servi\u00e7os que as concession\u00e1rias prestam \u00e0 popula\u00e7\u00e3o\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/04\/Governador-empossa-Mendon\u00e7a-Prado-na-Agrese-e1461086690624.jpeg\" width=\"599\" height=\"400\" \/><\/a><p id=\"caption-attachment-90885\" class=\"wp-caption-text\">Mendon\u00e7a Prado afirmou que pretende modernizar e ampliar as a\u00e7\u00f5es da Agrese com o intu\u00eddo de melhorar os servi\u00e7os que as concession\u00e1rias prestam \u00e0 popula\u00e7\u00e3o. (Foto: Victor Ribeiro\/ASN)<\/p><\/div>\n<p style=\"text-align: justify;\">O governador deu as boas vindas a Mendon\u00e7a Prado neste novo cargo e pediu que a equipe comece a estudar a possibilidade de amplia\u00e7\u00e3o dos trabalhos da Ag\u00eancia. A Agrese tem a fun\u00e7\u00e3o de regulamentar as concess\u00f5es que s\u00e3o concedidas pelo Estado, como saneamento b\u00e1sico, transporte e g\u00e1s canalizado. No momento, a Ag\u00eancia est\u00e1 trabalhando com a regulamenta\u00e7\u00e3o do g\u00e1s.<\/p>\n<p style=\"text-align: justify;\">Mendon\u00e7a Prado afirmou que pretende modernizar e ampliar as a\u00e7\u00f5es da Agrese com o objetivo de melhorar os servi\u00e7os que as concession\u00e1rias prestam \u00e0 popula\u00e7\u00e3o.<\/p>\n<p><em><strong>Acompanhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/\" target=\"_blank\">Twitter<\/a>,\u00a0<a href=\"https:\/\/www.facebook.com\/senoticias1\/\" target=\"_blank\">Facebook\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram<\/a><\/strong><\/em><\/p>\n<p><strong><em>Ag\u00eancia Sergipe de Not\u00edcias<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Jackson Barreto empossou no final da tarde desta segunda-feira, 18, no Pal\u00e1cio de Despachos, o ex-secret\u00e1rio de Estado da Seguran\u00e7a P\u00fablica, Mendon\u00e7a Prado, na presid\u00eancia da Ag\u00eancia Reguladora de Servi\u00e7os do Estado de Sergipe (Agrese), em substitui\u00e7\u00e3o ao ex-prefeito Edvaldo Nogueira, que entregou o cargo h\u00e1 15 dias. Compareceram ao ato, o vice-governador [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":90885,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-90884","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/90884"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=90884"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/90884\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/90885"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=90884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=90884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=90884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}