{"id":90873,"date":"2016-04-19T09:38:22","date_gmt":"2016-04-19T12:38:22","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=90873"},"modified":"2016-04-19T22:18:26","modified_gmt":"2016-04-20T01:18:26","slug":"lider-de-associacao-criminosa-e-morto-em-confronto-com-policiais-no-olaria","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/lider-de-associacao-criminosa-e-morto-em-confronto-com-policiais-no-olaria\/","title":{"rendered":"Morto em confronto com a pol\u00edcia, l\u00edder de associa\u00e7\u00e3o criminosa de Nossa Senhora das Dores"},"content":{"rendered":"<p style=\"text-align: justify;\">Uma opera\u00e7\u00e3o realizada na manh\u00e3 desta ter\u00e7a-feira, 19, no bairro Olaria, pelos agentes da Delegacia Regional de Nossa Senhora das Dores, em parceria com policiais da Divis\u00e3o de Intelig\u00eancia e Planejamento Policial (DIPOL), Grupo Especial de Repress\u00e3o e Buscas (GERB) e Departamento de Narc\u00f3ticos (Denarc), culminou na morte de Josivan Souza Ferreira, mais conhecido como &#8220;Gago ou Vanzinho&#8221;, durante confronto com os policiais. Ele era acusado de ser o l\u00edder de uma associa\u00e7\u00e3o criminosa que atuava na cidade de Dores e regi\u00e3o.<\/p>\n<div id=\"attachment_90874\" style=\"width: 517px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/04\/L\u00edder-de-associa\u00e7\u00e3o-criminosa-\u00e9-morto-em-confronto-com-policiais-no-Olaria.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-90874\" class=\"size-full wp-image-90874\" alt=\"No local, foram apreendidos dois rev\u00f3lveres, muni\u00e7\u00f5es de diversos calibres, al\u00e9m de certa quantia em esp\u00e9cie. (Foto: SSP\/SE)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/04\/L\u00edder-de-associa\u00e7\u00e3o-criminosa-\u00e9-morto-em-confronto-com-policiais-no-Olaria.jpg\" width=\"507\" height=\"380\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/04\/L\u00edder-de-associa\u00e7\u00e3o-criminosa-\u00e9-morto-em-confronto-com-policiais-no-Olaria.jpg 507w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/04\/L\u00edder-de-associa\u00e7\u00e3o-criminosa-\u00e9-morto-em-confronto-com-policiais-no-Olaria-300x224.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/04\/L\u00edder-de-associa\u00e7\u00e3o-criminosa-\u00e9-morto-em-confronto-com-policiais-no-Olaria-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/04\/L\u00edder-de-associa\u00e7\u00e3o-criminosa-\u00e9-morto-em-confronto-com-policiais-no-Olaria-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/04\/L\u00edder-de-associa\u00e7\u00e3o-criminosa-\u00e9-morto-em-confronto-com-policiais-no-Olaria-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/04\/L\u00edder-de-associa\u00e7\u00e3o-criminosa-\u00e9-morto-em-confronto-com-policiais-no-Olaria-269x201.jpg 269w\" sizes=\"(max-width: 507px) 100vw, 507px\" \/><\/a><p id=\"caption-attachment-90874\" class=\"wp-caption-text\">No local, foram apreendidos dois rev\u00f3lveres, muni\u00e7\u00f5es de diversos calibres, al\u00e9m de certa quantia em esp\u00e9cie. (Foto: SSP\/SE)<\/p><\/div>\n<p style=\"text-align: justify;\">Segundo o delegado Fabio Santana, coordenador da opera\u00e7\u00e3o, a a\u00e7\u00e3o se deu em virtude de cumprimento de mandado de pris\u00e3o em desfavor de Josivan, autor de diversos crimes de roubos na regi\u00e3o. &#8220;De acordo com as investiga\u00e7\u00f5es, descobrimos que &#8220;Vanzinho&#8221; seria o l\u00edder de uma associa\u00e7\u00e3o criminosa. Ele era respons\u00e1vel por planejar e executar as a\u00e7\u00f5es do bando. Durante as investiga\u00e7\u00f5es, descobrimos que ele estaria escondido na resid\u00eancia de sua namorada, situada no bairro Olaria, em Aracaju. De posse dessas informa\u00e7\u00f5es, empreendemos dilig\u00eancias at\u00e9 o local para efetuar a pris\u00e3o do acusado&#8221;, explicou o delegado.<\/p>\n<p style=\"text-align: justify;\">Ao chegarem ao local indicado, os policiais deram ordem de pris\u00e3o ao acusado, que reagiu efetuando v\u00e1rios disparos de arma de fogo. No confronto, &#8220;Vanzinho&#8221; acabou alvejado e posteriormente conduzido ao Hospital de Urg\u00eancia de Sergipe para atendimento m\u00e9dico, entretanto, ele n\u00e3o resistiu aos ferimentos e veio a \u00f3bito. No local, foram apreendidos dois rev\u00f3lveres, muni\u00e7\u00f5es de diversos calibres, al\u00e9m de certa quantia em esp\u00e9cie.<\/p>\n<p style=\"text-align: justify;\">Ainda conforme F\u00e1bio Santana, as investiga\u00e7\u00f5es continuam no intuito de localizar os outros integrantes da organiza\u00e7\u00e3o criminosa, que continuam foragidos: &#8220;conseguimos identificar cerca de seis pessoas que t\u00eam participa\u00e7\u00e3o nos crimes comandados por Josivan. Agora vamos continuar os trabalhos a fim de efetuar a pris\u00e3o dos demais integrantes&#8221;.<\/p>\n<p style=\"text-align: justify;\"><em><strong>\u00a0Acompanhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/\" target=\"_blank\">Twitter<\/a>,\u00a0<a href=\"https:\/\/www.facebook.com\/senoticias1\/\" target=\"_blank\">Facebook\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram<\/a><\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><strong><em>Informa\u00e7\u00f5es da SSP\/SE<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma opera\u00e7\u00e3o realizada na manh\u00e3 desta ter\u00e7a-feira, 19, no bairro Olaria, pelos agentes da Delegacia Regional de Nossa Senhora das Dores, em parceria com policiais da Divis\u00e3o de Intelig\u00eancia e Planejamento Policial (DIPOL), Grupo Especial de Repress\u00e3o e Buscas (GERB) e Departamento de Narc\u00f3ticos (Denarc), culminou na morte de Josivan Souza Ferreira, mais conhecido como [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":90874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-90873","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/90873"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=90873"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/90873\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/90874"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=90873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=90873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=90873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}