{"id":90732,"date":"2016-04-15T10:43:56","date_gmt":"2016-04-15T13:43:56","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=90732"},"modified":"2016-04-15T10:50:52","modified_gmt":"2016-04-15T13:50:52","slug":"agricultores-do-quissama-participam-da-feira-da-agricultura-familiar","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/agricultores-do-quissama-participam-da-feira-da-agricultura-familiar\/","title":{"rendered":"Agricultores do Quissam\u00e3 participam da Feira da Agricultura Familiar"},"content":{"rendered":"<p style=\"text-align: justify;\">Agricultores do assentamento Moacir Wanderley, localizado no povoado Quissam\u00e3, munic\u00edpio de Nossa Senhora do Socorro, participaram pela primeira vez da Feira da Agricultura Familiar, realizada no p\u00e1tio da Secretaria da Mulher, Inclus\u00e3o e Assist\u00eancia Social, do Trabalho e dos Direitos Humanos (Seidh), nesta quinta-feira, 14. Os agricultores da comunidade fazem parte de um projeto de agricultura urbana e periurbana implantado pela Seidh, atrav\u00e9s do Departamento de Seguran\u00e7a Alimentar e Nutricional (DSAN), que oferece suporte na produ\u00e7\u00e3o de alimentos org\u00e2nicos em hortas.<\/p>\n<div id=\"attachment_90734\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/04\/SENOTICIAS-FEIRA-DA-AGRICULTURA-FAMULIAR-FOTO-JADILSON-SIMOES-140416-13-e1460728150228.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-90734\" class=\"size-full wp-image-90734\" alt=\"Agricultores do Quissam\u00e3 participam da Feira da Agricultura Familiar. (Foto: Jadilson Sim\u00f5es)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/04\/SENOTICIAS-FEIRA-DA-AGRICULTURA-FAMULIAR-FOTO-JADILSON-SIMOES-140416-13-e1460728150228.jpg\" width=\"599\" height=\"398\" \/><\/a><p id=\"caption-attachment-90734\" class=\"wp-caption-text\">Agricultores do Quissam\u00e3 participam da Feira da Agricultura Familiar. (Foto: Jadilson Sim\u00f5es)<\/p><\/div>\n<p style=\"text-align: justify;\">A diretora do DSAN, Lucileide Rodrigues, explica que a iniciativa surgiu devido \u00e0 necessidade de solucionar dificuldades existentes na comunidade, al\u00e9m de otimizar a incentivar a agricultura org\u00e2nica, por meio de hortas. \u201cEsse projeto \u00e9 de 2011 e, no ano passado, conseguimos concretiz\u00e1-lo. Hoje, al\u00e9m da estufa e das hortas, tamb\u00e9m temos um mini-ind\u00fastria para a produ\u00e7\u00e3o de doces e alimentos processados, que vai come\u00e7ar a funcionar. O objetivo \u00e9 que eles plantem para consumo e para venda\u201d.<\/p>\n<p style=\"text-align: justify;\">Ainda de acordo com Lucileide, a Secretaria tamb\u00e9m disponibiliza o material para viabilizar o trabalho dos agricultores org\u00e2nicos. \u201cOfertamos estrumo, areia preta, sementes, mudas de frutas, produtos de irriga\u00e7\u00e3o, aventais, luvas e o que vier a ser necess\u00e1rio. Tamb\u00e9m prestamos assist\u00eancia t\u00e9cnica para auxiliar na orienta\u00e7\u00e3o e monitoramento do servi\u00e7o. Vamos ao assentamento semanalmente ou, no m\u00e1ximo, quinzenalmente, para verificar a planta\u00e7\u00e3o. Eles tamb\u00e9m recebem capacita\u00e7\u00e3o de como fazer o processamento desses alimentos. \u00c9 um meio que ajuda na gera\u00e7\u00e3o de renda\u201d, destacou.<\/p>\n<p style=\"text-align: justify;\">Para a agricultora Luci Cl\u00e1udia Alvez, a participa\u00e7\u00e3o na Feira da Agricultura Familiar trouxe um resultado significativo. De acordo com ela, antes do in\u00edcio dessa parceria, os trabalhadores n\u00e3o tinham onde vender. \u201cProduzimos cheiro verde, alface, maxixe, coentro e outras hortali\u00e7as. Isso \u00e9 muito bom e esperamos vir mais vezes. Quando a mini-ind\u00fastria estiver em funcionando, iremos vender os doces aqui tamb\u00e9m. \u00c9 um \u00f3timo beneficiamento para o nosso desenvolvimento\u201d, disse.<\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe tamb\u00e9m o SEnot\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/\" target=\"_blank\">Twitter<\/a>,\u00a0<a href=\"https:\/\/www.facebook.com\/senoticias1\/\" target=\"_blank\">Facebook<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.instagram.com\/\" target=\"_blank\">Instagram<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><em>Assessoria de Comunica\u00e7\u00e3o\u00a0<\/em><\/strong><br \/>\n<strong><em>Secretaria de Estado da Mulher, da Inclus\u00e3o e Assist\u00eancia Social, do Trabalho e dos Direitos Humanos &#8211; SEIDH\u00a0<\/em><\/strong><br \/>\n<strong><em>Governo de Sergipe\u00a0<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agricultores do assentamento Moacir Wanderley, localizado no povoado Quissam\u00e3, munic\u00edpio de Nossa Senhora do Socorro, participaram pela primeira vez da Feira da Agricultura Familiar, realizada no p\u00e1tio da Secretaria da Mulher, Inclus\u00e3o e Assist\u00eancia Social, do Trabalho e dos Direitos Humanos (Seidh), nesta quinta-feira, 14. Os agricultores da comunidade fazem parte de um projeto de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":90734,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,1],"tags":[],"class_list":{"0":"post-90732","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios","8":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/90732"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=90732"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/90732\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/90734"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=90732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=90732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=90732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}