{"id":90659,"date":"2016-04-13T12:03:09","date_gmt":"2016-04-13T15:03:09","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=90659"},"modified":"2016-04-14T13:51:44","modified_gmt":"2016-04-14T16:51:44","slug":"policia-federal-investiga-quadrilha-de-fraudadores-em-obtencao-de-registros-no-conselho-regional-de-medicina","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/policia-federal-investiga-quadrilha-de-fraudadores-em-obtencao-de-registros-no-conselho-regional-de-medicina\/","title":{"rendered":"Pol\u00edcia Federal investiga quadrilha de fraudadores  em obten\u00e7\u00e3o de Registros no Conselho Regional de Medicina"},"content":{"rendered":"<p style=\"text-align: justify;\">Na tarde do dia de ontem, dia 12, por volta da 15h30m, a Pol\u00edcia Federal foi acionada\u00a0pelo Conselho Regional de Medicina com a informa\u00e7\u00e3o de que duas pessoas estariam\u00a0tentando obter mediante fraude a Carteira de Identidade Profissional junto ao CRM.\u00a0Segundo informa\u00e7\u00e3o, um casal teria ido \u00e0 sede do Conselho Regional de Medicina em\u00a0Sergipe para tentar obter o Registro Profissional, todavia, ap\u00f3s o procedimento padr\u00e3o,\u00a0ficou verificado que se tratava de uma fraude. O casal apresentou toda a documenta\u00e7\u00e3o\u00a0necess\u00e1ria para a obten\u00e7\u00e3o do registro, inclusive realizando pagamentos da anuidade e\u00a0da taxa de inscri\u00e7\u00e3o.<\/p>\n<div id=\"attachment_90663\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/04\/SENOTICIAS-REGISTRO-e1460562976701.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-90663\" class=\"size-full wp-image-90663\" alt=\"Pol\u00edcia Federal investiga quadrilha de fraudadores em obten\u00e7\u00e3o de Registros no Conselho Regional de Medicina\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/04\/SENOTICIAS-REGISTRO-e1460562976701.jpg\" width=\"599\" height=\"256\" \/><\/a><p id=\"caption-attachment-90663\" class=\"wp-caption-text\">Pol\u00edcia Federal investiga quadrilha de fraudadores em obten\u00e7\u00e3o de Registros no Conselho Regional de Medicina. (Foto: meramente ilustrativa\/Net)<\/p><\/div>\n<p style=\"text-align: justify;\">A constata\u00e7\u00e3o ocorreu ap\u00f3s o CRM\/SE confirmar junto \u00e0 Universidade do Sul de Santa\u00a0Catarina, que o casal n\u00e3o era formado por esta institui\u00e7\u00e3o, a qual constava nos diplomas\u00a0apresentados para a obten\u00e7\u00e3o dos registros, pois teria recebido anteriormente um e-mail\u00a0falso origin\u00e1rio da Universidade que constava o nome do casal investigado.<\/p>\n<p style=\"text-align: justify;\">Em depoimento \u00e0 Policia Federal, o casal informou que eram m\u00e9dicos formados na\u00a0Universidade Saint Paul na Bol\u00edvia e estavam tentando validar o diploma no Brasil,\u00a0sendo que para tanto teriam pago o valor de R$ 115.000,00 a um suposto facilitador e\u00a0que foram orientados por este, para fazer o requerimento junto ao CRM em Sergipe,\u00a0com a apresenta\u00e7\u00e3o de diploma falso.<\/p>\n<p style=\"text-align: justify;\">A dupla responder\u00e1 pelo crime de estelionato, previsto no artigo 171,\u00a72\u00ba do C\u00f3digo\u00a0Penal, com pena prevista de um a seis anos e meio e multa.<\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe tamb\u00e9m o SEnot\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/\" target=\"_blank\">Twitter<\/a>,\u00a0<a href=\"https:\/\/www.facebook.com\/senoticias1\/\" target=\"_blank\">Facebook<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.instagram.com\/\" target=\"_blank\">Instagram<\/a><\/strong><\/p>\n<p><strong>Comunica\u00e7\u00e3o Social \/\u00a0Pol\u00edcia Federal em Sergipe<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na tarde do dia de ontem, dia 12, por volta da 15h30m, a Pol\u00edcia Federal foi acionada\u00a0pelo Conselho Regional de Medicina com a informa\u00e7\u00e3o de que duas pessoas estariam\u00a0tentando obter mediante fraude a Carteira de Identidade Profissional junto ao CRM.\u00a0Segundo informa\u00e7\u00e3o, um casal teria ido \u00e0 sede do Conselho Regional de Medicina em\u00a0Sergipe para tentar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":90663,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[310,7],"tags":[],"class_list":{"0":"post-90659","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques-da-semana","8":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/90659"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=90659"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/90659\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/90663"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=90659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=90659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=90659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}