{"id":89468,"date":"2016-03-07T19:21:22","date_gmt":"2016-03-07T22:21:22","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=89468"},"modified":"2016-03-07T21:34:52","modified_gmt":"2016-03-08T00:34:52","slug":"marcio-macedo-oposicao-midia-e-setores-da-pf-mp-e-judiciario-querem-inviabilizar-lula","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/marcio-macedo-oposicao-midia-e-setores-da-pf-mp-e-judiciario-querem-inviabilizar-lula\/","title":{"rendered":"M\u00e1rcio Mac\u00eado: &#8216;oposi\u00e7\u00e3o, m\u00eddia e setores da PF, MP e Judici\u00e1rio querem inviabilizar Lula&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\">O secret\u00e1rio nacional de Finan\u00e7as do PT, M\u00e1rcio Mac\u00eado, afirmou, nesta segunda-feira (7), que h\u00e1 uma \u201cuma a\u00e7\u00e3o sincronizada\u201d da oposi\u00e7\u00e3o, de setores do Judici\u00e1rio, do Minist\u00e9rio P\u00fablico e da Pol\u00edcia Federal e dos grandes conglomerados de m\u00eddia contra o ex-presidente Lula para tentar impedi-lo de disputar a Presid\u00eancia novamente em 2018. Para o petista, a condu\u00e7\u00e3o coercitiva do ex-presidente, que ocorreu na semana passada, dentro da Opera\u00e7\u00e3o Lava Jato, foi um \u201cabuso\u201d e um golpe contra a democracia.<\/p>\n<p style=\"text-align: justify;\">\u201cQue as pessoas possam refletir sobre o que ocorre no pa\u00eds neste momento. Existe um golpe em marcha. O que ocorreu com Lula na \u00faltima sexta-feira foi um teste para ver se teria rea\u00e7\u00e3o popular, al\u00e9m de ter sido uma tentativa de influenciar a decis\u00e3o do Supremo Tribunal Federal sobre o pedido feito pelo ex-presidente de manter a investiga\u00e7\u00e3o sobre ele no Minist\u00e9rio P\u00fablico de S\u00e3o Paulo. A condu\u00e7\u00e3o coercitiva de Lula foi um abuso de autoridade, um sequestro, um exagero, para tentar desmoralizar o maior l\u00edder popular deste pa\u00eds. O que est\u00e1 em jogo no pa\u00eds n\u00e3o \u00e9 Lula, nem o PT, mas sim a jovem democracia brasileira, o respeito \u00e0s leis e \u00e0s liberdades individuais\u201d, afirmou ele em entrevista \u00e0 r\u00e1dio 103 FM.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_39661\" style=\"width: 556px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/09\/foto22.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-39661\" class=\"size-full wp-image-39661\" alt=\"Ex-deputado de Sergipe, M\u00e1rcio Macedo.(Foto?Divulga\u00e7\u00e3o)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/09\/foto22.jpg\" width=\"546\" height=\"819\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/09\/foto22.jpg 546w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/09\/foto22-200x300.jpg 200w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/09\/foto22-342x513.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/09\/foto22-300x450.jpg 300w\" sizes=\"(max-width: 546px) 100vw, 546px\" \/><\/a><p id=\"caption-attachment-39661\" class=\"wp-caption-text\">Ex-deputado de Sergipe, M\u00e1rcio Macedo.(Foto?Divulga\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">Ele ressaltou que n\u00e3o est\u00e1 defendendo privil\u00e9gios para Lula, mas pontuou que a lei precisa ser respeitada, o que no caso do ex-presidente n\u00e3o ocorreu, uma vez que ele foi levado coercitivamente para prestar um depoimento, antes mesmo de uma intima\u00e7\u00e3o. \u201cNingu\u00e9m est\u00e1 acima da lei, nem tamb\u00e9m o juiz. O juiz que est\u00e1 com a toga e tem o poder de exercitar a lei n\u00e3o pode rasgar a Constitui\u00e7\u00e3o brasileira\u201d, ressaltou.<\/p>\n<p style=\"text-align: justify;\">Para o representante do PT, o Brasil vive um momento de acirrada disputa pol\u00edtica, que tem criado um clima de confronto de classe. \u201cIsso quebra a cordialidade brasileira e divide o pa\u00eds ao meio. Isso est\u00e1 sendo feito pela grande m\u00eddia em acordo com a oposi\u00e7\u00e3o, que n\u00e3o tem projeto, nem for\u00e7a eleitoral e quer impedir Lula de disputar 2018\u201d, pontuou.<\/p>\n<p style=\"text-align: justify;\">O petista alertou que \u201cos atos de \u00f3dio, intoler\u00e2ncia e falta de respeito que ocorrerem daqui para frente ser\u00e1 de responsabilidade dos grandes conglomerados de comunica\u00e7\u00e3o, dos partidos de oposi\u00e7\u00e3o e de setores da Justi\u00e7a, do MP e da PF que est\u00e3o criando um estado de exce\u00e7\u00e3o dentro do estado de direito\u201d.<\/p>\n<p style=\"text-align: justify;\">M\u00e1rcio Mac\u00eado destacou que a maioria da popula\u00e7\u00e3o brasileira desaprovou o modo como se deu a condu\u00e7\u00e3o coercitiva de Lula. Ele citou os dados divulgados pelo instituto de pesquisas Vox Populi. \u201cA pesquisa mostrou que o Brasil reprovou, que houve um exagero. 56% dos brasileiros desaprovaram a inclus\u00e3o de Lula na Lava Jato e 43% desaprovaram a conduta do juiz S\u00e9rgio Moro. 65% viram exagero na condu\u00e7\u00e3o coercitiva e 57% disseram acreditar na palavra de Lula\u201d, destacou.<\/p>\n<p style=\"text-align: justify;\">Ele elogiou o posicionamento do governador Jackson Barreto contra o golpe e destacou o ato realizado pelo PT e pelos movimentos sociais e centrais sindicais em Aracaju. &#8220;Nesse epis\u00f3dio me impressionou e me emocionou a capacidade de rea\u00e7\u00e3o do PT e dos movimentos sociais que dialogam conosco. Mais de mil cidades fizeram manifesta\u00e7\u00f5es de apoio. Aqui em Sergipe, o PT deu demonstra\u00e7\u00e3o de muita unidade junto aos movimentos sociais e aos companheiros da Frente Brasil Popular, CUT, MST, CNP. O ato de Sergipe foi muito significativo na defesa da democracia e no desagravo a Lula Fiquei orgulhoso tamb\u00e9m em ver o governador Jackson Barreto ser um dos primeiros gestores a condenar os excessos da Lava Jato&#8221;, disse.<\/p>\n<p style=\"text-align: justify;\">O secret\u00e1rio de Finan\u00e7as do PT anunciou que haver\u00e1 ao longo de mar\u00e7o uma s\u00e9rie de atos em defesa da democracia em todo o pa\u00eds. O primeiro dia de manifesta\u00e7\u00f5es \u00e9 nesta ter\u00e7a-feira (8), durante as comemora\u00e7\u00f5es pelo Dia da Mulheres. Outros protestos ocorrer\u00e3o nos dias 18 e 31 deste m\u00eas. No m\u00eas que vem, segundo informou M\u00e1rcio Mac\u00eado, o ex-presidente viajar\u00e1 todo o pa\u00eds para dialogar com a popula\u00e7\u00e3o sobre o que est\u00e1 ocorrendo. \u201cN\u00e3o deixam alternativa a Lula que n\u00e3o seja pedir apoio ao povo\u201d, justificou. Lula come\u00e7ar\u00e1 viajando pelo Nordeste.<\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><em><strong>Da Assessoria de Imprensa<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O secret\u00e1rio nacional de Finan\u00e7as do PT, M\u00e1rcio Mac\u00eado, afirmou, nesta segunda-feira (7), que h\u00e1 uma \u201cuma a\u00e7\u00e3o sincronizada\u201d da oposi\u00e7\u00e3o, de setores do Judici\u00e1rio, do Minist\u00e9rio P\u00fablico e da Pol\u00edcia Federal e dos grandes conglomerados de m\u00eddia contra o ex-presidente Lula para tentar impedi-lo de disputar a Presid\u00eancia novamente em 2018. Para o petista, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":39661,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,1],"tags":[],"class_list":{"0":"post-89468","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica","8":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/89468"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=89468"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/89468\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/39661"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=89468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=89468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=89468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}