{"id":88929,"date":"2016-02-19T08:21:30","date_gmt":"2016-02-19T11:21:30","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=88929"},"modified":"2016-02-19T08:21:50","modified_gmt":"2016-02-19T11:21:50","slug":"acusado-de-latrocinio-e-preso-em-salgado","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/acusado-de-latrocinio-e-preso-em-salgado\/","title":{"rendered":"Acusado de latroc\u00ednio \u00e9 preso em Salgado"},"content":{"rendered":"<div id=\"attachment_88930\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/02\/salgado.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-88930\" class=\"size-medium wp-image-88930\" alt=\"Robson Loureiro Doria, 43 anos.\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/02\/salgado-300x244.jpg\" width=\"300\" height=\"244\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/02\/salgado-300x244.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/02\/salgado-342x278.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/02\/salgado.jpg 467w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-88930\" class=\"wp-caption-text\">Robson Loureiro Dorea, 43 anos. (Foto: SSP\/SE)<\/p><\/div>\n<p style=\"text-align: justify;\">Policiais civis da Delegacia Regional de Lagarto efetuaram nessa quinta-feira, 18, a pris\u00e3o de Robson Loureiro Doria, 43 anos, em cumprimento a um mandado de pris\u00e3o pelo crime de latroc\u00ednio (roubo seguido de morte) contra Adelson Bispo de Andrade, cometido em 2006. A a\u00e7\u00e3o ocorreu no munic\u00edpio de Salgado, distante 50 km da capital sergipana.<\/p>\n<p style=\"text-align: justify;\">Segundo os agentes, na \u00e9poca o crime teria chocado a popula\u00e7\u00e3o, pois a v\u00edtima era uma pessoa querida. \u201cRobson teria invadido a resid\u00eancia de Adelson, subtraindo uma pequena quantia em dinheiro e pertences de pouco valor. Apesar disso, Robson teria disparado contra a v\u00edtima na frente da fam\u00edlia, inclusive de seus dois filhos\u201d, frisou um dos policiais.<\/p>\n<p style=\"text-align: justify;\">O acusado foi condenado a 20 anos de pris\u00e3o pelo crime, embora recentemente tenha sido preso pelos crimes de roubo e tr\u00e1fico de drogas.<\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a>,<a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">\u00a0Instagram\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><em><strong>Informa\u00e7\u00f5es da SSP\/SE<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Policiais civis da Delegacia Regional de Lagarto efetuaram nessa quinta-feira, 18, a pris\u00e3o de Robson Loureiro Doria, 43 anos, em cumprimento a um mandado de pris\u00e3o pelo crime de latroc\u00ednio (roubo seguido de morte) contra Adelson Bispo de Andrade, cometido em 2006. A a\u00e7\u00e3o ocorreu no munic\u00edpio de Salgado, distante 50 km da capital sergipana. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":88930,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-88929","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/88929"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=88929"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/88929\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/88930"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=88929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=88929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=88929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}