{"id":88918,"date":"2016-02-18T22:39:06","date_gmt":"2016-02-19T01:39:06","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=88918"},"modified":"2016-02-20T00:08:09","modified_gmt":"2016-02-20T03:08:09","slug":"fornecedor-de-armas-e-drogas-preso-na-operacao-gaviria-chega-a-sergipe","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/fornecedor-de-armas-e-drogas-preso-na-operacao-gaviria-chega-a-sergipe\/","title":{"rendered":"Fornecedor de armas e drogas preso na Opera\u00e7\u00e3o Gav\u00edria chega a Sergipe"},"content":{"rendered":"<p style=\"text-align: justify;\">Chegou a Sergipe, nesta quinta-feira, 18, Emerson Quintana de Matos, 30 anos, preso no Mato Grosso do Sul, como resultado da Opera\u00e7\u00e3o Gav\u00edria, apresentada na tarde dessa quarta-feira, 17. A quadrilha interestadual de drogas e armas tinha atua\u00e7\u00e3o nos estados de<strong> Sergipe, Bahia, Mato Grosso do Sul, S\u00e3o Paulo e Cear\u00e1.<\/strong><\/p>\n<div id=\"attachment_88920\" style=\"width: 608px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/02\/Armas-e1455846112376.jpeg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-88920\" class=\"size-full wp-image-88920\" alt=\"Emerson Quintana de Matos, 30 anos, foi preso no Mato Grosso do Sul. (Foto: SSP\/SE)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/02\/Armas-e1455846112376.jpeg\" width=\"598\" height=\"365\" \/><\/a><p id=\"caption-attachment-88920\" class=\"wp-caption-text\">Emerson Quintana de Matos, 30 anos, foi preso no Mato Grosso do Sul. (Foto: SSP\/SE)<\/p><\/div>\n<p style=\"text-align: justify;\">De acordo com o Delegado-Geral, Everton Santos, Emerson, respons\u00e1vel pelo fornecimento de drogas e armas, foi preso com aux\u00edlio da Pol\u00edcia Federal, em uma parceria que envolveu equipe com policiais sergipanos na ocorr\u00eancia. &#8220;Na escala hier\u00e1rquica, ele era o segundo abaixo de Bar\u00e3o, l\u00edder da quadrilha. A partir de agora, todos os presos ser\u00e3o ouvidos para darmos sequ\u00eancia \u00e0 conclus\u00e3o dos procedimentos&#8221;, destaca.<\/p>\n<p style=\"text-align: justify;\">A investiga\u00e7\u00e3o de cinco meses do Complexo de Opera\u00e7\u00f5es Policiais Especiais (COPE) e do Batalh\u00e3o de Radiopatrulha, com apoio da Divis\u00e3o de Intelig\u00eancia Policial (Dipol) e Pol\u00edcia Federal do Mato Grosso do Sul, foi iniciada em agosto do ano passado a partir da pris\u00e3o de duas pessoas no estacionamento de um hipermercado da zona norte de Aracaju. Os dois foram flagrados transportando 50 quilos de maconha escondidos dentro de uma carga de milho verde.<\/p>\n<p style=\"text-align: justify;\">Pouco tempo depois, a partir da realiza\u00e7\u00e3o de outras pris\u00f5es com as mesmas caracter\u00edsticas, foi montado um organograma com a atua\u00e7\u00e3o de cada membro da quadrilha, chegando-se assim ao nome do l\u00edder da organiza\u00e7\u00e3o criminosa e do fornecedor das drogas e das armas, Emerson Quintana.<\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a>,<a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">\u00a0Instagram\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><em>Informa\u00e7\u00f5es da SSP\/SE<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chegou a Sergipe, nesta quinta-feira, 18, Emerson Quintana de Matos, 30 anos, preso no Mato Grosso do Sul, como resultado da Opera\u00e7\u00e3o Gav\u00edria, apresentada na tarde dessa quarta-feira, 17. A quadrilha interestadual de drogas e armas tinha atua\u00e7\u00e3o nos estados de Sergipe, Bahia, Mato Grosso do Sul, S\u00e3o Paulo e Cear\u00e1. De acordo com o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":88920,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-88918","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/88918"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=88918"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/88918\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/88920"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=88918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=88918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=88918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}