{"id":88319,"date":"2016-01-26T21:54:33","date_gmt":"2016-01-27T00:54:33","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=88319"},"modified":"2016-01-26T23:39:54","modified_gmt":"2016-01-27T02:39:54","slug":"aneel-reduz-valor-extra-na-conta-de-luz-a-partir-de-fevereiro","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/aneel-reduz-valor-extra-na-conta-de-luz-a-partir-de-fevereiro\/","title":{"rendered":"Aneel reduz valor extra na conta de luz a partir de fevereiro"},"content":{"rendered":"<p style=\"text-align: justify;\">Em reuni\u00e3o ordin\u00e1ria realizada hoje (26), a Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) aprovou a redu\u00e7\u00e3o nas bandeiras tarif\u00e1rias amarela e vermelha, que aumentam a conta de luz do consumidor quando fica mais caro produzir energia no pa\u00eds.<\/p>\n<div id=\"attachment_56917\" style=\"width: 607px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/energia-eletrica-torre-alta-tensao.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-56917\" class=\"size-full wp-image-56917\" alt=\"A medida faz parte do sistema de bandeiras tarif\u00e1rias. (Foto: Reprodu\u00e7\u00e3o) \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/energia-eletrica-torre-alta-tensao.jpg\" width=\"597\" height=\"336\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/energia-eletrica-torre-alta-tensao.jpg 597w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/energia-eletrica-torre-alta-tensao-300x168.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/energia-eletrica-torre-alta-tensao-342x192.jpg 342w\" sizes=\"(max-width: 597px) 100vw, 597px\" \/><\/a><p id=\"caption-attachment-56917\" class=\"wp-caption-text\">A medida faz parte do sistema de bandeiras tarif\u00e1rias. (Foto: Reprodu\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">A partir de fevereiro, o valor da bandeira amarela vai cair de R$ 2,50 para R$ 1,50 para cada 100 quilowatts-hora (kWh) consumidos, redu\u00e7\u00e3o de 40%.<\/p>\n<p style=\"text-align: justify;\">J\u00e1 a bandeira vermelha ter\u00e1 um patamar intermedi\u00e1rio, mais barato, de R$ 3,50 para cada 100 kWh. O patamar mais caro foi mantido em R$ 4,50 para cada 100 kWh.<\/p>\n<p style=\"text-align: justify;\">As bandeiras tarif\u00e1rias coloridas \u2013 verde, amarela e vermelha \u2013 foram criadas como uma maneira de informar ao consumidor os custos que s\u00e3o repassados para a conta de luz com o acionamento de usinas termel\u00e9tricas, que geram uma energia mais cara e s\u00e3o ligadas quando as hidrel\u00e9tricas produzem menos por causa do baixo n\u00edvel de seus reservat\u00f3rios.<\/p>\n<p style=\"text-align: justify;\">A Aneel divulga no pr\u00f3ximo dia 29 de janeiro qual ser\u00e1 a bandeira tarif\u00e1ria que vai incidir sobre as contas de luz de fevereiro. A bandeira vermelha encontra-se vigente, onerando a conta do consumidor, pelo menos desde mar\u00e7o de 2015.<\/p>\n<p style=\"text-align: justify;\">A decis\u00e3o desta ter\u00e7a foi baseada em estudos da Superintend\u00eancia de Gest\u00e3o Tarif\u00e1ria da Aneel.<\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a>, <a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram<\/a> e no <a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Fonte: Portal Ag\u00eancia Brasil.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em reuni\u00e3o ordin\u00e1ria realizada hoje (26), a Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) aprovou a redu\u00e7\u00e3o nas bandeiras tarif\u00e1rias amarela e vermelha, que aumentam a conta de luz do consumidor quando fica mais caro produzir energia no pa\u00eds. A partir de fevereiro, o valor da bandeira amarela vai cair de R$ 2,50 para R$ 1,50 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":56917,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,6],"tags":[],"class_list":{"0":"post-88319","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios","8":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/88319"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=88319"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/88319\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/56917"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=88319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=88319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=88319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}