{"id":88318,"date":"2016-01-26T21:44:31","date_gmt":"2016-01-27T00:44:31","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=88318"},"modified":"2016-01-26T21:44:31","modified_gmt":"2016-01-27T00:44:31","slug":"auxilio-doenca-para-cuidar-de-parentes-proximos-aguarda-decisao-do-congresso","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/auxilio-doenca-para-cuidar-de-parentes-proximos-aguarda-decisao-do-congresso\/","title":{"rendered":"Aux\u00edlio-doen\u00e7a para cuidar de parentes pr\u00f3ximos aguarda decis\u00e3o do Congresso"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\"><\/span>A lei j\u00e1 garante aos trabalhadores segurados do INSS o direito de se licenciar pelo tempo necess\u00e1rio para cuidar da pr\u00f3pria sa\u00fade, conforme recomenda\u00e7\u00e3o m\u00e9dica. Os primeiros 15 dias de afastamento (contados dentro de um per\u00edodo de 60 dias) ficam a cargo da empresa. Caso a licen\u00e7a seja mais longa do que isso, cabe \u00e0 Previd\u00eancia pagar o aux\u00edlio-doen\u00e7a, cujo valor varia conforme diversos crit\u00e9rios. Clique aqui para saber tudo sobre o aux\u00edlio-doen\u00e7a.<\/p>\n<div id=\"attachment_61793\" style=\"width: 606px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/03\/grande-senado_080812-e1453855388825.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-61793\" class=\"size-full wp-image-61793\" alt=\"(Foto:Ag\u00eancia Senado)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2014\/03\/grande-senado_080812-e1453855388825.jpg\" width=\"596\" height=\"396\" \/><\/a><p id=\"caption-attachment-61793\" class=\"wp-caption-text\">(Foto:Ag\u00eancia Senado)<\/p><\/div>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Mas e quando a pessoa que precisa cuidar da sa\u00fade n\u00e3o \u00e9 o pr\u00f3prio trabalhador, mas um parente dele? Nesse caso a lei ainda n\u00e3o garante o direito ao afastamento, mas isso pode mudar. O Senado Federal aprovou, em 2015, o Projeto de Lei do Senado (PLS) 286\/14, que cria um novo tipo de benef\u00edcio da Previd\u00eancia Social, o aux\u00edlio doen\u00e7a parental. Para virar lei, o projeto agora s\u00f3 depende da aprova\u00e7\u00e3o da C\u00e2mara dos Deputados.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">De acordo com o projeto, ser\u00e1 concedido aux\u00edlio-doen\u00e7a ao segurado por motivo de doen\u00e7a do c\u00f4njuge, dos pais, dos filhos, do padrasto, madrasta, enteado, ou dependente que viva a suas expensas e conste da sua declara\u00e7\u00e3o de rendimentos. O aux\u00edlio se dar\u00e1 mediante comprova\u00e7\u00e3o por per\u00edcia m\u00e9dica, at\u00e9 o limite m\u00e1ximo de doze meses.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">A autora do projeto, senadora Ana Am\u00e9lia (PP-RS), afirmou, na justificativa da proposta, que a mat\u00e9ria busca dar tratamento ison\u00f4mico aos segurados do Regime Geral de Previd\u00eancia Social (RGPS) em rela\u00e7\u00e3o aos segurados dos Regimes Pr\u00f3prios de Previd\u00eancia Social (RPPS). Segundo ela, a regra em vigor no RGPS prev\u00ea o benef\u00edcio somente \u00e0quele que sofreu uma les\u00e3o incapacitante ou que tem um problema psiqui\u00e1trico.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Ana Am\u00e9lia ainda explicou que o pagamento do benef\u00edcio nos moldes defendidos seria uma forma de economia aos cofres p\u00fablicos, j\u00e1 que a presen\u00e7a do ente familiar pode auxiliar em diversos tratamentos e diminuir o tempo de interna\u00e7\u00e3o do paciente.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>Na C\u00e2mara, o projeto tramita como PL 1876\/2015.<\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<strong><em>Acompanhe o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a>, <a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram <\/a>e no <a href=\"https:\/\/www.facebook.com\/senoticias1 \" target=\"_blank\">Facebook<\/a><\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong><em>\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<strong><em>Fonte: Portal Ag\u00eancia Senado.<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A lei j\u00e1 garante aos trabalhadores segurados do INSS o direito de se licenciar pelo tempo necess\u00e1rio para cuidar da pr\u00f3pria sa\u00fade, conforme recomenda\u00e7\u00e3o m\u00e9dica. Os primeiros 15 dias de afastamento (contados dentro de um per\u00edodo de 60 dias) ficam a cargo da empresa. Caso a licen\u00e7a seja mais longa do que isso, cabe \u00e0 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":78738,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-88318","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/88318"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=88318"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/88318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/78738"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=88318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=88318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=88318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}