{"id":87693,"date":"2016-01-07T13:28:09","date_gmt":"2016-01-07T16:28:09","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=87693"},"modified":"2016-01-08T13:12:54","modified_gmt":"2016-01-08T16:12:54","slug":"um-morto-e-dois-feridos-em-tiroteio-no-conjunto-eduardo-gomes","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/um-morto-e-dois-feridos-em-tiroteio-no-conjunto-eduardo-gomes\/","title":{"rendered":"Um morre e dois ficam feridos em noite violenta no Eduardo Gomes"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Por C\u00e1ssia Santana*<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Um homem morreu no local e outras duas pessoas ficaram feridas em tiroteio ocorrido na noite desta quarta-feira, 6, no Conjunto Eduardo Gomes, no munic\u00edpio de S\u00e3o Crist\u00f3v\u00e3o, regi\u00e3o metropolitana. De acordo com informa\u00e7\u00f5es da Pol\u00edcia Militar, o jovem identificado como Cl\u00e9verton Ricardo Farias Santos, 25, morreu no local do crime, enquanto que um adolescente de 15 anos e uma mulher de 30 anos foram atingidos pelos disparos e socorridos pela equipe do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu).<\/p>\n<div id=\"attachment_87700\" style=\"width: 608px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/01\/90f4f056-678f-403f-9e7c-e3aeb1184378-e1452185543872.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-87700\" class=\"size-full wp-image-87700\" alt=\" O adolescente de 15 anos permanece na ala vermelha do HUSE, local para onde s\u00e3o encaminhados os pacientes em estado cr\u00edtico. (Foto: enviada pelo Whatsapp\/SENot\u00edcias)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/01\/90f4f056-678f-403f-9e7c-e3aeb1184378-e1452185543872.jpg\" width=\"598\" height=\"331\" \/><\/a><p id=\"caption-attachment-87700\" class=\"wp-caption-text\">O adolescente de 15 anos permanece na ala vermelha do HUSE, local para onde s\u00e3o encaminhados os pacientes em estado cr\u00edtico. (Foto: enviada pelo Whatsapp\/SENot\u00edcias)<\/p><\/div>\n<p style=\"text-align: justify;\">O motivo do crime ainda n\u00e3o foi esclarecido. Os policiais militares de plant\u00e3o no Eduardo Gomes foram mobilizados pela equipe do Centro Integrado de Opera\u00e7\u00f5es em Seguran\u00e7a (Ciosp) para atender a ocorr\u00eancia, segundo informa\u00e7\u00f5es da capit\u00e3 Evangelina de Deus, auxiliar da 5\u00aa. O crime foi registrado por volta das 21h30 na rua 93, daquele n\u00facleo habitacional, e quando os policiais chegaram n\u00e3o conseguiram identificar suspeitos.<\/p>\n<p style=\"text-align: justify;\">Conforme a capit\u00e3, os bandidos j\u00e1 tinham fugido a p\u00e9 pelas ruas do conjunto, levando as armas. Quando os policiais chegaram, Cl\u00e9verton j\u00e1 estava morto. Os dois sobreviventes foram levados para o Hospital de Urg\u00eancia de Sergipe (Huse). De acordo com informa\u00e7\u00f5es da assessoria de imprensa, o adolescente chegou ao hospital \u00e0s 23h12 e a mulher \u00e0s 23h16. A mulher passou por cirurgia e nesta quinta-feira, 7, ela se mant\u00e9m em sala espec\u00edfica p\u00f3s-cirurgia enquanto o adolescente permanece na ala vermelha, local para onde s\u00e3o encaminhados os pacientes em estado cr\u00edtico.<\/p>\n<p style=\"text-align: justify;\"><strong><em>Por C\u00e1ssia Santana, do <a href=\"http:\/\/www.infonet.com.br\/cidade\/ler.asp?id=181508&amp;pagina=1\" target=\"_blank\">Portal Infonet<\/a><\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/\" target=\"_blank\">Twitter<\/a> e no <a href=\" https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><em>\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><em>\u00a0<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por C\u00e1ssia Santana* Um homem morreu no local e outras duas pessoas ficaram feridas em tiroteio ocorrido na noite desta quarta-feira, 6, no Conjunto Eduardo Gomes, no munic\u00edpio de S\u00e3o Crist\u00f3v\u00e3o, regi\u00e3o metropolitana. De acordo com informa\u00e7\u00f5es da Pol\u00edcia Militar, o jovem identificado como Cl\u00e9verton Ricardo Farias Santos, 25, morreu no local do crime, enquanto [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":87700,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,38,7],"tags":[],"class_list":{"0":"post-87693","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques","8":"category-municipios","9":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/87693"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=87693"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/87693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/87700"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=87693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=87693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=87693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}