{"id":85546,"date":"2015-11-03T12:52:18","date_gmt":"2015-11-03T15:52:18","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=85546"},"modified":"2015-11-03T12:56:34","modified_gmt":"2015-11-03T15:56:34","slug":"cpprv-registra-oito-acidentes-nas-rodovias-estaduais-durante-a-operacao-finados","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/cpprv-registra-oito-acidentes-nas-rodovias-estaduais-durante-a-operacao-finados\/","title":{"rendered":"CPRv registra oito acidentes nas rodovias estaduais durante a Opera\u00e7\u00e3o Finados"},"content":{"rendered":"<p style=\"text-align: justify;\">A Pol\u00edcia Militar do Estado de Sergipe, por meio da Companhia de Pol\u00edcia Rodovi\u00e1ria Estadual (CPRv), registrou um total de oito acidentes de tr\u00e2nsito, com 10 pessoas lesionadas e duas mortes no local, durante o feriado prolongado do Dia de Finados.<\/p>\n<div id=\"attachment_85548\" style=\"width: 608px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/11\/CPRv-e1446566109677.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-85548\" class=\"size-full wp-image-85548\" alt=\"CPRv registrou oito acidentes nas rodovias estaduais durante o feriad\u00e3o. (Foto: PM\/SE)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/11\/CPRv-e1446566109677.png\" width=\"598\" height=\"400\" \/><\/a><p id=\"caption-attachment-85548\" class=\"wp-caption-text\">CPRv registrou oito acidentes nas rodovias estaduais durante o feriad\u00e3o. (Foto: PM\/SE)<\/p><\/div>\n<p style=\"text-align: justify;\">Os acidentes foram registrados nas rodovias SE 170, munic\u00edpio de Itabaiana; SE 100, em Barra dos Coqueiros; SE 335, em Ne\u00f3polis; SE 170, no Campo do Brito; SE 100, no munic\u00edpio de Estancia; SE 385, em Itabaianinha; SE 170, em Itabaiana, e SE 361, no munic\u00edpio de Po\u00e7o Verde.<\/p>\n<p style=\"text-align: justify;\">O acidente de maior gravidade foi registrado na noite do domingo, 1\u00ba, na rodovia SE 385, entre Itabaianinha e Arau\u00e1, envolvendo um ve\u00edculo Fiat Uno, GM Corsa e um ciclomotor Shineray. Durante o sinistro, o condutor e a passageira do ciclomotor n\u00e3o resistiram aos ferimentos e vieram a \u00f3bito.<\/p>\n<p style=\"text-align: justify;\">A CPRv tamb\u00e9m intensificou o policiamento nas rodovias, autuando 120 condutores, recolhendo uma CNH e 14 ve\u00edculos, sendo estes removidos ao p\u00e1tio do Detran. Nas fiscaliza\u00e7\u00f5es com baf\u00f4metros, 180 condutores foram submetidos ao teste, um deles\u00a0conduzido \u00e0 delegacia e outro teve a sua habilita\u00e7\u00e3o recolhida com base na Lei Seca.<\/p>\n<p style=\"text-align: justify;\"><strong>2014<\/strong><\/p>\n<p style=\"text-align: justify;\">Segundo dados da CPRv, na Opera\u00e7\u00e3o Finados 2014, entre s\u00e1bado e domingo, a pol\u00edcia registrou um acidente de tr\u00e2nsito, com uma pessoa lesionada.<\/p>\n<p style=\"text-align: justify;\"><em><strong>Acompanhe o SE Not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>Ascom PM\/SE<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Militar do Estado de Sergipe, por meio da Companhia de Pol\u00edcia Rodovi\u00e1ria Estadual (CPRv), registrou um total de oito acidentes de tr\u00e2nsito, com 10 pessoas lesionadas e duas mortes no local, durante o feriado prolongado do Dia de Finados. Os acidentes foram registrados nas rodovias SE 170, munic\u00edpio de Itabaiana; SE 100, em [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":85548,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,1],"tags":[],"class_list":{"0":"post-85546","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia","8":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/85546"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=85546"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/85546\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/85548"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=85546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=85546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=85546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}