{"id":85290,"date":"2015-10-26T15:36:28","date_gmt":"2015-10-26T18:36:28","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=85290"},"modified":"2015-10-26T15:41:21","modified_gmt":"2015-10-26T18:41:21","slug":"comunidade-cobra-retomada-das-reformas-da-escola-armindo-guarana","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/comunidade-cobra-retomada-das-reformas-da-escola-armindo-guarana\/","title":{"rendered":"Comunidade cobra retomada das obras da Escola Armindo Guaran\u00e1"},"content":{"rendered":"<p style=\"text-align: justify;\">A comunidade do Bairro Rosa Elze, em S\u00e3o Crist\u00f3v\u00e3o, est\u00e1 insatisfeita com a situa\u00e7\u00e3o da escola Estadual Armindo Guaran\u00e1, que est\u00e1 em obra h\u00e1 dois anos e nos \u00faltimos meses teve a reforma suspensa. Enquanto a obra n\u00e3o termina, os quase 600 alunos da institui\u00e7\u00e3o de ensino est\u00e3o estudando em um galp\u00e3o, com salas de aula improvisadas.<\/p>\n<div id=\"attachment_85295\" style=\"width: 608px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/10\/Armindo-e1445884760972.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-85295\" class=\"size-full wp-image-85295\" alt=\"Secretaria de Estado da Educa\u00e7\u00e3o confirmou a paralisa\u00e7\u00e3o da obra e previu sua retomada em dezembro. (Foto: A8SE)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/10\/Armindo-e1445884760972.jpg\" width=\"598\" height=\"399\" \/><\/a><p id=\"caption-attachment-85295\" class=\"wp-caption-text\">Secretaria de Estado da Educa\u00e7\u00e3o confirmou a paralisa\u00e7\u00e3o da obra e previu sua retomada em 60 dias. (Foto: A8SE)<\/p><\/div>\n<p style=\"text-align: justify;\">De acordo com o vigilante do col\u00e9gio, Marcos Andr\u00e9 Tavares, s\u00e3o tr\u00eas meses de obra parada. \u201cOs oper\u00e1rios abandonaram o local e o pessoal que trabalhava aqui disse que foi por corte de verba. Agora j\u00e1 s\u00e3o tr\u00eas meses com o material aqui parado, coisas de valor como areia, porta de alum\u00ednio. N\u00e3o tem um m\u00eas que entraram aqui e roubaram as ferramentas\u201d, contou.<\/p>\n<p style=\"text-align: justify;\">O estudante Dilton Luiz, que \u00e9 morador da regi\u00e3o, disse que \u00e9 uma perda grande para a comunidade. \u201cEnquanto isso os alunos, apesar do esfor\u00e7o da diretora, est\u00e3o tendo aulas em p\u00e9ssimas condi\u00e7\u00f5es, pois as divis\u00f3rias das salas n\u00e3o v\u00e3o at\u00e9 o teto e s\u00e3o de um material bem fino, o barulho \u00e9 grande de uma sala para outra\u201d, relatou.<\/p>\n<p style=\"text-align: justify;\"><strong>Seed<\/strong><\/p>\n<p style=\"text-align: justify;\">De acordo com a assessoria da Secretaria de Estado da Educa\u00e7\u00e3o (SEED), as obras da escola est\u00e3o bem adiantadas e foram suspensas, pois a empresa alegou n\u00e3o ter mais condi\u00e7\u00f5es de continuar com a obra. \u201cHouve o destrato do contrato e agora estamos tomando as medidas jur\u00eddicas legais para substituir a empresa. Acreditamos que em at\u00e9 60 dias uma nova firma j\u00e1 tenha assumido a obra\u201d, afirmou Elton Coelho.<\/p>\n<p><strong>Acompanhe o SE Not\u00edcias no<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\"> Twitter<\/a> e no<a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\"> Facebook<\/a><\/strong><\/p>\n<p><strong>Mat\u00e9ria postada originalmente no Portal <a href=\"http:\/\/a8se.com\/sergipe\/noticia\/2015\/10\/85350-comunidade-denuncia-abandono-de-obra-na-escola-estadual-armindo-guarana.html\" target=\"_blank\">A8SE<\/a>.com<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A comunidade do Bairro Rosa Elze, em S\u00e3o Crist\u00f3v\u00e3o, est\u00e1 insatisfeita com a situa\u00e7\u00e3o da escola Estadual Armindo Guaran\u00e1, que est\u00e1 em obra h\u00e1 dois anos e nos \u00faltimos meses teve a reforma suspensa. Enquanto a obra n\u00e3o termina, os quase 600 alunos da institui\u00e7\u00e3o de ensino est\u00e3o estudando em um galp\u00e3o, com salas de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":85295,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":{"0":"post-85290","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/85290"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=85290"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/85290\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/85295"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=85290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=85290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=85290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}