{"id":83971,"date":"2015-09-14T19:39:32","date_gmt":"2015-09-14T22:39:32","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=83971"},"modified":"2015-09-16T12:00:35","modified_gmt":"2015-09-16T15:00:35","slug":"gerente-de-banco-e-preso-suspeito-de-aplicar-golpe-de-cerca-de-r-2-mi","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/gerente-de-banco-e-preso-suspeito-de-aplicar-golpe-de-cerca-de-r-2-mi\/","title":{"rendered":"Gerente do Banese \u00e9 preso suspeito de aplicar golpe de cerca de R$ 2 milh\u00f5es"},"content":{"rendered":"<div id=\"attachment_83972\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/09\/1492015184317.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-83972\" class=\"size-medium wp-image-83972\" alt=\"Foto: Gerliano Brito\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/09\/1492015184317-300x300.jpg\" width=\"300\" height=\"300\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/09\/1492015184317-300x300.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/09\/1492015184317-150x150.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/09\/1492015184317-50x50.jpg 50w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/09\/1492015184317-342x342.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/09\/1492015184317-70x70.jpg 70w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/09\/1492015184317-55x55.jpg 55w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/09\/1492015184317.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-83972\" class=\"wp-caption-text\">Jos\u00e9 Rog\u00e9rio Cruz, \u00e9 ex-gerente do Banese de Tobias Barreto. (Foto: Gerliano Brito)<\/p><\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">O gerente de uma ag\u00eancia banc\u00e1ria, suspeito de estelionato, foi preso por policiais da cidade de Tobias Barreto na tarde desta segunda-feira (14), ap\u00f3s dois meses de investiga\u00e7\u00e3o. O ent\u00e3o gerente duplicava os empr\u00e9stimos solicitados pelos clientes causando assim um desfalque junto ao banco.<\/p>\n<p style=\"text-align: justify;\">&#8220;Ele solicitava a documenta\u00e7\u00e3o do cliente e no meio dos documentos colocava uma ordem de saque em seu nome, e quando o dinheiro entrava na conta ele sacava. Em seguida, bloqueava a conta e quando o cliente o procurava ele dizia que o processo deveria ser reiniciado. E assim a duplica\u00e7\u00e3o do empr\u00e9stimo era realizada&#8221;, explicou o delegado Edson Nixon.<\/p>\n<p style=\"text-align: justify;\">O delegado revelou que na ocasi\u00e3o, os clientes estavam procurando a ag\u00eancia banc\u00e1ria para reclamar e o banco instaurou um processo administrativo para investigar o caso e ap\u00f3s perceber que seria descoberto o gerente resolveu fugir. &#8221; Ele percebeu que iriam descobrir o golpe, j\u00e1 que o n\u00famero de v\u00edtimas era alto e os clientes estavam buscando entender o que estava acontecendo em suas contas banc\u00e1rias&#8221;.<\/p>\n<p style=\"text-align: justify;\">Segundo o delegado, cerca de 72 pessoas foram v\u00edtimas do golpe no valor de aproximadamente R$ 2 milh\u00f5es. &#8220;Durante as investiga\u00e7\u00f5es descobrimos que ele responde, em liberdade, pelo por crime de estelionato, praticado entre os anos de 2007 e 2008 contra uma outra ag\u00eancia banc\u00e1ria&#8221;.<\/p>\n<p style=\"text-align: justify;\">\u201cEle vai permanecer custodiado na delegacia at\u00e9 que o inqu\u00e9rito seja conclu\u00eddo e outras v\u00edtimas sejam ouvidas. Depois ele segue para o sistema carcer\u00e1rio\u201d, disse. Ainda segundo o delegado, durante a pris\u00e3o uma arma e um ve\u00edculo foram apreendidos.<\/p>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es do G1, em Sergipe<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias?ref=bookmarks\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O gerente de uma ag\u00eancia banc\u00e1ria, suspeito de estelionato, foi preso por policiais da cidade de Tobias Barreto na tarde desta segunda-feira (14), ap\u00f3s dois meses de investiga\u00e7\u00e3o. O ent\u00e3o gerente duplicava os empr\u00e9stimos solicitados pelos clientes causando assim um desfalque junto ao banco. &#8220;Ele solicitava a documenta\u00e7\u00e3o do cliente e no meio dos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":83972,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[310,7],"tags":[],"class_list":{"0":"post-83971","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques-da-semana","8":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/83971"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=83971"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/83971\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/83972"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=83971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=83971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=83971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}