{"id":83804,"date":"2015-09-10T14:39:31","date_gmt":"2015-09-10T17:39:31","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=83804"},"modified":"2015-09-11T17:57:41","modified_gmt":"2015-09-11T20:57:41","slug":"para-a-fies-o-inverno-chegou-na-economia-brasileira","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/para-a-fies-o-inverno-chegou-na-economia-brasileira\/","title":{"rendered":"Para a FIES o inverno chegou na economia brasileira"},"content":{"rendered":"<p align=\"center\"><b>\u00a0<\/b><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">O Presidente da Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de Sergipe (FIES), Eduardo Prado de Oliveira, avaliou que o inverno chegou na economia brasileira, devido \u00e0 perda do grau de investimento pela ag\u00eancia de classifica\u00e7\u00e3o de risco Standard and Poor\u2019s (S&amp;P). Para Eduardo, \u201ch\u00e1 a possibilidade desse inverno ser seguido de uma grande tempestade, e com certeza esse rebaixamento da nota conquistada a duras penas pelo pa\u00eds, causar\u00e1 certamente um forte impacto no desenvolvimento do pa\u00eds e de Sergipe nos pr\u00f3ximos anos\u201d.<\/p>\n<div id=\"attachment_83823\" style=\"width: 608px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/09\/Economia1-e1441907416288.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-83823\" class=\"size-full wp-image-83823\" alt=\"Para a FIES o inverno chegou na economia brasileira. (Foto: Divulga\u00e7\u00e3o\/Fies)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/09\/Economia1-e1441907416288.jpg\" width=\"598\" height=\"398\" \/><\/a><p id=\"caption-attachment-83823\" class=\"wp-caption-text\">Para a FIES o inverno chegou na economia brasileira. (Foto: Divulga\u00e7\u00e3o\/Fies)<\/p><\/div>\n<p style=\"text-align: justify;\">Sobre essa quest\u00e3o, o empres\u00e1rio ainda afirmou que \u201cn\u00e3o h\u00e1 como manter um \u201car de normalidade\u201d ante o anormal caminho por onde a economia vai sendo conduzida\u201d.<\/p>\n<p style=\"text-align: justify;\"><b>Aumento do Imposto de Renda e CIDE<\/b><\/p>\n<p style=\"text-align: justify;\">O Presidente da FIES tamb\u00e9m recha\u00e7a a ideia de elevar o Imposto de Renda e a Cide para tentar combater os refeitos da crise econ\u00f4mica. Para ele, \u201co momento \u00e9 de pensar no pa\u00eds, n\u00e3o em partido ou governo. Precisamos urgentemente de reformas e cortes de gastos p\u00fablicos para n\u00e3o termos uma d\u00e9cada perdida h\u00e1 frente\u201d.<\/p>\n<p>\u00a0<strong>Acompanhe o SE Not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p><em><strong>UNICOM\/FIES<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 &nbsp; O Presidente da Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de Sergipe (FIES), Eduardo Prado de Oliveira, avaliou que o inverno chegou na economia brasileira, devido \u00e0 perda do grau de investimento pela ag\u00eancia de classifica\u00e7\u00e3o de risco Standard and Poor\u2019s (S&amp;P). Para Eduardo, \u201ch\u00e1 a possibilidade desse inverno ser seguido de uma grande tempestade, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":83823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-83804","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/83804"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=83804"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/83804\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/83823"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=83804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=83804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=83804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}