{"id":83793,"date":"2015-09-10T07:10:06","date_gmt":"2015-09-10T10:10:06","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=83793"},"modified":"2015-09-10T07:14:47","modified_gmt":"2015-09-10T10:14:47","slug":"camara-aprova-doacao-de-empresas-a-partidos-e-conclui-reforma-politica","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/camara-aprova-doacao-de-empresas-a-partidos-e-conclui-reforma-politica\/","title":{"rendered":"C\u00e2mara rejeita mudan\u00e7as do Senado e restabelece financiamento privado"},"content":{"rendered":"<div id=\"attachment_83795\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/09\/Plen\u00e1rio-da-C\u00e2mara-300x218.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-83795\" class=\"size-full wp-image-83795\" alt=\"Minirreforma eleitoral: C\u00e2mara modificou texto aprovado pelo Senado. (Foto: Divulga\u00e7\u00e3o \/ C\u00e2mara dos Deputados)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/09\/Plen\u00e1rio-da-C\u00e2mara-300x218.jpg\" width=\"300\" height=\"218\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/09\/Plen\u00e1rio-da-C\u00e2mara-300x218.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/09\/Plen\u00e1rio-da-C\u00e2mara-300x218-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/09\/Plen\u00e1rio-da-C\u00e2mara-300x218-90x65.jpg 90w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-83795\" class=\"wp-caption-text\">Minirreforma eleitoral: C\u00e2mara modificou texto aprovado pelo Senado. (Foto: Divulga\u00e7\u00e3o \/ C\u00e2mara dos Deputados)<\/p><\/div>\n<p style=\"text-align: justify;\">A C\u00e2mara dos Deputados rejeitou, na noite de hoje, a maioria das emendas do Senado ao Projeto de Lei (PL) 5.735\/13, a minirreforma eleitoral. Entre as emendas mais pol\u00eamicas que foram rejeitadas est\u00e3o a que trata da doa\u00e7\u00e3o de empresas a partidos pol\u00edticos para as campanhas at\u00e9 o limite de R$ 20 milh\u00f5es por campanha; a que reduz o prazo de filia\u00e7\u00e3o partid\u00e1ria de um ano para seis meses e mant\u00e9m a exig\u00eancia do domic\u00edlio eleitoral de um ano para se candidatar a cargo eletivo.<\/p>\n<p style=\"text-align: justify;\">Com a aprova\u00e7\u00e3o do substitutivo apresentado pelo relator da reforma, deputado Rodrigo Maia (DEM-RJ), \u00e0s emendas aprovadas pelo Senado e com a vota\u00e7\u00e3o de todos os destaques e emendas que visavam a alterar o substitutivo, a C\u00e2mara concluiu a vota\u00e7\u00e3o da minirreforma eleitoral. O texto aprovado seguir\u00e1 agora para san\u00e7\u00e3o presidencial a fim de que possa valer para as elei\u00e7\u00f5es municipais do ano que vem.<\/p>\n<p style=\"text-align: justify;\">O PT tentou retirar do texto aprovado pelos deputados a possibilidade das empresas fazerem doa\u00e7\u00f5es aos partidos para as campanhas eleitorais. No entanto, 285 deputados votaram pela manuten\u00e7\u00e3o do texto e 180 pela proibi\u00e7\u00e3o das doa\u00e7\u00f5es de empresas aos partidos. Os deputados tamb\u00e9m rejeitaram a emenda do Senado que proibia pagamento a cabos eleitorais pelo trabalho nas campanhas.<\/p>\n<p style=\"text-align: justify;\">Os deputados aprovaram a cria\u00e7\u00e3o de uma janela de 30 dias, antes do fim do prazo de filia\u00e7\u00e3o, para que os eleitos possam deixar a legenda de origem sem perder o mandato. Voltou a permiss\u00e3o de carros de som, que o Senado havia retirado da reforma pol\u00edtica. O texto aprovado tamb\u00e9m, segundo o relator, reduziu o tempo dos programas eleitorais em bloco e aumentou o tempo destinado \u00e0s inser\u00e7\u00f5es que s\u00e3o veiculadas nas emissoras durante a programa\u00e7\u00e3o normal.<\/p>\n<p style=\"text-align: justify;\">Um dos destaques aprovados na noite de hoje, apresentado pelo PT, substituiu o limite de 65% dos gastos\u00a0para campanha a deputado federal, que seriam aplicados sobre o maior gasto nacional para o cargo na elei\u00e7\u00e3o anterior, pelo limite de 70% do maior gasto contratado para a disputa do cargo em cada estado na elei\u00e7\u00e3o anterior.<\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><em>Da Ag\u00eancia Brasil<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara dos Deputados rejeitou, na noite de hoje, a maioria das emendas do Senado ao Projeto de Lei (PL) 5.735\/13, a minirreforma eleitoral. Entre as emendas mais pol\u00eamicas que foram rejeitadas est\u00e3o a que trata da doa\u00e7\u00e3o de empresas a partidos pol\u00edticos para as campanhas at\u00e9 o limite de R$ 20 milh\u00f5es por campanha; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":83795,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-83793","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/83793"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=83793"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/83793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/83795"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=83793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=83793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=83793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}