{"id":83726,"date":"2015-09-08T18:10:48","date_gmt":"2015-09-08T21:10:48","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=83726"},"modified":"2015-09-10T06:50:10","modified_gmt":"2015-09-10T09:50:10","slug":"ciclista-morre-em-pleno-treinamento-apos-acidente-entre-caminhoes","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/ciclista-morre-em-pleno-treinamento-apos-acidente-entre-caminhoes\/","title":{"rendered":"Ciclista morre atropelado por caminh\u00e3o na BR-101, enquanto treinava para corrida"},"content":{"rendered":"<p style=\"text-align: justify;\">Uma ciclista morreu no in\u00edcio da tarde desta ter\u00e7a-feira (08) ap\u00f3s um acidente entre dois caminh\u00f5es, na BR-101, no munic\u00edpio de S\u00e3o Crist\u00f3v\u00e3o, regi\u00e3o da Grande Aracaju.<\/p>\n<p style=\"text-align: justify;\">Segundo informa\u00e7\u00f5es da Pol\u00edcia Rodovi\u00e1ria Federal (PRF), o caminh\u00e3o acabou colidindo na traseira do outro caminh\u00e3o que vinha logo a frente.<\/p>\n<div id=\"attachment_83727\" style=\"width: 608px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/09\/br-e1441755836303.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-83727\" class=\"size-full wp-image-83727\" alt=\"Ciclista treinava para competi\u00e7\u00e3o em Campo do Brito (Foto: Divulga\u00e7\u00e3o\/PRF) \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/09\/br-e1441755836303.jpg\" width=\"598\" height=\"449\" \/><\/a><p id=\"caption-attachment-83727\" class=\"wp-caption-text\">Ciclista treinava para competi\u00e7\u00e3o em Campo do Brito (Foto: Divulga\u00e7\u00e3o\/PRF)<\/p><\/div>\n<p style=\"text-align: justify;\">Ainda de acordo com a PRF, o ciclista pode ter sido atingido por estar na via e estar pedalando ao fundo do caminh\u00e3o que vinha a frente.<br \/>\nA PRF disse tamb\u00e9m que o motorista do caminh\u00e3o que vinha no fundo teria dormido ao volante.<\/p>\n<p style=\"text-align: justify;\"><strong>Ciclista<\/strong><\/p>\n<p style=\"text-align: justify;\">Atleta treinava para disputar a 10\u00aa etapa do Campeonato Sergipano de Ciclismo, em Campo do Brito, no pr\u00f3ximo domingo (13).<br \/>\nAos 39 anos, natural de Boquim, interior de Sergipe, Jocival Costa, deixa esposa. O atleta competia o Campeonato Sergipano na categoria master &#8216;A&#8217;.<\/p>\n<p style=\"text-align: justify;\">Nesta temporada, ele estava na quarta coloca\u00e7\u00e3o, com 66 pontos. Ele tamb\u00e9m estava classificado para disputar a Copa Brasil, que acontecer\u00e1 dia 20 de setembro, em Macei\u00f3 (AL).<\/p>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es do G1, em Sergipe<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma ciclista morreu no in\u00edcio da tarde desta ter\u00e7a-feira (08) ap\u00f3s um acidente entre dois caminh\u00f5es, na BR-101, no munic\u00edpio de S\u00e3o Crist\u00f3v\u00e3o, regi\u00e3o da Grande Aracaju. Segundo informa\u00e7\u00f5es da Pol\u00edcia Rodovi\u00e1ria Federal (PRF), o caminh\u00e3o acabou colidindo na traseira do outro caminh\u00e3o que vinha logo a frente. Ainda de acordo com a PRF, o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":83727,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-83726","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/83726"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=83726"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/83726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/83727"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=83726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=83726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=83726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}