{"id":83260,"date":"2015-08-24T20:34:02","date_gmt":"2015-08-24T23:34:02","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=83260"},"modified":"2015-08-24T20:38:01","modified_gmt":"2015-08-24T23:38:01","slug":"tribunal-regional-eleitoral-divulga-edital-do-concurso-publico","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/tribunal-regional-eleitoral-divulga-edital-do-concurso-publico\/","title":{"rendered":"Tribunal Regional Eleitoral divulga edital do concurso p\u00fablico"},"content":{"rendered":"<div id=\"attachment_23880\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/02\/Concurso-II.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-23880\" class=\"size-medium wp-image-23880\" alt=\"As inscri\u00e7\u00f5es estar\u00e3o abertas de 24\/08\/15 a 22\/09\/15 (Imagem ilustrativa)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/02\/Concurso-II-300x200.jpg\" width=\"300\" height=\"200\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/02\/Concurso-II-300x200.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/02\/Concurso-II-342x227.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/02\/Concurso-II.jpg 510w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-23880\" class=\"wp-caption-text\">As inscri\u00e7\u00f5es estar\u00e3o abertas de 24\/08\/15 a 22\/09\/15 (Imagem ilustrativa)<\/p><\/div>\n<p style=\"text-align: justify;\" align=\"justify\">O Presidente do Tribunal Regional Eleitoral de Sergipe, Desembargador\u00a0<b>Cez\u00e1rio Siqueira Neto<\/b>, comunica que foi aberto o\u00a0<b>Edital n\u00ba 01\/2015<\/b>, publicado no DOU do dia 20\/08\/15, do concurso p\u00fablico\u00a0para provimento de cargos efetivos, de n\u00edvel m\u00e9dio e superior, do Quadro Permanente de Pessoal deste Tribunal. A ser realizado pela Funda\u00e7\u00e3o Carlos Chagas .<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Ser\u00e3o ofertadas as seguintes vagas: uma vaga mais cadastro reserva para Analista Judici\u00e1rio -\u00c1rea Judici\u00e1ria; cadastro reserva para Analista Judici\u00e1rio -\u00c1rea Administrativa e dez vagas mais cadastro reserva para o cargo de T\u00e9cnico Judici\u00e1rio -\u00c1rea Administrativa, sendo destas uma reservada a candidatos com defici\u00eancia e duas vagas destinadas a candidatos negros.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">A remunera\u00e7\u00e3o inicial para o cargo de Analista Judici\u00e1rio -\u00c1rea Judici\u00e1ria e Administrativa \u00e9 de\u00a0<b>R$ 8.863,84<\/b>\u00a0e para o cargo de T\u00e9cnico Judici\u00e1rio- \u00c1rea Administrativa \u00e9 de R<b>$ 5.425,79<\/b>, incluindo o vencimento, Gratifica\u00e7\u00e3o de Atividade Judici\u00e1ria (GAJ) e Vantagem Pecuni\u00e1ria Individual (VPI), tendo carga hor\u00e1ria de 40 horas semanais.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">O edital prev\u00ea que do total de vagas que vierem a ser oferecidas durante o prazo de validade do concurso haver\u00e1 reserva para pessoas com defici\u00eancia (PCD) e pessoas negras ou pardas (PPP).<\/p>\n<h3 style=\"text-align: justify;\">Inscri\u00e7\u00f5es<\/h3>\n<p style=\"text-align: justify;\" align=\"justify\">As inscri\u00e7\u00f5es estar\u00e3o abertas de\u00a0<b>24\/08\/15 a 22\/09\/15<\/b>, no site da Funda\u00e7\u00e3o Carlos Chagas (http:\/\/www.concursosfcc.com.br), mediante o pagamento da taxa de inscri\u00e7\u00e3o de\u00a0<b>R$ 90,00 (noventa) reais<\/b>\u00a0para Analista Judici\u00e1rio (n\u00edvel superior) e\u00a0<b>R$ 70,00 (setenta) reais<\/b>\u00a0para o cargo de T\u00e9cnico Judici\u00e1rio (n\u00edvel m\u00e9dio).<\/p>\n<h3 style=\"text-align: justify;\">Provas<\/h3>\n<p style=\"text-align: justify;\">O Concurso P\u00fablico constar\u00e1 de Provas Objetivas, de Conhecimentos Gerais e Espec\u00edficos para todos os cargos e para o cargo de Analista Judici\u00e1rio constar\u00e1 tamb\u00e9m Prova Discursiva, todas com data prevista para\u00a0<b>o dia 01 de novembro de 2015<\/b>.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Os conte\u00fados a serem cobrados nas provas para Conhecimentos Gerais s\u00e3o: Gram\u00e1tica e interpreta\u00e7\u00e3o de texto da l\u00edngua portuguesa, No\u00e7\u00f5es de Inform\u00e1tica, No\u00e7\u00f5es Aplic\u00e1veis aos Servidores P\u00fablicos Federais e Regimento Interno do TRE\/SE.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Para o cargo de Analista Judici\u00e1rio<\/strong> &#8211; \u00c1rea Judici\u00e1ria ser\u00e3o cobrados Conhecimentos Espec\u00edficos em: Direito Constitucional, Direito Administrativo, Direito Eleitoral, Direito Civil, Direito Processual Civil, Direito Penal, Direito Processual Penal, No\u00e7\u00f5es de Administra\u00e7\u00e3o P\u00fablica e Atribui\u00e7\u00f5es do Chefe de Cart\u00f3rio e demais servidores lotados nos Cart\u00f3rios Eleitorais.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Para o cargo de Analista Judici\u00e1rio &#8211;<\/strong> \u00c1rea Administrativa ser\u00e3o cobrados Conhecimentos Espec\u00edficos em: Direito Constitucional, Direito Administrativo, Direito Eleitoral, Administra\u00e7\u00e3o P\u00fablica, Administra\u00e7\u00e3o Financeira e Or\u00e7ament\u00e1ria, No\u00e7\u00f5es de Direito Civil, No\u00e7\u00f5es de Direito Processual Civil, No\u00e7\u00f5es de Direito Penal, No\u00e7\u00f5es de Direito Processual Penal e Atribui\u00e7\u00f5es do Chefe de Cart\u00f3rio e demais servidores lotados nos Cart\u00f3rios Eleitorais.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Para o cargo de T\u00e9cnico Judici\u00e1rio<\/strong> &#8211; \u00c1rea Administrativa ser\u00e3o cobrados Conhecimentos Espec\u00edficos em: No\u00e7\u00f5es de Direito Constitucional, No\u00e7\u00f5es de Direito Administrativo, No\u00e7\u00f5es de Direito Eleitoral e Atribui\u00e7\u00f5es do Chefe de Cart\u00f3rio e demais servidores lotados nos Cart\u00f3rios Eleitorais.<\/p>\n<p align=\"left\">O edital e as atualiza\u00e7\u00f5es deste concurso poder\u00e3o ser consultados no site da Funda\u00e7\u00e3o Carlos Chagas\u00a0<i>(<\/i><a href=\"http:\/\/www.concursosfcc.com.br\/\"><i>www.concursosfcc.com.br<\/i><\/a><i>).<\/i><\/p>\n<p align=\"left\">Confira o edital no DOU\u00a0<i>(http:\/\/www.jusbrasil.com.br\/diarios\/98233480\/dou-secao-3-20-08-2015-pg-208)<\/i><\/p>\n<p align=\"left\"><strong>Acompanhe o SE Not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p align=\"left\"><strong><em>Informa\u00e7\u00f5es do site do TRE\/SE<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Presidente do Tribunal Regional Eleitoral de Sergipe, Desembargador\u00a0Cez\u00e1rio Siqueira Neto, comunica que foi aberto o\u00a0Edital n\u00ba 01\/2015, publicado no DOU do dia 20\/08\/15, do concurso p\u00fablico\u00a0para provimento de cargos efetivos, de n\u00edvel m\u00e9dio e superior, do Quadro Permanente de Pessoal deste Tribunal. A ser realizado pela Funda\u00e7\u00e3o Carlos Chagas . Ser\u00e3o ofertadas as seguintes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23880,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":{"0":"post-83260","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-concursos"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/83260"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=83260"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/83260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/23880"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=83260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=83260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=83260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}