{"id":82850,"date":"2015-08-12T12:52:53","date_gmt":"2015-08-12T15:52:53","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=82850"},"modified":"2015-08-12T12:52:53","modified_gmt":"2015-08-12T15:52:53","slug":"assaltantes-fazem-arrastao-em-hospital-de-laranjeiras","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/assaltantes-fazem-arrastao-em-hospital-de-laranjeiras\/","title":{"rendered":"Assaltantes fazem arrast\u00e3o em hospital de Laranjeiras"},"content":{"rendered":"<div id=\"attachment_82851\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/08\/grande-assalto_hospital_laranjeiras_120815.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-82851\" class=\"size-medium wp-image-82851\" alt=\"O arrast\u00e3o ocorreu no pronto-socorro do hospital e maternidade (Fotos: Portal Infonet) \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/08\/grande-assalto_hospital_laranjeiras_120815-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/08\/grande-assalto_hospital_laranjeiras_120815-300x199.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/08\/grande-assalto_hospital_laranjeiras_120815-342x227.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/08\/grande-assalto_hospital_laranjeiras_120815.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-82851\" class=\"wp-caption-text\">O arrast\u00e3o ocorreu no pronto-socorro do hospital e maternidade (Fotos: Portal Infonet)<\/p><\/div>\n<p style=\"text-align: justify;\">Funcion\u00e1rios e pacientes do Hospital e Maternidade S\u00e3o Jo\u00e3o de Deus viveram momentos de p\u00e2nico na noite da \u00faltima ter\u00e7a-feira, 11, ap\u00f3s assaltantes invadirem o hospital, situado no munic\u00edpio de Laranjeiras.<\/p>\n<p style=\"text-align: justify;\">Por volta das 22h tr\u00eas homens armados, sendo dois com arma de fogo e um com arma branca entraram no pronto-socorro da unidade e assaltaram pacientes e funcion\u00e1rios, levando celulares e dinheiro das v\u00edtimas.<\/p>\n<p style=\"text-align: justify;\">\u201cEles levaram os pertences de umas 11 pessoas, sendo tr\u00eas pacientes que estavam na observa\u00e7\u00e3o. Foi um corre-corre. Um deles colocou a faca em mim. Nunca esperei ver aquilo na minha vida. Achei que fosse uma brincadeira\u201d, relata uma das funcion\u00e1rias.<\/p>\n<p style=\"text-align: justify;\">Segundo a diretora da unidade, Keila Talita Medeiros de Melo, os tr\u00eas suspeitos estavam encapuzados. \u201cAs tr\u00eas pessoas encapuzadas chegaram a p\u00e9. Um ficou do lado de fora, enquanto os outros dois entraram no pronto-socorro e renderam a equipe de enfermagem e os tr\u00eas guardas municipais do hospital. Eles j\u00e1 chegaram pedindo celular e o dinheiro das pessoas. Esse assalto foi bem planejado. Infelizmente aconteceu isso, mas eu me sinto confort\u00e1vel dos nossos funcion\u00e1rios n\u00e3o terem sido lesionados, todos est\u00e3o com vida e ningu\u00e9m foi agredido a n\u00e3o ser o susto de fato. Vamos providenciar um CD com as imagens das c\u00e2meras para entregar a pol\u00edcia\u201d, informa.<\/p>\n<p style=\"text-align: justify;\">Ap\u00f3s o assalto, funcion\u00e1rios acionaram a pol\u00edcia que encaminhou duas viaturas para realizar buscas pela localidade, mas n\u00e3o conseguiu localizar os assaltantes.<\/p>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es do Portal Infonet<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Funcion\u00e1rios e pacientes do Hospital e Maternidade S\u00e3o Jo\u00e3o de Deus viveram momentos de p\u00e2nico na noite da \u00faltima ter\u00e7a-feira, 11, ap\u00f3s assaltantes invadirem o hospital, situado no munic\u00edpio de Laranjeiras. Por volta das 22h tr\u00eas homens armados, sendo dois com arma de fogo e um com arma branca entraram no pronto-socorro da unidade e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":82851,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-82850","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/82850"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=82850"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/82850\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/82851"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=82850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=82850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=82850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}