{"id":82839,"date":"2015-08-12T11:53:06","date_gmt":"2015-08-12T14:53:06","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=82839"},"modified":"2015-08-13T11:20:56","modified_gmt":"2015-08-13T14:20:56","slug":"coleta-de-lixo-e-suspensa-por-causa-de-impasse-entre-empresa-e-prefeitura","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/coleta-de-lixo-e-suspensa-por-causa-de-impasse-entre-empresa-e-prefeitura\/","title":{"rendered":"Coleta de lixo \u00e9 suspensa por causa de impasse entre empresa e prefeitura"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Marina Fontenele, do G1 SE<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">A Torre suspendeu a coleta de lixo domiciliar em Aracaju nesta quarta-feira (12) alegando descumprimento de um acordo por parte da prefeitura. Os funcion\u00e1rios que chegaram para trabalhar nesta manh\u00e3 foram liberados a voltarem para casa at\u00e9 que a situa\u00e7\u00e3o seja resolvida entre a empresa e a administra\u00e7\u00e3o municipal.<\/p>\n<p style=\"text-align: justify;\">A Empresa Municipal de Servi\u00e7os Urbanos (Emsurb), que gerencia o servi\u00e7o, informou atrav\u00e9s de nota oficial que todas as medidas j\u00e1 est\u00e3o sendo tomadas no intuito da solu\u00e7\u00e3o do problema.<\/p>\n<div id=\"attachment_82842\" style=\"width: 608px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/08\/2-e1439391232165.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-82842\" class=\"size-full wp-image-82842\" alt=\"Torre liberou funcion\u00e1rios que chegaram para trabalhar para irem para casa.\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/08\/2-e1439391232165.jpg\" width=\"598\" height=\"449\" \/><\/a><p id=\"caption-attachment-82842\" class=\"wp-caption-text\">Torre liberou funcion\u00e1rios que chegaram para trabalhar para irem para casa. (Foto: marina Fontenele\/G1)<\/p><\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">\u201cO presidente da Emsurb ficou surpreso com essa suspens\u00e3o porque ficou acertado de ele informar a data do pagamento de uma d\u00edvida antiga at\u00e9 as 10h desta quarta-feira (12), mas a empresa decidiu parar antes do fim desse prazo\u201d, disse a assessoria de comunica\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Apesar do impasse, outros servi\u00e7os est\u00e3o sendo mantidos como o mutir\u00e3o de limpeza no Lamar\u00e3o, a manuten\u00e7\u00e3o das avenidas Her\u00e1clito Rollemberg, Rio de Janeiro e Mel\u00edcio Machado. A\u00e7\u00f5es de paisagismo nas pra\u00e7as Durval Andrade, do Conj Castelo Branco e Mar Azul tamb\u00e9m s\u00e3o feitas normalmente. Assim como a limpeza de canais no JK, canal da Rua Salatiel no bairro S. Dumont e canais do bairro 17 de Mar\u00e7o.<\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marina Fontenele, do G1 SE A Torre suspendeu a coleta de lixo domiciliar em Aracaju nesta quarta-feira (12) alegando descumprimento de um acordo por parte da prefeitura. Os funcion\u00e1rios que chegaram para trabalhar nesta manh\u00e3 foram liberados a voltarem para casa at\u00e9 que a situa\u00e7\u00e3o seja resolvida entre a empresa e a administra\u00e7\u00e3o municipal. A [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":82842,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,6],"tags":[],"class_list":{"0":"post-82839","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios","8":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/82839"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=82839"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/82839\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/82842"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=82839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=82839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=82839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}