{"id":82678,"date":"2015-08-07T06:38:17","date_gmt":"2015-08-07T09:38:17","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=82678"},"modified":"2015-08-07T21:29:21","modified_gmt":"2015-08-08T00:29:21","slug":"100-presos-da-2a-e-10a-dm-serao-transferidos-para-cadeiao-de-socorro","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/100-presos-da-2a-e-10a-dm-serao-transferidos-para-cadeiao-de-socorro\/","title":{"rendered":"100 presos da 2\u00aa e 10\u00aa DM ser\u00e3o transferidos para Cadei\u00e3o de Socorro"},"content":{"rendered":"<p style=\"text-align: justify;\">A Secretaria de Estado da Seguran\u00e7a Publica informa que diante da situa\u00e7\u00e3o que ocorreu nesta quinta-feira, 6, na 2\u00aa e 10\u00aa Delegacias Metropolitanas de Aracaju, e depois de entendimento firmado com a Secretaria de Estado da Justi\u00e7a e Cidadania, conseguiu a transfer\u00eancia de 100 presos que estavam custodiados nestas unidades policiais para a Cadeia P\u00fablica localizada na cidade de Nossa Senhora do Socorro.<\/p>\n<div id=\"attachment_82680\" style=\"width: 608px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/08\/gallery_big_d18b2b1b0fa3636f844fc679216f23bd-e1438940589806.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-82680\" class=\"size-full wp-image-82680\" alt=\"100 presos foram transferidos para a Cadeia P\u00fablica de Nossa Senhora do Socorro. (Foto: ASN)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/08\/gallery_big_d18b2b1b0fa3636f844fc679216f23bd-e1438940589806.jpg\" width=\"598\" height=\"414\" \/><\/a><p id=\"caption-attachment-82680\" class=\"wp-caption-text\">100 presos foram transferidos para a Cadeia P\u00fablica de Nossa Senhora do Socorro. (Foto: ASN)<\/p><\/div>\n<p style=\"text-align: justify;\">O procedimento para que os 100 presos possam efetivamente ser transferidos para a Cadeia P\u00fablica de Socorro j\u00e1 est\u00e1 em andamento, tendo em vista que os mesmos devem passar pelo Instituto M\u00e9dico Legal (IML) e Instituto de Identifica\u00e7\u00e3o antes de serem encaminhados para a unidade prisional.<\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no <a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><em>Ag\u00eancia Sergipe de Not\u00edcias<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado da Seguran\u00e7a Publica informa que diante da situa\u00e7\u00e3o que ocorreu nesta quinta-feira, 6, na 2\u00aa e 10\u00aa Delegacias Metropolitanas de Aracaju, e depois de entendimento firmado com a Secretaria de Estado da Justi\u00e7a e Cidadania, conseguiu a transfer\u00eancia de 100 presos que estavam custodiados nestas unidades policiais para a Cadeia P\u00fablica [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":82680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-82678","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/82678"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=82678"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/82678\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/82680"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=82678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=82678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=82678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}