{"id":82027,"date":"2015-07-21T13:16:23","date_gmt":"2015-07-21T16:16:23","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=82027"},"modified":"2015-07-21T13:16:23","modified_gmt":"2015-07-21T16:16:23","slug":"tam-vai-reduzir-operacoes-no-pais-e-estima-demissoes","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/tam-vai-reduzir-operacoes-no-pais-e-estima-demissoes\/","title":{"rendered":"TAM vai reduzir opera\u00e7\u00f5es no pa\u00eds e estima demiss\u00f5es"},"content":{"rendered":"<p style=\"text-align: justify;\">A companhia a\u00e9rea TAM anunciou que vai reduzir suas opera\u00e7\u00f5es no mercado dom\u00e9stico em at\u00e9 10%. Segundo a companhia, a estimativa \u00e9 que tamb\u00e9m haja demiss\u00f5es, com redu\u00e7\u00e3o de at\u00e9 2% no quadro de pessoal.<\/p>\n<div id=\"attachment_82028\" style=\"width: 586px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/001.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-82028\" class=\" wp-image-82028  \" alt=\"Companhia a\u00e9rea anunciou que pode cortar 2% do quadro de funcion\u00e1rios. (Foto: Divulga\u00e7\u00e3o)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/001.png\" width=\"576\" height=\"383\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/001.png 800w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/001-300x199.png 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/001-342x227.png 342w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/a><p id=\"caption-attachment-82028\" class=\"wp-caption-text\">Companhia a\u00e9rea anunciou que pode cortar 2% do quadro de funcion\u00e1rios. (Foto: Divulga\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">\u201cN\u00e3o haver\u00e1 impacto nas equipes de tripula\u00e7\u00e3o, dado os planos de crescimento de m\u00e9dio prazo. A companhia dar\u00e1 apoio aos colaboradores impactados por meio de consultorias especializadas em recoloca\u00e7\u00e3o profissional\u201d, diz nota da empresa.<\/p>\n<p style=\"text-align: justify;\">Segundo a TAM, a medida n\u00e3o afetar\u00e1 os destinos, uma vez que n\u00e3o deixar\u00e1 de operar voos para nenhuma das localidades servidas pela empresa. \u201cA TAM est\u00e1 tomando esta medida para enfrentar um contexto econ\u00f4mico dif\u00edcil no Brasil. Por isso se faz necess\u00e1rio buscar ajustes de malha sem prejudicar a conectividade dos nossos passageiros e fortalecendo ainda mais nossa competitividade no pa\u00eds\u201d, disse a presidenta da companhia, Claudia Sender.<\/p>\n<p style=\"text-align: justify;\">Em maio, a Associa\u00e7\u00e3o Brasileira das Empresas A\u00e9reas (Abear) j\u00e1 apontava para uma estagna\u00e7\u00e3o da demanda dom\u00e9stica do setor, registrando crescimento de apenas 1% em rela\u00e7\u00e3o ao mesmo m\u00eas do ano anterior. \u201cO cen\u00e1rio que temos descrito desde o segundo semestre de 2014 segue inalterado. Com menos neg\u00f3cios sendo fechados no pa\u00eds, reduzem-se as viagens de trabalho, e a avia\u00e7\u00e3o perde um p\u00fablico importante em quantidade e qualidade de receitas\u201d, disse Eduardo Sanovicz, presidente da entidade, na \u00e9poca.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: Ag\u00eancia Brasil<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A companhia a\u00e9rea TAM anunciou que vai reduzir suas opera\u00e7\u00f5es no mercado dom\u00e9stico em at\u00e9 10%. Segundo a companhia, a estimativa \u00e9 que tamb\u00e9m haja demiss\u00f5es, com redu\u00e7\u00e3o de at\u00e9 2% no quadro de pessoal. \u201cN\u00e3o haver\u00e1 impacto nas equipes de tripula\u00e7\u00e3o, dado os planos de crescimento de m\u00e9dio prazo. A companhia dar\u00e1 apoio aos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":82028,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-82027","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/82027"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=82027"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/82027\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/82028"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=82027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=82027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=82027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}