{"id":81999,"date":"2015-07-20T18:51:16","date_gmt":"2015-07-20T21:51:16","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=81999"},"modified":"2015-07-20T18:51:52","modified_gmt":"2015-07-20T21:51:52","slug":"familias-despejadas-da-ocupacao-dandara-estao-acampadas-em-rua-do-centro","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/familias-despejadas-da-ocupacao-dandara-estao-acampadas-em-rua-do-centro\/","title":{"rendered":"Fam\u00edlias despejadas da ocupa\u00e7\u00e3o Dandara est\u00e3o acampadas em rua do Centro"},"content":{"rendered":"<div id=\"attachment_82000\" style=\"width: 595px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/galeria_2_464_20150720104305_55acfae93fb64.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-82000\" class=\" wp-image-82000 \" alt=\"Foto: Jamile Pavlova\/Portal A8\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/galeria_2_464_20150720104305_55acfae93fb64.jpg\" width=\"585\" height=\"354\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/galeria_2_464_20150720104305_55acfae93fb64.jpg 650w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/galeria_2_464_20150720104305_55acfae93fb64-300x181.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/galeria_2_464_20150720104305_55acfae93fb64-342x206.jpg 342w\" sizes=\"(max-width: 585px) 100vw, 585px\" \/><\/a><p id=\"caption-attachment-82000\" class=\"wp-caption-text\">Foto: Jamile Pavlova\/Portal A8<\/p><\/div>\n<p style=\"text-align: justify;\">Um dia ap\u00f3s a desocupa\u00e7\u00e3o do pr\u00e9dio do antigo Hotel Aperip\u00ea, na chamda Ocupa\u00e7\u00e3o Dandara, no centro de Aracaju, muitas fam\u00edlias ainda ocupam com m\u00f3veis e pertences as ruas pr\u00f3ximas ao edif\u00edcio.<\/p>\n<p style=\"text-align: justify;\">Cerca de 80 fam\u00edlias foram desabrigadas neste domingo. Na manh\u00e3 desta segunda-feira (20), ainda 30 fam\u00edlias permanecem sem ter onde ficar. O cruzamento das ruas Capela com a rua S\u00e3o Crist\u00f3v\u00e3o foi obstru\u00eddo para que os populares se alojassem.<\/p>\n<p style=\"text-align: justify;\">De acordo com a representante dos desabrigados, Elis\u00e2ngela dos Santos, a maioria das fam\u00edlias encontrou um lugar para ficar ou alugou resid\u00eancias. Segundo ela, o munic\u00edpio realizou o cadastro dos desabrigados e se comprometeu em oferecer aux\u00edlio moradia at\u00e9 o m\u00eas de setembro.<\/p>\n<p style=\"text-align: justify;\">De imediato, as fam\u00edlias aguardam uma a\u00e7\u00e3o do Estado para tira-los da rua e lev\u00e1-los para um abrigo. \u201cTodo mundo est\u00e1 desesperado. Ningu\u00e9m quer ficar aqui no relento, tomando chuva, pegando sol. N\u00f3s queremos um lugar para ficar e at\u00e9 o momento o poder p\u00fablico n\u00e3o fez nada\u201d, afirma Elis\u00e2ngela.<\/p>\n<p style=\"text-align: justify;\"><strong>Tr\u00e2nsito<\/strong><\/p>\n<p style=\"text-align: justify;\">Os motoristas que tentaram transitar pela rua Capela no centro, tiveram que realizar o desvio pela rua Geru. J\u00e1 o acesso \u00e0 rua S\u00e3o Crist\u00f3v\u00e3o foi interferido pela rua Santo Amaro. Equipes da SMTT est\u00e3o trabalhando por toda regi\u00e3o para organizar e orientar os condutores.<\/p>\n<p style=\"text-align: justify;\"><strong>Nota<\/strong><\/p>\n<p style=\"text-align: justify;\">A Secretaria Municipal da Fam\u00edlia e da Assist\u00eancia Social (Semfas) informa que j\u00e1 realizou o cadastro das fam\u00edlias que se encontram no antigo Hotel Aperip\u00ea, na Ocupa\u00e7\u00e3o Dandara, para a concess\u00e3o do aux\u00edlio-moradia. Esclarece, por\u00e9m, que, para o requerimento do aux\u00edlio, \u00e9 necess\u00e1rio que as fam\u00edlias procurem casas para alugar e levem a documenta\u00e7\u00e3o necess\u00e1ria para o Centro de Refer\u00eancia de Assist\u00eancia Social (CRAS) Gon\u00e7alo Rollemberg Leite, onde ser\u00e1 requerido o benef\u00edcio. A Semfas informa ainda que estas informa\u00e7\u00f5es foram dadas aos moradores do pr\u00e9dio h\u00e1 cerca de oito dias, na ocasi\u00e3o do cadastro, e, que apenas a partir do requerimento, \u00e9 concedido o aluguel social. Das fam\u00edlias cadastradas, apenas uma fam\u00edlia foi \u00e0 unidade para requerer o benef\u00edcio. As fam\u00edlias da Dandara receber\u00e3o o aux\u00edlio-moradia at\u00e9 que sejam inseridas em programas de habita\u00e7\u00e3o popular.<\/p>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es do A8SE<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um dia ap\u00f3s a desocupa\u00e7\u00e3o do pr\u00e9dio do antigo Hotel Aperip\u00ea, na chamda Ocupa\u00e7\u00e3o Dandara, no centro de Aracaju, muitas fam\u00edlias ainda ocupam com m\u00f3veis e pertences as ruas pr\u00f3ximas ao edif\u00edcio. Cerca de 80 fam\u00edlias foram desabrigadas neste domingo. Na manh\u00e3 desta segunda-feira (20), ainda 30 fam\u00edlias permanecem sem ter onde ficar. O cruzamento [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":82000,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":{"0":"post-81999","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/81999"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=81999"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/81999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/82000"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=81999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=81999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=81999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}