{"id":81888,"date":"2015-07-16T16:52:26","date_gmt":"2015-07-16T19:52:26","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=81888"},"modified":"2015-07-18T11:34:22","modified_gmt":"2015-07-18T14:34:22","slug":"pedrinho-barreto-e-nomeado-como-o-novo-presidente-do-psdb-em-sergipe","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/pedrinho-barreto-e-nomeado-como-o-novo-presidente-do-psdb-em-sergipe\/","title":{"rendered":"Pedrinho Barreto \u00e9 nomeado como o novo presidente do PSDB em Sergipe"},"content":{"rendered":"<p style=\"text-align: justify;\">O advogado Pedrinho Barreto foi nomeado como o novo presidente estadual do Partido da Social Democracia Brasileira (PSDB). Ele foi indicado pelo grupo liderado pelo senador Eduardo Amorim (PSC) e a chapa montada foi avaliada e aprovada pela executiva nacional do partido em Bras\u00edlia.<\/p>\n<p style=\"text-align: justify;\">&#8220;Recebi o convite e aceitei o desafio para somar. Vamos apoiar o trabalho realizado pelo vice-prefeito de Aracaju, Jos\u00e9 Carlos Machado, e demais filiados com ou sem cargo do interior do estado\u201d, garante.<\/p>\n<div id=\"attachment_81889\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/11755695_861895800551220_696332753656800827_n-e1437076283683.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-81889\" class=\"size-full wp-image-81889\" alt=\"A\u00e9cio Neves, presidente nacional do PSDB, cumprimenta Pedrinho Barreto em Brasilia (Foto: Arquivo Pessoal)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/11755695_861895800551220_696332753656800827_n-e1437076283683.jpg\" width=\"599\" height=\"449\" \/><\/a><p id=\"caption-attachment-81889\" class=\"wp-caption-text\">A\u00e9cio Neves, presidente nacional do PSDB, cumprimenta Pedrinho Barreto em Brasilia (Foto: Arquivo Pessoal)<\/p><\/div>\n<p style=\"text-align: justify;\">O novo presidente desconversou quando foi questionado sobre o futuro do partido. &#8220;Ainda n\u00e3o discutimos sobre isso. O momento \u00e9 para a nova executiva conhecer a estrutura e depois come\u00e7ar a pensar nas elei\u00e7\u00f5es municipais de 2016&#8221;.<\/p>\n<p style=\"text-align: justify;\">Jos\u00e9 Carlos Machado continua no partido e assume a fun\u00e7\u00e3o de secret\u00e1rio. A executiva estadual conta ainda com Jo\u00e3o Fontes (vice-presidente), Walter Soares Filho (tesoureiro), Dielson Tadeu Barreto Leite, Edna Quit\u00e9ria do Amorim Cista, Zeca Ramos da Silva e Jo\u00e3o Bosco Dantas de Andrade Lima.<\/p>\n<p>No in\u00edcio deste m\u00eas, Pedrinho assinou a desfilia\u00e7\u00e3o do Partido da Rep\u00fablica (PR) e filiou-se aoPSDB\u00a0no Tribunal Reguonal Eleitoral (TRE).<\/p>\n<p style=\"text-align: justify;\">Pedrinho j\u00e1 foi filiado ao PSDB e PR, nas elei\u00e7\u00f5es de 2012 ficou como suplente de vereador deAracaju. No Governo\u00a0Albano Franco\u00a0foi secret\u00e1rio geral.<\/p>\n<p>Atualmente o PSDB tem dois prefeitos (Itabaianinha\u00a0e\u00a0Lagarto), cinco vice-prefeitos e 36 vereadores. Na semana passada os prefeitos de\u00a0Itaporanga\u00a0D&#8217;Ajuda, Maria das Gra\u00e7as Souza Garcez, e de Santa Luzia do Itanhy, Edson Santos Cruz, deixaram o partido.<\/p>\n<p><strong><em>Fredson Navarro, do G1 SE<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O advogado Pedrinho Barreto foi nomeado como o novo presidente estadual do Partido da Social Democracia Brasileira (PSDB). Ele foi indicado pelo grupo liderado pelo senador Eduardo Amorim (PSC) e a chapa montada foi avaliada e aprovada pela executiva nacional do partido em Bras\u00edlia. &#8220;Recebi o convite e aceitei o desafio para somar. Vamos apoiar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":81889,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-81888","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/81888"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=81888"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/81888\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/81889"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=81888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=81888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=81888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}