{"id":81653,"date":"2015-07-09T09:33:03","date_gmt":"2015-07-09T12:33:03","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=81653"},"modified":"2015-07-10T10:05:17","modified_gmt":"2015-07-10T13:05:17","slug":"motociclista-morre-apos-colisao-com-um-cavalo-em-lagarto","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/motociclista-morre-apos-colisao-com-um-cavalo-em-lagarto\/","title":{"rendered":"Motociclista morre ap\u00f3s colis\u00e3o com um cavalo, em Lagarto"},"content":{"rendered":"<p style=\"text-align: justify;\">Um homem colidiu contra um animal na regi\u00e3o do Povoado Boieiro, em Lagarto, e acabou morrendo no local. O acidente aconteceu por volta das 4h de hoje (9)<\/p>\n<div id=\"attachment_81654\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/Motociclista-e1436444974395.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-81654\" class=\"size-full wp-image-81654\" alt=\"Motociclista morre em colis\u00e3o com um cavalo. (Foto: Portal Lagartense)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/Motociclista-e1436444974395.jpg\" width=\"599\" height=\"449\" \/><\/a><p id=\"caption-attachment-81654\" class=\"wp-caption-text\">Motociclista morre em colis\u00e3o com um cavalo. (Foto: Portal Lagartense)<\/p><\/div>\n<p style=\"text-align: justify;\">Segundo informa\u00e7\u00f5es, o homem, que foi identificado como Jos\u00e9 dos Reis, morador do munic\u00edpio de Sim\u00e3o Dias, bateu a motocicleta em que seguia contra um burro. O impacto da colis\u00e3o foi muito forte e o condutor acabou n\u00e3o resistindo aos ferimentos.<\/p>\n<p style=\"text-align: justify;\">Segundo informa\u00e7\u00f5es, a v\u00edtima trabalhava numa empresa do ramo de cimentos. Uma viatura do Instituto M\u00e9dico Legal (IML) foi ao local para recolhimento do corpo. A Pol\u00edcia Militar esteve na ocorr\u00eancia.<\/p>\n<p style=\"text-align: justify;\">Acompanhe o SE Not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Informa\u00e7\u00f5es do Portal Lagartense<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem colidiu contra um animal na regi\u00e3o do Povoado Boieiro, em Lagarto, e acabou morrendo no local. O acidente aconteceu por volta das 4h de hoje (9) Segundo informa\u00e7\u00f5es, o homem, que foi identificado como Jos\u00e9 dos Reis, morador do munic\u00edpio de Sim\u00e3o Dias, bateu a motocicleta em que seguia contra um burro. O [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":81654,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-81653","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/81653"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=81653"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/81653\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/81654"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=81653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=81653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=81653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}