{"id":81359,"date":"2015-07-01T14:00:58","date_gmt":"2015-07-01T17:00:58","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=81359"},"modified":"2015-07-02T17:31:11","modified_gmt":"2015-07-02T20:31:11","slug":"policia-apreende-r-600-mil-em-carga-roubada-no-municipio-de-lagarto","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/policia-apreende-r-600-mil-em-carga-roubada-no-municipio-de-lagarto\/","title":{"rendered":"Pol\u00edcia apreende R$ 600 mil em carga roubada no munic\u00edpio de Lagarto"},"content":{"rendered":"<p style=\"text-align: justify;\">A Delegacia de Combate ao Roubo de Cargas de Sergipe realizou uma entrevista coletiva na manh\u00e3 desta quarta-feira (1) para divulgar a apreens\u00e3o de R$ 600 mil em carga roubada. O material foi encontrado em galp\u00f5es de uma f\u00e1brica no povoado Col\u00f4nia 13, no munic\u00edpio de Lagarto, centro-sul de Sergipe.<\/p>\n<div id=\"attachment_81360\" style=\"width: 568px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/carga01.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-81360\" class=\" wp-image-81360 \" alt=\"Carga avaliada em R$ 600 mil saiu de S\u00e3o Paulo e tinha como destino final Pernambuco (Foto: T\u00e1ssio Andrade\/G1) \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/carga01.jpg\" width=\"558\" height=\"419\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/carga01.jpg 620w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/carga01-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/carga01-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/carga01-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/carga01-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/07\/carga01-269x201.jpg 269w\" sizes=\"(max-width: 558px) 100vw, 558px\" \/><\/a><p id=\"caption-attachment-81360\" class=\"wp-caption-text\">Carga avaliada em R$ 600 mil saiu de S\u00e3o Paulo e tinha como destino final Pernambuco (Foto: T\u00e1ssio Andrade\/G1)<\/p><\/div>\n<p style=\"text-align: justify;\">Segundo o delegado Cristino Barreto, os produtos, m\u00e1quinas de lavar e fornos el\u00e9tricos, foram roubados de um caminh\u00e3o bitrem no domingo (28). \u201cDois indiv\u00edduos armados renderam o motorista do \u00f4nibus em um posto de gasolina em Alagoinhas, na Bahia. O rapaz foi mantido ref\u00e9m durante 12 horas at\u00e9 a carga ter seu destino programado pelos assaltantes\u201d, conta o delegado.<\/p>\n<p style=\"text-align: justify;\">O caminh\u00e3o foi abandonado no munic\u00edpio de Coronel Jo\u00e3o S\u00e1, na Bahia. \u201cA carga foi levada para outro ve\u00edculo, mais dois homens estavam aguardando a carga roubada no povoado Loreto, divisa entre Bahia e Sergipe, no munic\u00edpio de Rio Real. Logo em seguida, o motorista foi liberado, ele procurou ajuda da Pol\u00edcia Rodovi\u00e1ria Federal em Cristin\u00e1polis. Entramos em contato com o representante da empresa respons\u00e1vel pela carga roubada e encaminhamos uma equipe de policiais at\u00e9 o munic\u00edpio de Lagarto. A den\u00fancia que recebemos estava correta e encontramos todo o material roubado\u201d, explica Cristiano Barreto.<\/p>\n<p style=\"text-align: justify;\">O caminh\u00e3o saiu do Estado de S\u00e3o Paulo e tinha como destino final Pernambuco. \u201cAcredito que a carga depois que foi roubada, tinha como destino certo essa regi\u00e3o do centro-sul de Sergipe. Essa \u00e9 a terceira apreens\u00e3o no munic\u00edpio de Lagarto, acreditamos que a regi\u00e3o virou um ponto de recepta\u00e7\u00e3o e distribui\u00e7\u00e3o de carga roubada\u201d, diz o delegado.<\/p>\n<p style=\"text-align: justify;\">Os donos dos galp\u00f5es onde a carga roubada foi encontrada informaram \u00e0 pol\u00edcia que aluga o espa\u00e7o para terceiros. \u201cA informa\u00e7\u00e3o que temos neste princ\u00edpio de investiga\u00e7\u00e3o \u00e9 que a f\u00e1brica possui alguns galp\u00f5es que s\u00e3o destinados para o aluguel. O representante da empresa nos entregou o contrato de aluguel com o nome do locat\u00e1rio, mas essa pessoa at\u00e9 o momento n\u00e3o foi localizada, a pol\u00edcia continua investigando toda a situa\u00e7\u00e3o\u201d, conclui Cristiano Barreto.<\/p>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es do G1, em Sergipe<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Delegacia de Combate ao Roubo de Cargas de Sergipe realizou uma entrevista coletiva na manh\u00e3 desta quarta-feira (1) para divulgar a apreens\u00e3o de R$ 600 mil em carga roubada. O material foi encontrado em galp\u00f5es de uma f\u00e1brica no povoado Col\u00f4nia 13, no munic\u00edpio de Lagarto, centro-sul de Sergipe. Segundo o delegado Cristino Barreto, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":81360,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[310,7],"tags":[],"class_list":{"0":"post-81359","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques-da-semana","8":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/81359"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=81359"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/81359\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/81360"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=81359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=81359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=81359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}