{"id":81149,"date":"2015-06-25T23:44:36","date_gmt":"2015-06-26T02:44:36","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=81149"},"modified":"2015-06-25T23:44:36","modified_gmt":"2015-06-26T02:44:36","slug":"tce-estabelece-os-indices-provisorios-de-icms-para-2016","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/tce-estabelece-os-indices-provisorios-de-icms-para-2016\/","title":{"rendered":"TCE estabelece os \u00edndices provis\u00f3rios de ICMS para 2016"},"content":{"rendered":"<div id=\"attachment_81150\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/06\/12372014123558.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-81150\" class=\"size-medium wp-image-81150\" alt=\"Foto: Cleverton Ribeiro\/TCE\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/06\/12372014123558-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/06\/12372014123558-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/06\/12372014123558-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/06\/12372014123558-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/06\/12372014123558-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/06\/12372014123558-269x201.jpg 269w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/06\/12372014123558.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-81150\" class=\"wp-caption-text\">Foto: Cleverton Ribeiro\/TCE<\/p><\/div>\n<p style=\"text-align: justify;\">Os \u00edndices percentuais provis\u00f3rios de ICMS pertencentes aos munic\u00edpios sergipanos para o ano de 2016 foram definidos pelo Tribunal de Contas do Estado (TCE\/SE) na manh\u00e3 desta quinta-feira (25). A partir da publica\u00e7\u00e3o no Di\u00e1rio Oficial do Estado, prevista para a pr\u00f3xima segunda-feira (29), os munic\u00edpios ter\u00e3o o prazo de 30 dias para apresentar impugna\u00e7\u00e3o, desde que devidamente comprovada alguma incorre\u00e7\u00e3o nas informa\u00e7\u00f5es prestadas pelos contribuintes.<\/p>\n<p style=\"text-align: justify;\">Na sess\u00e3o do Pleno, a diverg\u00eancia ficou por conta do rateio do Valor Adicionado Fiscal (VAF) proveniente da Companhia Hidroel\u00e9trica do S\u00e3o Francisco (Chesf). Por maioria, seguindo o voto do conselheiro Carlos Alberto Sobral, o colegiado, com base em liminar do Desembargador Jos\u00e9 Art\u00eamio Barreto, ratificada posteriormente pelo Ministro do Supremo Tribunal Federal (STF), Nelson Jobim, manteve o entendimento de que toda a produ\u00e7\u00e3o da Usina de Xing\u00f3 dever\u00e1 ser revertida para o munic\u00edpio de Canind\u00e9 do S\u00e3o Francisco.<\/p>\n<p style=\"text-align: justify;\">Em seu voto vencido, o conselheiro-relator Cl\u00f3vis Barbosa questionou a destina\u00e7\u00e3o dos 100% desse Valor Adicionado Fiscal para o munic\u00edpio de Canind\u00e9 devido \u00e0 Chesf informar apenas 50% de sua produ\u00e7\u00e3o para o munic\u00edpio. Para Cl\u00f3vis, \u201ca decis\u00e3o judicial liminar do Ministro Nelson Jobim tem validade apenas para o Ato Deliberativo n\u00ba. 678\/04, de sorte que o Tribunal n\u00e3o pode, sem decis\u00e3o judicial que assim o ordene, duplicar os valores que s\u00e3o informados pelos contribuintes \u00e0 Sefaz, sob pena de prejudicar todos os munic\u00edpios\u201d.<\/p>\n<p style=\"text-align: justify;\">No relat\u00f3rio aprovado pelo Pleno consta ainda a sugest\u00e3o de verifica\u00e7\u00e3o fiscal \u00e0 Secretaria de Estado da Fazenda (Sefaz), nos contribuintes que tiveram incremento, redu\u00e7\u00e3o ou n\u00e3o informaram o VAF. Entre eles est\u00e1 a Petrobras, que no exerc\u00edcio financeiro 2014 alterou seu movimento econ\u00f4mico e fiscal significativamente, impactando na redu\u00e7\u00e3o do VAF total de alguns munic\u00edpios.<\/p>\n<p style=\"text-align: justify;\">Ao dar cumprimento \u00e0 sua fun\u00e7\u00e3o constitucional de efetuar os c\u00e1lculos para defini\u00e7\u00e3o das quotas pertencentes a cada munic\u00edpio em 2016, o TCE utiliza como base os dados consolidados pela Secretaria de Estado da Fazenda referentes \u00e0s declara\u00e7\u00f5es de informa\u00e7\u00f5es dos contribuintes nos exerc\u00edcios de 2013 e 2014.<\/p>\n<p style=\"text-align: justify;\">Ainda no relat\u00f3rio, elaborado pela Comiss\u00e3o T\u00e9cnica do ICMS, consta que o Valor Adicionado Fiscal do Estado de Sergipe no exerc\u00edcio de 2014 \u00e9 de R$10.612.395.93209, apresentando 22.387 declara\u00e7\u00f5es \u00e0 Corte de Contas.<\/p>\n<p style=\"text-align: justify;\">De todo o produto da arrecada\u00e7\u00e3o do ICMS 25% pertencem aos munic\u00edpios. Destes, 1\/4 \u00e9 dividido em partes iguais entre todos eles enquanto os 3\/4 restantes respeitam a propor\u00e7\u00e3o do Valor Adicionado Fiscal.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: TCE<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os \u00edndices percentuais provis\u00f3rios de ICMS pertencentes aos munic\u00edpios sergipanos para o ano de 2016 foram definidos pelo Tribunal de Contas do Estado (TCE\/SE) na manh\u00e3 desta quinta-feira (25). A partir da publica\u00e7\u00e3o no Di\u00e1rio Oficial do Estado, prevista para a pr\u00f3xima segunda-feira (29), os munic\u00edpios ter\u00e3o o prazo de 30 dias para apresentar impugna\u00e7\u00e3o, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":81150,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-81149","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/81149"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=81149"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/81149\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/81150"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=81149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=81149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=81149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}