{"id":79789,"date":"2015-05-18T14:34:40","date_gmt":"2015-05-18T17:34:40","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=79789"},"modified":"2015-05-18T14:34:40","modified_gmt":"2015-05-18T17:34:40","slug":"travestis-e-transexuais-poderao-usar-nome-social-no-enem-2015","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/travestis-e-transexuais-poderao-usar-nome-social-no-enem-2015\/","title":{"rendered":"Travestis e transexuais poder\u00e3o usar nome social no Enem 2015"},"content":{"rendered":"<div id=\"attachment_79690\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/enem-logo-6.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-79690\" class=\"size-medium wp-image-79690\" alt=\"Foto: Divulga\u00e7\u00e3o \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/enem-logo-6-300x192.jpg\" width=\"300\" height=\"192\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/enem-logo-6-300x192.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/enem-logo-6-342x219.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/enem-logo-6.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-79690\" class=\"wp-caption-text\">Foto: Divulga\u00e7\u00e3o<\/p><\/div>\n<p style=\"text-align: justify;\">Travestis e transexuais poder\u00e3o solicitar este ano o uso do nome social no Exame Nacional do Ensino M\u00e9dio (Enem) ap\u00f3s a inscri\u00e7\u00e3o pela internet. O nome social passou a ser adotado oficialmente na aplica\u00e7\u00e3o do exame no ano passado, mas era preciso solicitar o uso por telefone. No dia do exame, as pessoas trans dever\u00e3o ser tratadas pelo nome com o qual se identificam e n\u00e3o pelo nome que consta no documento de identidade. Al\u00e9m disso, usar\u00e3o o banheiro do g\u00eanero com o qual se identificam.<\/p>\n<p style=\"text-align: justify;\">&#8220;Isso quer dizer que ningu\u00e9m da equipe do Enem poder\u00e1 se dirigir \u00e0 pessoa por um nome que n\u00e3o seja o da sua condi\u00e7\u00e3o, o que se inscreveu. O nome que essa pessoa usa \u00e9 com o qual deve ser chamado&#8221;, afirmou o ministro da Educa\u00e7\u00e3o, Renato Janine Ribeiro. &#8220;As pessoas t\u00eam o direito de ser tratadas com o respeito que merecem. Portanto, ningu\u00e9m deve submet\u00ea-las a situa\u00e7\u00e3o vexat\u00f3ria&#8221;, acrescentou o ministro.<\/p>\n<p style=\"text-align: justify;\">Ano passado, foram feitos 95 requerimentos por telefone para o uso do nome social.<\/p>\n<p style=\"text-align: justify;\">Nesta edi\u00e7\u00e3o, os participantes que desejarem esse atendimento dever\u00e3o enviar c\u00f3pia do documento de identifica\u00e7\u00e3o, formul\u00e1rio preenchido e foto recente pelo sistema de inscri\u00e7\u00e3o de 15 a 26 de junho, ap\u00f3s o per\u00edodo de inscri\u00e7\u00e3o, que \u00e9 de 25 de maio a 5 de junho.<\/p>\n<p style=\"text-align: justify;\">Para o cantor e ativista trans Erick Barbi, a medida foi bem recebida. &#8220;O simples fato de o MEC autorizar o nome social j\u00e1 na inscri\u00e7\u00e3o tira o peso de termos que nos explicar para as demais pessoas. Alivia muito o processo e, com certeza, levar\u00e1 mais jovens ao exame. Todos ficar\u00e3o mais tranquilos e poder\u00e3o melhorar at\u00e9 o desempenho na prova.&#8221;<\/p>\n<p style=\"text-align: justify;\">Ele destaca ainda a import\u00e2ncia do uso do banheiro de acordo com a identidade de g\u00eanero: &#8220;A maioria das pessoas trans tem problemas ao frequentar o banheiro. Muitos evitam ir ao banheiro&#8221;, acrescenta.<\/p>\n<p style=\"text-align: justify;\">Coordenadora colegiada do F\u00f3rum de L\u00e9sbicas, Gays, Bissexuais, Travestis e Transexuais (F\u00f3rum LGBT) do Esp\u00edrito Santo, Deborah Sabar\u00e1 fez o Enem em 2014 e vai se inscrever novamente este ano. Ela quer cursar servi\u00e7o social. &#8220;Sabemos que \u00e9 dif\u00edcil ingressar em uma escola com um g\u00eanero diferente do que o sexo designa, mas com o direito de usar o nome social a gente constroi esse espa\u00e7o&#8221;, destacou.<\/p>\n<p style=\"text-align: justify;\">Deborah informou que, desde a prova do ano passado, recebe mensagens de outras travestis e transexuais pedindo informa\u00e7\u00f5es e mostrando interesse no exame. &#8220;Vou participar de novo e usar isso como instrumento de milit\u00e2ncia, de modo a incentivar outras a participarem e voltarem a estudar.&#8221;<\/p>\n<p style=\"text-align: justify;\">Para a pedagoga Janaina Lima, integrante do Grupo Identidade, de Campinas, a iniciativa \u00e9 positiva, na medida que atrai travestis e transsexuais para os estudos. Ela ficou quase 20 anos afastada da escola e disse que voltou a estudar &#8220;gra\u00e7as ao Enem&#8221;. Ela conseguiu ingresssar na gradua\u00e7\u00e3o pelo Programa Universidade para Todos (ProUni).<\/p>\n<p style=\"text-align: justify;\">Segundo Janaina, a possibilidade de ser chamada pelo nome da identidade afastava as pessoas trans. &#8220;Quando a pessoa ia fazer o Enem tinha a quest\u00e3o do nome, uma barreira, podia ser colocada em uma situa\u00e7\u00e3o vexat\u00f3ria. Agora, se tiver, \u00e9 uma pessoa ou outra que vai querer praticar ato discriminat\u00f3rio, vai ser menor e \u00e9 uma pessoa, e n\u00e3o a institui\u00e7\u00e3o.&#8221;<\/p>\n<p style=\"text-align: justify;\">O edital do exame ser\u00e1 publicado nesta segunda-feira (18) no Di\u00e1rio Oficial da Uni\u00e3o. As provas ser\u00e3o nos dias 24 e 25 de outubro.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: Ag\u00eancia Brasil<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Travestis e transexuais poder\u00e3o solicitar este ano o uso do nome social no Exame Nacional do Ensino M\u00e9dio (Enem) ap\u00f3s a inscri\u00e7\u00e3o pela internet. O nome social passou a ser adotado oficialmente na aplica\u00e7\u00e3o do exame no ano passado, mas era preciso solicitar o uso por telefone. No dia do exame, as pessoas trans dever\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":79690,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[],"class_list":{"0":"post-79789","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-educacao"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/79789"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=79789"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/79789\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/79690"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=79789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=79789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=79789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}