{"id":79684,"date":"2015-05-15T08:22:05","date_gmt":"2015-05-15T11:22:05","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=79684"},"modified":"2015-05-15T08:23:20","modified_gmt":"2015-05-15T11:23:20","slug":"suspeitos-de-trafico-de-drogas-sao-presos-em-hospital-abandonado","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/suspeitos-de-trafico-de-drogas-sao-presos-em-hospital-abandonado\/","title":{"rendered":"Suspeitos de tr\u00e1fico de drogas s\u00e3o presos em hospital abandonado"},"content":{"rendered":"<p style=\"text-align: justify;\">A pol\u00edcia prendeu em flagrante nesta quinta-feira (14) tr\u00eas homens suspeitos de tr\u00e1fico de drogas, no Bairro Siqueira Campos, em Aracaju. Eles foram flagrados em um pr\u00e9dio abandonado onde funcionava um hospital psiqui\u00e1trico e abriga algumas fam\u00edlias.<\/p>\n<div id=\"attachment_79685\" style=\"width: 568px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150514-wa0047.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-79685\" class=\" wp-image-79685 \" alt=\"Suspeitos de tr\u00e1fico de drogas s\u00e3o presos em hospital abandonado (Foto: Getam \/ Divulga\u00e7\u00e3o) \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150514-wa0047.jpg\" width=\"558\" height=\"419\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150514-wa0047.jpg 620w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150514-wa0047-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150514-wa0047-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150514-wa0047-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150514-wa0047-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150514-wa0047-269x201.jpg 269w\" sizes=\"(max-width: 558px) 100vw, 558px\" \/><\/a><p id=\"caption-attachment-79685\" class=\"wp-caption-text\">Suspeitos de tr\u00e1fico de drogas s\u00e3o presos em hospital abandonado (Foto: Getam \/ Divulga\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">De acordo com o capit\u00e3o Wenner Ferreira do Grupamento Especial T\u00e1tico de Motos (Getam), quando a pol\u00edcia se aproximou um dos suspeitos jogou uma sacola branca para o alto e o fato chamou aten\u00e7\u00e3o e atraiu curiosos<\/p>\n<p style=\"text-align: justify;\">Policiais flagraram na sacola uma grande quantidade de maconha prensada. Tamb\u00e9m foram encontrados no pr\u00e9dio abandonado onde eles estavam v\u00e1rios produtos como televisor e aparelhos celulares, al\u00e9m de 17 p\u00e1ssaros silvestres. Os suspeitos foram encaminhados para a 8\u00aa Delegacia.<\/p>\n<div id=\"attachment_79686\" style=\"width: 568px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150514-wa0043.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-79686\" class=\" wp-image-79686 \" alt=\"P\u00e1ssaros silvestres tamb\u00e9m foram apreendidos (Foto: Getam \/ Divulga\u00e7\u00e3o) \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150514-wa0043.jpg\" width=\"558\" height=\"419\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150514-wa0043.jpg 620w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150514-wa0043-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150514-wa0043-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150514-wa0043-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150514-wa0043-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150514-wa0043-269x201.jpg 269w\" sizes=\"(max-width: 558px) 100vw, 558px\" \/><\/a><p id=\"caption-attachment-79686\" class=\"wp-caption-text\">P\u00e1ssaros silvestres tamb\u00e9m foram apreendidos (Foto: Getam \/ Divulga\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es do G1, em Sergipe<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pol\u00edcia prendeu em flagrante nesta quinta-feira (14) tr\u00eas homens suspeitos de tr\u00e1fico de drogas, no Bairro Siqueira Campos, em Aracaju. Eles foram flagrados em um pr\u00e9dio abandonado onde funcionava um hospital psiqui\u00e1trico e abriga algumas fam\u00edlias. De acordo com o capit\u00e3o Wenner Ferreira do Grupamento Especial T\u00e1tico de Motos (Getam), quando a pol\u00edcia se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":79685,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-79684","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/79684"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=79684"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/79684\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/79685"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=79684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=79684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=79684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}