{"id":79521,"date":"2015-05-12T11:08:35","date_gmt":"2015-05-12T14:08:35","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=79521"},"modified":"2015-05-13T11:16:24","modified_gmt":"2015-05-13T14:16:24","slug":"governador-jackson-barreto-e-secretario-mendonca-prado-participam-de-promocao-de-oficiais-no-corpo-de-bombeiros","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/governador-jackson-barreto-e-secretario-mendonca-prado-participam-de-promocao-de-oficiais-no-corpo-de-bombeiros\/","title":{"rendered":"Jackson Barreto e  Prado participam de promo\u00e7\u00e3o de oficiais no Corpo de Bombeiros"},"content":{"rendered":"<p style=\"text-align: justify;\">O Corpo de Bombeiros Militar de Sergipe realizou na tarde dessa segunda-feira, 11, uma solenidade de promo\u00e7\u00e3o de oficiais ao posto de coronel QOBM.<\/p>\n<div id=\"attachment_79523\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/Bombeiros-e1431439901817.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-79523\" class=\"size-full wp-image-79523\" alt=\"Em seu discurso, o Comandante Geral enfatizou o empenho do Governador do Estado, Jackson Barreto, que se fez presente na solenidade. (Foto: CBMS)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/Bombeiros-e1431439901817.jpg\" width=\"599\" height=\"399\" \/><\/a><p id=\"caption-attachment-79523\" class=\"wp-caption-text\">Em seu discurso, o Comandante Geral enfatizou o empenho do Governador do Estado, Jackson Barreto, que se fez presente na solenidade. (Foto: CBMS)<\/p><\/div>\n<p style=\"text-align: justify;\">Na oportunidade, tamb\u00e9m foi inaugurado o audit\u00f3rio da Corpora\u00e7\u00e3o, o qual leva o nome da professora Neuzice Barreto de Lima. \u201cEste preito objetivou homenagear o centen\u00e1rio desta grande mulher, que exerceu um papel ativo, interativo e protag\u00f4nico como agente de mudan\u00e7a, tal qual a hist\u00f3ria desta Corpora\u00e7\u00e3o\u201d, ressaltou o Comandante Geral do CBMSE, o Coronel Reginaldo D\u00f3ria de Freitas.<\/p>\n<p>A obra compreendida em um espa\u00e7o de 400m\u00b2, localizada no quartel do Comando Geral do Bombeiro, foi or\u00e7ada em aproximadamente 500 mil reais, constru\u00edda com recursos pr\u00f3prios do er\u00e1rio estadual.<\/p>\n<p style=\"text-align: justify;\">Em seu discurso, o Comandante Geral enfatizou o empenho do Governador do Estado, Jackson Barreto, que se fez presente na solenidade, e dos engenheiros da Corpora\u00e7\u00e3o, o capit\u00e3o Silvio Leonardo e o capit\u00e3o Cleiton Cruz, bem como agradeceu o trabalho de todos os oper\u00e1rios da empresa Sergifrio LTDA.<\/p>\n<p style=\"text-align: justify;\">Durante o evento, o comandante anunciou que j\u00e1 se iniciaram os trabalhos de licita\u00e7\u00e3o para a conclus\u00e3o da reforma do Centro de Manuten\u00e7\u00e3o desta Institui\u00e7\u00e3o, com previs\u00e3o para ser conclu\u00edda ainda este ano. Esta Unidade Operacional levar\u00e1 o nome da 3\u00ba Sargento Tha\u00edse Fernanda Santana dos Santos (in memorian), a primeira profissional mulher a conduzir uma viatura de urg\u00eancia e emerg\u00eancia do estado de Sergipe.<\/p>\n<p style=\"text-align: justify;\">O Governador Jackson Barreto enfatizou a import\u00e2ncia das a\u00e7\u00f5es do bombeiro, ressaltando que durante o seu governo e o de Marcelo D\u00e9da foram investidos mais de 10 milh\u00f5es de reais, enaltecendo a seriedade deste trabalho, e ao agradecer a homenagem feita \u00e0 sua genitora, se emocionou ao falar da hist\u00f3ria de vida de sua m\u00e3e, uma mulher de fibra e sonhadora. \u201cFico feliz pela homenagem \u00e0quele audit\u00f3rio que recebeu o nome da minha m\u00e3e. Fique sabendo, coronel Reginaldo, que isso vai ficar guardado nesse cora\u00e7\u00e3o\u201d, afirmou Barreto.<\/p>\n<p><strong>Acompanhe o SE Not\u00edcias no Twitter e no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p>Ag\u00eancia Sergipe de Not\u00edcias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Corpo de Bombeiros Militar de Sergipe realizou na tarde dessa segunda-feira, 11, uma solenidade de promo\u00e7\u00e3o de oficiais ao posto de coronel QOBM. Na oportunidade, tamb\u00e9m foi inaugurado o audit\u00f3rio da Corpora\u00e7\u00e3o, o qual leva o nome da professora Neuzice Barreto de Lima. \u201cEste preito objetivou homenagear o centen\u00e1rio desta grande mulher, que exerceu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":79523,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-79521","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/79521"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=79521"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/79521\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/79523"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=79521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=79521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=79521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}