{"id":79518,"date":"2015-05-12T09:51:06","date_gmt":"2015-05-12T12:51:06","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=79518"},"modified":"2015-05-13T13:43:55","modified_gmt":"2015-05-13T16:43:55","slug":"criminosos-explodem-caixas-eletronicos-do-banese-em-malhador","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/criminosos-explodem-caixas-eletronicos-do-banese-em-malhador\/","title":{"rendered":"Criminosos explodem caixas eletr\u00f4nicos do Banese em Malhador"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>Do G1 SE<\/em><\/p>\n<p style=\"text-align: justify;\">Uma ag\u00eancia do Banco do Estado de Sergipe (Banese) foi algo de um grupo de criminosos na madrugada desta ter\u00e7a-feira (12) em Malhador. Segundo uma vizinha da institui\u00e7\u00e3o financeira, foram tr\u00eas explos\u00f5es seguidas durante a madrugada, a mais forte foi sentida na parte mais interna da casa dela.<\/p>\n<div id=\"attachment_79519\" style=\"width: 606px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150512-wa0034.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-79519\" class=\"size-full wp-image-79519\" alt=\"Ag\u00eancia do Banese foi destru\u00edda com o impacto das explos\u00f5es (Foto: Luzia Souza\/VC na TV Sergipe)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150512-wa0034.jpg\" width=\"596\" height=\"447\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150512-wa0034.jpg 596w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150512-wa0034-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150512-wa0034-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150512-wa0034-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150512-wa0034-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/05\/img-20150512-wa0034-269x201.jpg 269w\" sizes=\"(max-width: 596px) 100vw, 596px\" \/><\/a><p id=\"caption-attachment-79519\" class=\"wp-caption-text\">Ag\u00eancia do Banese foi destru\u00edda com o impacto das explos\u00f5es (Foto: Luzia Souza\/VC na TV Sergipe)<\/p><\/div>\n<p style=\"text-align: justify;\">\u201cDava para ouvir eles correndo dentro do banco e falando alto para os outros serem mais r\u00e1pidos e explodir logo. A a\u00e7\u00e3o durou de 5 a 10 minutos e uma outra vizinha chegou a ir na cal\u00e7ada depois do susto da explos\u00e3o, foi quando ela diz que um homem armado mandou ela voltar para casa que n\u00e3o era para ela ver essas coisas\u201d, afirma a mulher que prefere n\u00e3o ser identificada. Segundo ela, as explos\u00f5es provocaram rachaduras na parede da casa dela.<\/p>\n<p style=\"text-align: justify;\">O Centro Integrado de Opera\u00e7\u00f5es de Seguran\u00e7a P\u00fablica (Ciosp) confirma o roubo a ag\u00eancia. Segundo a testemunha, tr\u00eas carros ficaram nas esquinas do banco fazendo a seguran\u00e7a dos que estavam dentro do banco. A pol\u00edcia chegou ao local minutos depois, mas os criminosos j\u00e1 haviam fugido.<\/p>\n<p style=\"text-align: justify;\">A assessoria de comunica\u00e7\u00e3o da Pol\u00edcia Militar informa que oito homens armados, suspeitos de roubar o banco, foram perseguidos e entraram em confronto com os policiais na regi\u00e3o rural no trecho entre Malhador e Areia Branca, pr\u00f3ximo a Serra de Itabaiana.<\/p>\n<p style=\"text-align: justify;\">&#8220;Um dos ve\u00edculos utilizados pelo grupo, um Fox prata com placa de Petrolina (PE), foi apreeendido. Nesta manh\u00e3 25 policiais participam da opera\u00e7\u00e3o em busca desses suspeitos. Quem perceber alguma movimenta\u00e7\u00e3o estranha na regi\u00e3o pode informar a pol\u00edcia atrav\u00e9s do telefone 190&#8221;, completa o tenente-coronel Paulo Paiva.<\/p>\n<p><strong>Acompanhe o SE Not\u00edcias no <a href=\"  https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Do G1 SE Uma ag\u00eancia do Banco do Estado de Sergipe (Banese) foi algo de um grupo de criminosos na madrugada desta ter\u00e7a-feira (12) em Malhador. Segundo uma vizinha da institui\u00e7\u00e3o financeira, foram tr\u00eas explos\u00f5es seguidas durante a madrugada, a mais forte foi sentida na parte mais interna da casa dela. \u201cDava para ouvir eles [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":79519,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[310,7],"tags":[],"class_list":{"0":"post-79518","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques-da-semana","8":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/79518"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=79518"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/79518\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/79519"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=79518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=79518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=79518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}