{"id":79045,"date":"2015-04-28T14:28:47","date_gmt":"2015-04-28T17:28:47","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=79045"},"modified":"2015-04-28T14:28:47","modified_gmt":"2015-04-28T17:28:47","slug":"guarda-municipal-de-aracaju-recebera-denuncias-atraves-do-whatsapp","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/guarda-municipal-de-aracaju-recebera-denuncias-atraves-do-whatsapp\/","title":{"rendered":"Guarda Municipal de Aracaju receber\u00e1 den\u00fancias atrav\u00e9s do WhatsApp"},"content":{"rendered":"<div id=\"attachment_79046\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/284201571350.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-79046\" class=\"size-medium wp-image-79046\" alt=\"Foto: Divulga\u00e7\u00e3o \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/284201571350-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/284201571350-300x199.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/284201571350-342x227.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/284201571350.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-79046\" class=\"wp-caption-text\">Foto: Divulga\u00e7\u00e3o<\/p><\/div>\n<p style=\"text-align: justify;\">Servir como mais um canal de comunica\u00e7\u00e3o e intera\u00e7\u00e3o entre a popula\u00e7\u00e3o aracajuana e a Guarda Municipal de Aracaju (GMA). Essa foi a raz\u00e3o que motivou a cria\u00e7\u00e3o do disque den\u00fancia atrav\u00e9s do whatsApp. &#8220;Ap\u00f3s reuni\u00f5es com nosso corpo de assessores, e atendendo um apelo antigo da coordena\u00e7\u00e3o da inspetoria de comunica\u00e7\u00e3o e v\u00eddeo monitoramento, entendemos que se fazia necess\u00e1rio criar outro meio de comunica\u00e7\u00e3o entre a institui\u00e7\u00e3o e a comunidade aracajuana. Dessa forma, diante da din\u00e2mica e da velocidade atual das informa\u00e7\u00f5es decidimos criar uma conta no whatsApp com o prop\u00f3sito de facilitar as den\u00fancias e o contato da comunidade com a GMA&#8221;, afirma Jonatas Souza, subcomandante da Guarda Municipal de Aracaju.<\/p>\n<p style=\"text-align: justify;\">O WhatsApp da Guarda Municipal de Aracaju funcionar\u00e1 como um complemento ao disque den\u00fancia 153 e receber\u00e1 al\u00e9m de mensagens de texto, imagens, v\u00eddeos e mensagens de \u00e1udio sobre den\u00fancias de crimes nos espa\u00e7os p\u00fablicos municipais como pra\u00e7as, mercados, unidades de sa\u00fade, escolas municipais, terminais de integra\u00e7\u00e3o e \u00f4nibus do transporte p\u00fablico. De acordo com o coordenador da inspetoria de comunica\u00e7\u00e3o e v\u00eddeo monitoramento, Odmar Arcanjo, essa nova ferramenta vai minimizar o tempo de resposta por parte da GMA.<\/p>\n<p style=\"text-align: justify;\">&#8220;Acreditamos que esse novo canal de comunica\u00e7\u00e3o vai otimizar a atua\u00e7\u00e3o da Guarda Municipal de Aracaju, j\u00e1 que vai desburocratizar esse contato no momento em as pessoas est\u00e3o necessitando de uma a\u00e7\u00e3o r\u00e1pida por parte da GMA. Solicitamos \u00e0 popula\u00e7\u00e3o que ao fazer as den\u00fancias procurem ser minuciosos quanto aos detalhes, a exemplo do local onde o crime est\u00e1 sendo cometido, caracter\u00edsticas dos suspeitos como cor e tipo das roupas e qualquer outro detalhe que julgue necess\u00e1rio. Essas informa\u00e7\u00f5es s\u00e3o essenciais para o sucesso de nossas a\u00e7\u00f5es&#8221;, declara Odmar.<\/p>\n<p style=\"text-align: justify;\">O n\u00famero da conta do WhatsApp da Guarda Municipal de Aracaju \u00e9 (79) 8869-4575 e j\u00e1 est\u00e1 dispon\u00edvel . Esse n\u00famero n\u00e3o aceitar\u00e1 liga\u00e7\u00f5es e servir\u00e1 exclusivamente para den\u00fancias atrav\u00e9s do WhatsApp. Den\u00fancias atrav\u00e9s de liga\u00e7\u00f5es telef\u00f4nicas continuam sendo feitas atrav\u00e9s do telefone 153.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: Ag\u00eancia Aracaju<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Servir como mais um canal de comunica\u00e7\u00e3o e intera\u00e7\u00e3o entre a popula\u00e7\u00e3o aracajuana e a Guarda Municipal de Aracaju (GMA). Essa foi a raz\u00e3o que motivou a cria\u00e7\u00e3o do disque den\u00fancia atrav\u00e9s do whatsApp. &#8220;Ap\u00f3s reuni\u00f5es com nosso corpo de assessores, e atendendo um apelo antigo da coordena\u00e7\u00e3o da inspetoria de comunica\u00e7\u00e3o e v\u00eddeo monitoramento, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":79046,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-79045","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/79045"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=79045"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/79045\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/79046"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=79045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=79045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=79045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}