{"id":79038,"date":"2015-04-28T14:21:00","date_gmt":"2015-04-28T17:21:00","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=79038"},"modified":"2015-04-28T14:22:40","modified_gmt":"2015-04-28T17:22:40","slug":"morre-aos-82-anos-o-artista-antonio-abujamra","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/morre-aos-82-anos-o-artista-antonio-abujamra\/","title":{"rendered":"Morre, aos 82 anos, o artista Ant\u00f4nio Abujamra"},"content":{"rendered":"<div id=\"attachment_79042\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/17369714-1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-79042\" class=\"size-medium wp-image-79042\" alt=\"Ant\u00f4nio Abujamra apresentava o programa &quot;Provoca\u00e7\u00f5es&quot; h\u00e1 14 anos \/ Reprodu\u00e7\u00e3o\/TV Cultura \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/17369714-1-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/17369714-1-300x199.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/17369714-1-342x227.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/17369714-1.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-79042\" class=\"wp-caption-text\">Ant\u00f4nio Abujamra apresentava o programa &#8220;Provoca\u00e7\u00f5es&#8221; h\u00e1 14 anos \/ Reprodu\u00e7\u00e3o\/TV Cultura<\/p><\/div>\n<p style=\"text-align: justify;\">Morreu, na manh\u00e3 desta ter\u00e7a-feira (28), aos 82 anos, Ant\u00f4nio Abujamra. O corpo do ator, diretor de teatro e apresentador foi encontrado pelo filho na casa em que o artista morava, em S\u00e3o Paulo. Ainda n\u00e3o h\u00e1 informa\u00e7\u00f5es sobre a causa da morte.<\/p>\n<p style=\"text-align: justify;\">Desde 2000, Abujamra estava \u00e0 frente do programa \u201cProvoca\u00e7\u00f5es\u201d, da TV Cultura. Veja abaixo a \u00faltima entrevista do apresentador, com o humorista Eduardo Sterblitch, exibida na \u00faltima ter\u00e7a-feira (21).<\/p>\n<p style=\"text-align: justify;\">Abujamra era conhecido por sua irrever\u00eancia, suas encena\u00e7\u00f5es e por seu humor cr\u00edtico em rela\u00e7\u00e3o aos tabus sociais. Ele tamb\u00e9m foi um dos principais diretores da antiga TV Tupi.<\/p>\n<p style=\"text-align: justify;\">Sua \u00faltima interpreta\u00e7\u00e3o em novelas ocorreu em 2011, em \u201cCora\u00e7\u00f5es Feridos\u201d, do SBT, e no cinema foi em 2012, em \u201cBrichos 2 \u2013 A Floresta \u00e9 Nossa\u201d.<\/p>\n<p style=\"text-align: justify;\">Seu primeiro trabalho na TV foi em 1968, como diretor de \u201cO Estranho Mundo de Z\u00e9 do Caix\u00e3o\u201d, na Tupi.<\/p>\n<p style=\"text-align: justify;\">Abujamra deixa tr\u00eas filhos &#8211; Alexandre, o m\u00fasico Andr\u00e9 e a atriz Clarisse &#8211; e dois netos.<\/p>\n<p style=\"text-align: justify;\"><strong>Biografia<\/strong> &#8211; Ant\u00f4nio Abujamra nasceu em 15 de setembro de 1932, na cidade de Ourinhos, no interior de S\u00e3o Paulo. Atuou em mais de 14 novelas e 19 filmes de cinema. Al\u00e9m disso, dirigiu diversos programas de TV e pe\u00e7as de teatro.<\/p>\n<p style=\"text-align: justify;\">Foi premiado v\u00e1rias vezes durante os seus mais de 50 anos de carreira, recebendo o primeiro reconhecimento, o Pr\u00eamio Juscelino Kubitschek de Oliveira, pela dire\u00e7\u00e3o de \u201cA Cantora Careca\u201d, em 1959, logo no in\u00edcio de seus trabalhos.<\/p>\n<p style=\"text-align: justify;\">Ap\u00f3s, ganhou os pr\u00eamios de melhor ator na pe\u00e7a teatral \u201cO Contrabaixo\u201d, de Patrick Suskind (1987\/1995) e o Kikito, no Festival de Gramado, como melhor ator no filme \u201cFesta\u201d (1989). Abujamra tamb\u00e9m foi premiado com o Trof\u00e9u APCA, pela atua\u00e7\u00e3o na novela \u201cQue Rei Sou Eu?\u201d (1989) e ganhou o Lifetime Achievement, como diretor, no XI Festival Internacional de Teatro Hisp\u00e2nico, em Miami (1998).<\/p>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es de D\u00e9bora La\u00eds e Marco Tucci, do Di\u00e1rio de SP<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Morreu, na manh\u00e3 desta ter\u00e7a-feira (28), aos 82 anos, Ant\u00f4nio Abujamra. O corpo do ator, diretor de teatro e apresentador foi encontrado pelo filho na casa em que o artista morava, em S\u00e3o Paulo. Ainda n\u00e3o h\u00e1 informa\u00e7\u00f5es sobre a causa da morte. Desde 2000, Abujamra estava \u00e0 frente do programa \u201cProvoca\u00e7\u00f5es\u201d, da TV Cultura. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":79042,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":{"0":"post-79038","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-famosos"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/79038"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=79038"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/79038\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/79042"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=79038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=79038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=79038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}