{"id":78798,"date":"2015-04-22T15:03:35","date_gmt":"2015-04-22T18:03:35","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=78798"},"modified":"2015-04-22T15:03:35","modified_gmt":"2015-04-22T18:03:35","slug":"aracaju-recebe-mutiroes-fumace-e-outros-cuidados-contra-a-dengue","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/aracaju-recebe-mutiroes-fumace-e-outros-cuidados-contra-a-dengue\/","title":{"rendered":"Aracaju recebe mutir\u00f5es, fumac\u00ea e outros cuidados contra a dengue"},"content":{"rendered":"<div id=\"attachment_78799\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/24102012112053.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-78799\" class=\"size-medium wp-image-78799\" alt=\"Foto: Divulga\u00e7\u00e3o \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/24102012112053-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/24102012112053-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/24102012112053-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/24102012112053-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/24102012112053-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/24102012112053-269x201.jpg 269w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/24102012112053.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-78799\" class=\"wp-caption-text\">Foto: Divulga\u00e7\u00e3o<\/p><\/div>\n<p style=\"text-align: justify;\">Combater e eliminar focos do mosquito transmissor da dengue e da febre chikungunya \u00e9 uma prioridade para Sa\u00fade de Aracaju, que promove a\u00e7\u00f5es constantes em diversos pontos da cidade. No \u00faltimo s\u00e1bado (17), agentes de Endemias realizaram mutir\u00e3o no bairro Santos Dumont. Com 20 agentes mobilizados, mais 430 im\u00f3veis foram visitados, concluindo o ciclo de trabalho e garantindo que o \u00edndice de infesta\u00e7\u00e3o da dengue permane\u00e7a baixo. No pr\u00f3ximo s\u00e1bado (25), um outro mutir\u00e3o vai acontecer no bairro 18 do Forte.<\/p>\n<p style=\"text-align: justify;\">Segundo a coordenadora do Programa de Controle da Dengue de Aracaju, Ta\u00edse Cavalcante, as a\u00e7\u00f5es de cuidados contra \u00e0 dengue n\u00e3o param de acontecer. Hoje dia 22, e, nos dias 23, 24 , 27 e 28, a Sa\u00fade tamb\u00e9m refor\u00e7a o combate \u00e0 dengue na Zona de Expans\u00e3o, atuando nos povoados Robalo, Areia Branca e bairros 17 de Mar\u00e7o e Santa Maria. Al\u00e9m do trabalho dos agentes de Endemias, o carro fumac\u00ea aplica inseticidas contra o mosquito. De 22 \u00e0 24, o ve\u00edculo segue atuando nos bairros 17 de Mar\u00e7o e Pereira Lobo. &#8220;Todos os trabalhos visam eliminar o m\u00e1ximo poss\u00edvel a quantidade de mosquitos e de focos com a colabora\u00e7\u00e3o dos moradores&#8221;, afirma Ta\u00edse Cavalcante.<\/p>\n<p style=\"text-align: justify;\">&#8220;Al\u00e9m da borrifa\u00e7\u00e3o e inseticidas e das visitas as casas feitas pelos agentes, o que mais visamos com \u00e9 conscientizar a popula\u00e7\u00e3o quanto a import\u00e2ncia dos h\u00e1bitos preventivos. A preven\u00e7\u00e3o \u00e9 nosso maior aliado. Na luta contra a dengue todos devem diariamente estar fazendo sua parte, seja arrumando os quintais, n\u00e3o deixando latas, garrafas e pneus expostos, recipientes com \u00e1gua parada, seja cobrindo e limpando os reservat\u00f3rios de \u00e1gua e lavanderias para que o mosquito n\u00e3o deposite ovos&#8221;, explica a coordenadora.<\/p>\n<p style=\"text-align: justify;\">A supervisora do combate \u00e0 dengue na Zona de Expans\u00e3o, Daniela de Oliveira fala que os trabalhos naquela regi\u00e3o t\u00eam sido proveitosos. Os agentes j\u00e1 conclu\u00edram os im\u00f3veis na Aruana e agora seguem em \u00e1reas como povoados Robalo, Areia Branca e bairros 17 de Mar\u00e7o e Santa Maria.<\/p>\n<p style=\"text-align: justify;\">&#8220;Na Aruana fizemos a procura por focos a partir de den\u00fancias e tamb\u00e9m nas media\u00e7\u00f5es onde havia pessoas doentes com suspeita de dengue. Agora estamos nas demais \u00e1reas e no Robalo ,por exemplo, temos tido uma preocupa\u00e7\u00e3o a mais com a quest\u00e3o de casas que se encontra fechadas no dia em que as equipes est\u00e3o trabalhamos. Pedimos para os moradores se organizarem e permitirem a entrada dos agentes&#8221;, explica Daniela de Oliveira.<\/p>\n<p style=\"text-align: justify;\">Em casos de suspeita de foco de dengue em casas fechadas ou outras localidades, a popula\u00e7\u00e3o pode ligar para a Vigil\u00e2ncia Epidemiol\u00f3gica: 3179-1000 ou 3179-1067.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0Fonte: Secretaria Municipal de Sa\u00fade<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Combater e eliminar focos do mosquito transmissor da dengue e da febre chikungunya \u00e9 uma prioridade para Sa\u00fade de Aracaju, que promove a\u00e7\u00f5es constantes em diversos pontos da cidade. No \u00faltimo s\u00e1bado (17), agentes de Endemias realizaram mutir\u00e3o no bairro Santos Dumont. Com 20 agentes mobilizados, mais 430 im\u00f3veis foram visitados, concluindo o ciclo de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":78799,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":{"0":"post-78798","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/78798"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=78798"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/78798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/78799"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=78798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=78798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=78798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}