{"id":78316,"date":"2015-04-10T11:57:53","date_gmt":"2015-04-10T14:57:53","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=78316"},"modified":"2015-04-11T09:05:37","modified_gmt":"2015-04-11T12:05:37","slug":"apos-um-ano-jovem-e-morto-no-mesmo-local-que-o-pai","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/apos-um-ano-jovem-e-morto-no-mesmo-local-que-o-pai\/","title":{"rendered":"Ap\u00f3s um ano, jovem \u00e9 morto no mesmo local que o pai"},"content":{"rendered":"<div id=\"attachment_78318\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-78318\" class=\"size-medium wp-image-78318\" alt=\"Rapaz de 21 anos foi v\u00edtima de latroc\u00ednio em Tobias Barreto. (Foto: JC Online)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/1-300x291.jpg\" width=\"300\" height=\"291\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/1-300x291.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/1-50x50.jpg 50w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/1-342x332.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/04\/1.jpg 346w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-78318\" class=\"wp-caption-text\">Rapaz de 21 anos foi v\u00edtima de latroc\u00ednio em Tobias Barreto. (Foto: JC Online)<\/p><\/div>\n<p style=\"text-align: justify;\">Um ano depois o jovem Renato Nascimento, de 21 anos, foi morto a tiros no mesmo local que o pai foi assassinado. O rapaz foi atingido por tiros durante um assalto na noite desta quinta-feira (9), em frente \u00e0 sua casa, na localidade conhecida como \u201cRua dos Mission\u00e1rios\u201d, em Tobias Barreto.<\/p>\n<p style=\"text-align: justify;\">Ontem, dois homens em uma moto abordaram o rapaz e anunciaram o assalto, sendo que, logo em seguida, o indiv\u00edduo que seguia na garupa efetuou os disparos contra Renato. A v\u00edtima ainda foi socorrida e encaminhada para o hospital local, mas n\u00e3o resistiu.<\/p>\n<p>A dupla respons\u00e1vel pelo crime fugiu em uma moto Honda, modelo Bros.<\/p>\n<p style=\"text-align: justify;\">No ano passado, o pai de Renato tamb\u00e9m foi morto v\u00edtima de latroc\u00ednio em frente \u00e0 mesma casa.<\/p>\n<p style=\"text-align: justify;\">Renato era pai de dois filhos e a mulher estava gr\u00e1vida.\u00a0<em>(Informa\u00e7\u00f5es do JC Online)<\/em><\/p>\n<p><strong>Acompanhe o SE Not\u00edcias no <a href=\"  https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e no <a href=\"  https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um ano depois o jovem Renato Nascimento, de 21 anos, foi morto a tiros no mesmo local que o pai foi assassinado. O rapaz foi atingido por tiros durante um assalto na noite desta quinta-feira (9), em frente \u00e0 sua casa, na localidade conhecida como \u201cRua dos Mission\u00e1rios\u201d, em Tobias Barreto. Ontem, dois homens em [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":78318,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-78316","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/78316"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=78316"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/78316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/78318"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=78316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=78316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=78316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}