{"id":78307,"date":"2015-04-10T09:20:05","date_gmt":"2015-04-10T12:20:05","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=78307"},"modified":"2015-04-10T09:20:05","modified_gmt":"2015-04-10T12:20:05","slug":"camara-aprova-mp-que-aumenta-limite-de-descontos-na-folha-de-pagamentos","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/camara-aprova-mp-que-aumenta-limite-de-descontos-na-folha-de-pagamentos\/","title":{"rendered":"C\u00e2mara aprova MP que aumenta limite de descontos na folha de pagamentos"},"content":{"rendered":"<p style=\"text-align: justify;\">O plen\u00e1rio da C\u00e2mara aprovou hoje (9) a Medida Provis\u00f3ria 661, que aumenta o limite de descontos autorizados pelo trabalhador na folha de pagamentos para incluir despesas com cart\u00e3o de cr\u00e9dito. Pelas regras atuais, os trabalhadores podem autorizar o desconto de empr\u00e9stimos, financiamentos ou arrendamento mercantil at\u00e9 o limite de 30%. Com as novas regras, ser\u00e3o acrescidos mais 10% apenas para despesas com cart\u00e3o de cr\u00e9dito. A MP segue para analise do Senado.<\/p>\n<div id=\"attachment_53368\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/10\/Plen\u00e1rio-da-C\u00e2mara.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-53368\" class=\"size-full wp-image-53368\" alt=\"C\u00e2mara \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/10\/Plen\u00e1rio-da-C\u00e2mara.jpg\" width=\"590\" height=\"211\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/10\/Plen\u00e1rio-da-C\u00e2mara.jpg 590w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/10\/Plen\u00e1rio-da-C\u00e2mara-300x107.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/10\/Plen\u00e1rio-da-C\u00e2mara-342x122.jpg 342w\" sizes=\"(max-width: 590px) 100vw, 590px\" \/><\/a><p id=\"caption-attachment-53368\" class=\"wp-caption-text\">C\u00e2mara<\/p><\/div>\n<p style=\"text-align: justify;\">Os deputados tamb\u00e9m aprovaram na MP dispositivo que autoriza o Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES) a financiar contratos relativos \u00e0 compra ou leasing de caminh\u00f5es com a linha de cr\u00e9dito Pr\u00f3-Caminhoneiro, do BNDES. Os caminhoneiros aut\u00f4nomos, as empresas de transporte de carga e as arrendadoras com receita bruta at\u00e9 R$ 2,4 milh\u00f5es poder\u00e3o refinanciar as 12 primeiras presta\u00e7\u00f5es a vencer ap\u00f3s a entrada do pedido de financiamento.<\/p>\n<p style=\"text-align: justify;\">O texto da MP aprovada tamb\u00e9m concede cr\u00e9dito de R$ 30 bilh\u00f5es ao BNDES, em condi\u00e7\u00f5es a serem definidas pelo ministro da Fazenda. A cobertura das opera\u00e7\u00f5es se dar\u00e1 mediante a coloca\u00e7\u00e3o direta de t\u00edtulos da d\u00edvida p\u00fablica mobili\u00e1ria federal, em favor do BNDES, cujas caracter\u00edsticas tamb\u00e9m ser\u00e3o definidas pelo ministro.<\/p>\n<p style=\"text-align: justify;\">Nas vota\u00e7\u00f5es das emendas e dos destaques, os deputados aprovaram dispositivo para proibir o BNDES de se recusar a fornecer informa\u00e7\u00f5es sobre opera\u00e7\u00f5es de empr\u00e9stimo com base em sigilo contratual, incluindo empr\u00e9stimos para obras no exterior. A emenda aprovada direciona um m\u00ednimo de 2,5% dos recursos emprestados pelo BNDES ao custeio de atividades em extens\u00e3o rural a taxas subsidiadas.<\/p>\n<p style=\"text-align: justify;\">\n<strong>Acompanhe o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e no <a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook.<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Informa\u00e7\u00f5es do Portal Ag\u00eancia Brasil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O plen\u00e1rio da C\u00e2mara aprovou hoje (9) a Medida Provis\u00f3ria 661, que aumenta o limite de descontos autorizados pelo trabalhador na folha de pagamentos para incluir despesas com cart\u00e3o de cr\u00e9dito. Pelas regras atuais, os trabalhadores podem autorizar o desconto de empr\u00e9stimos, financiamentos ou arrendamento mercantil at\u00e9 o limite de 30%. Com as novas regras, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":45561,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-78307","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/78307"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=78307"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/78307\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/45561"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=78307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=78307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=78307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}