{"id":78296,"date":"2015-04-09T18:31:48","date_gmt":"2015-04-09T21:31:48","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=78296"},"modified":"2015-04-09T19:33:50","modified_gmt":"2015-04-09T22:33:50","slug":"deputado-critica-acao-do-coren-no-hospital-de-aquidaba","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/deputado-critica-acao-do-coren-no-hospital-de-aquidaba\/","title":{"rendered":"Deputado critica a\u00e7\u00e3o do Coren no hospital de Aquidab\u00e3"},"content":{"rendered":"<div id=\"attachment_28325\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/03\/Francisco-Gualberto.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-28325\" class=\"size-medium wp-image-28325\" alt=\"Gualberto critica a\u00e7\u00e3o do Coren no hospital de Aquidab\u00e3. (Foto: Cesar Oliveira)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/03\/Francisco-Gualberto-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/03\/Francisco-Gualberto-300x199.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/03\/Francisco-Gualberto-342x227.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2012\/03\/Francisco-Gualberto.jpg 448w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-28325\" class=\"wp-caption-text\">Gualberto critica a\u00e7\u00e3o do Coren no hospital de Aquidab\u00e3. (Foto: Cesar Oliveira)<\/p><\/div>\n<p style=\"text-align: justify;\">A interven\u00e7\u00e3o \u00e9tica feita pelo Conselho Regional de Enfermagem de Sergipe (Coren) na Funda\u00e7\u00e3o Hospitalar Santa Cec\u00edlia, localizada no munic\u00edpio de Aquidab\u00e3, foi alvo de protestos no plen\u00e1rio da Assembleia Legislativa nesta quinta-feira, 9. O ato do Coren que aconteceu na segunda-feira, 6, foi classificado pelo deputado estadual Francisco Gualberto (PT), l\u00edder do governo, como \u201cum desservi\u00e7o \u00e0 popula\u00e7\u00e3o\u201d.<br \/>\n\u201cFizeram um espet\u00e1culo na cidade. Convidaram toda a imprensa e levaram as principais redes de televis\u00e3o para a cidade, al\u00e9m da Pol\u00edcia Federal para garantir a entrada deles no hospital. E isso tudo num hospital onde todos os dias entram pessoas em cadeiras de rodas, com muletas e em macas. As portas est\u00e3o sempre abertas. Mas o Coren precisava levar a PF para entrara, como se fosse uma miss\u00e3o imposs\u00edvel\u201d, criticou Gualberto.<\/p>\n<p>Indignado com a atitude do conselho, que constrangeu os diretores da entidade que funciona como Hospital e Maternidade, Francisco Gualberto partiu para o ataque. \u201cA quem o Coren quis servir com essa atitude? Com certeza n\u00e3o foi para defender os enfermeiros. Algu\u00e9m est\u00e1 por tr\u00e1s disso. E n\u00f3s vamos descobrir e denunciar\u201d, frisou o deputado. Para ele, o Coren \u00e9 um \u00f3rg\u00e3o que s\u00f3 faz arrecadar mensalidades, n\u00e3o oferecendo nenhum benef\u00edcio \u00e0 categoria de enfermeiros.<\/p>\n<p style=\"text-align: justify;\">Com mais de 20 anos de presta\u00e7\u00e3o de servi\u00e7os em Aquidab\u00e3 e regi\u00e3o, o hospital Santa Cec\u00edlia atende em m\u00e9dia 2,5 mil pessoas por m\u00eas. Para isso, conta apenas com R$ 130 mil repassados mensalmente pelo Estado atrav\u00e9s do SUS. \u00c9 uma entidade filantr\u00f3pica mantida pelo m\u00e9dico Jo\u00e3o Feitoza e familiares. Mesmo assim, o Corem exige que o hospital contrate mais oito enfermeiros \u2013 com sal\u00e1rios de R$ 4 mil\/cada \u2013 e 17 t\u00e9cnicos de enfermagem. \u201cS\u00f3 faltou eles chegarem l\u00e1 com uma m\u00e1quina de fazer dinheiro e entregar aos diretores\u201d, ironizou Gualberto.<\/p>\n<p style=\"text-align: justify;\">Para o deputado, a inten\u00e7\u00e3o do \u00f3rg\u00e3o \u00e9 fechar definitivamente o hospital. \u201c\u00c9 a pol\u00edtica rasteira. E eu repudio isso, pois \u00e9 abuso de poder, coa\u00e7\u00e3o e atendimento de interesse pr\u00f3prio. Al\u00e9m da falta de bom senso. Por isso, merece o repudio de todo o povo sergipano\u201d, argumentou Gualberto, anunciando que j\u00e1 procurou a Secretaria de Estado da Sa\u00fade para tratar sobre o assunto.<\/p>\n<p style=\"text-align: justify;\">Na tribuna, o deputado lembrou ainda que o Coren de Sergipe j\u00e1 esteve envolvido em esc\u00e2ndalos com repercuss\u00e3o nacional, envolvendo o desvio de recursos. \u201cAdmitimos que h\u00e1 defici\u00eancias no hospital, como em v\u00e1rios outros. E o Coren poderia orientar no sentido de ajudar a resolver. Mas n\u00e3o foi isso que fizeram. Chegaram l\u00e1 com uma lista impositiva de contrata\u00e7\u00f5es. Portanto, fica evidente que foram chantagear\u201d, afirma Francisco Gualberto.<\/p>\n<p style=\"text-align: justify;\">O deputado ainda pediu \u00e0 Comiss\u00e3o de Sa\u00fade da Assembleia, presidida pela deputada Silvia Fontes (PDT), que constitua um grupo de parlamentares para fazer uma visita ao hospital, assim como ao promotor p\u00fabico e ao juiz de Aquidab\u00e3 para discutir o fato. De pronto, Silvia acatou a sugest\u00e3o. Outros deputados, como o m\u00e9dico Gilson Andrade, tamb\u00e9m foram solid\u00e1rios \u00e0 queixa de Gualberto. \u201c\u00c9 crime usar a dor dos outros, de uma popula\u00e7\u00e3o inteira, para buscar arrecada\u00e7\u00e3o para o Coren\u201d, disse o petista.<\/p>\n<p><strong>Acompanhe o SE Not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.facebook.com\/PortalSENoticias?ref=bookmarks\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\">Assessoria de Imprensa \u2013 Gilson Sousa \u2013 DRT \u2013 660\/SE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A interven\u00e7\u00e3o \u00e9tica feita pelo Conselho Regional de Enfermagem de Sergipe (Coren) na Funda\u00e7\u00e3o Hospitalar Santa Cec\u00edlia, localizada no munic\u00edpio de Aquidab\u00e3, foi alvo de protestos no plen\u00e1rio da Assembleia Legislativa nesta quinta-feira, 9. O ato do Coren que aconteceu na segunda-feira, 6, foi classificado pelo deputado estadual Francisco Gualberto (PT), l\u00edder do governo, como [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":28325,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-78296","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/78296"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=78296"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/78296\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/28325"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=78296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=78296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=78296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}