{"id":76847,"date":"2015-03-05T08:26:43","date_gmt":"2015-03-05T11:26:43","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=76847"},"modified":"2015-03-06T09:36:02","modified_gmt":"2015-03-06T12:36:02","slug":"deputado-pede-responsabilidade-quando-falar-sobre-seguranca-publica","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/deputado-pede-responsabilidade-quando-falar-sobre-seguranca-publica\/","title":{"rendered":"Deputado pede responsabilidade quando falar sobre Seguran\u00e7a P\u00fablica"},"content":{"rendered":"<div id=\"attachment_76849\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/03\/Robson_Viana.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-76849\" class=\"size-medium wp-image-76849\" alt=\"Robson Viana (PMDB-SE). (Foto: Ascom)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/03\/Robson_Viana-300x198.jpg\" width=\"300\" height=\"198\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/03\/Robson_Viana-300x198.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/03\/Robson_Viana-342x226.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/03\/Robson_Viana.jpg 594w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-76849\" class=\"wp-caption-text\">Robson Viana (PMDB-SE). (Foto: Ascom)<\/p><\/div>\n<p style=\"text-align: justify;\">\u201cA gente n\u00e3o pode criar aqui um palanque eleitoral em rela\u00e7\u00e3o \u00e0 Seguran\u00e7a P\u00fablica do nosso Estado. \u00c9 preciso que a gente fa\u00e7a um pacto pela seguran\u00e7a e sa\u00fade dos sergipanos. Se a gente for discutir seguran\u00e7a p\u00fablica nesse caminho, quem vai sofrer \u00e9 o povo de Sergipe. Tenho certeza que nenhum dos deputados desta casa quer que piore. Est\u00e1 com dificuldade? Sim. Vamos procurar um mecanismo? Vamos. Quais s\u00e3o as sugest\u00f5es? Esse \u00e9 o nosso papel aqui como legisladores nesta casa, independente de sigla partid\u00e1ria\u201d.\u00a0 Foi com essa afirma\u00e7\u00e3o que o deputado estadual, Robson Viana (PMDB), usou a tribuna do grande expediente da Assembleia Legislativa em que contestou as afirma\u00e7\u00f5es do colega deputado capit\u00e3o Samuel a uma reportagem publicada semana passada em um jornal de grande circula\u00e7\u00e3o, cujo, manchete foi \u201cDeputado den\u00fancia boicote a Mendon\u00e7a na seguran\u00e7a e acusa Iunes\u201d.<\/p>\n<p style=\"text-align: justify;\">Durante o pronunciamento Robson Viana pede clareza e responsabilidade, disse ainda que n\u00e3o \u00e9 necess\u00e1rio criar dificuldades com certos tipos de reportagem porque dificulta o conv\u00edvio da seguran\u00e7a. \u201cVenho acompanhando e sei que o deputado Capit\u00e3o Samuel, aqui nesta casa, foi um dos deputados que mais discutiu seguran\u00e7a p\u00fablica. Mas, com muita tranquilidade, digo que devemos ter clareza e responsabilidade no que a gente diz aqui na tribuna ou em qualquer reportagem\u201d, afirmou o parlamentar. Acrescentou ainda que a pedido do deputado Valmir Monteiro, na pr\u00f3xima segunda-feira, dia 09, o secret\u00e1rio de Estado da Seguran\u00e7a P\u00fablica, Mendon\u00e7a Prado, estar\u00e1 na Assembleia Legislativa para esclarecer as dificuldades da SSP.<\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias pelo\u00a0<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><em><b><span style=\"color: #444444;\">Kelly Monique Oliveira<br \/>\n<\/span><\/b><b><span style=\"color: #444444;\">Assessoria de Comunica\u00e7\u00e3o<\/span><\/b><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cA gente n\u00e3o pode criar aqui um palanque eleitoral em rela\u00e7\u00e3o \u00e0 Seguran\u00e7a P\u00fablica do nosso Estado. \u00c9 preciso que a gente fa\u00e7a um pacto pela seguran\u00e7a e sa\u00fade dos sergipanos. Se a gente for discutir seguran\u00e7a p\u00fablica nesse caminho, quem vai sofrer \u00e9 o povo de Sergipe. Tenho certeza que nenhum dos deputados desta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":76849,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,6],"tags":[],"class_list":{"0":"post-76847","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques","8":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/76847"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=76847"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/76847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/76849"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=76847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=76847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=76847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}