{"id":76727,"date":"2015-03-02T19:52:49","date_gmt":"2015-03-02T22:52:49","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=76727"},"modified":"2015-03-02T20:02:16","modified_gmt":"2015-03-02T23:02:16","slug":"sindijor-se-repudia-demissoes-no-jornal-e-tv-cidade","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/sindijor-se-repudia-demissoes-no-jornal-e-tv-cidade\/","title":{"rendered":"SINDIJOR-SE repudia demiss\u00f5es no Jornal e TV Cidade"},"content":{"rendered":"<p align=\"center\"><b>\u00a0<\/b><\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_56686\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/grande-sindijor_paulo_200913.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-56686\" class=\"size-medium wp-image-56686\" alt=\"Paulo Sousa, presidente do SINDIJOR. (Foto: Divulga\u00e7\u00e3o)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/grande-sindijor_paulo_200913-300x266.jpg\" width=\"300\" height=\"266\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/grande-sindijor_paulo_200913-300x266.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/grande-sindijor_paulo_200913-342x303.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/12\/grande-sindijor_paulo_200913.jpg 453w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-56686\" class=\"wp-caption-text\">Paulo Sousa, presidente do SINDIJOR. (Foto: Divulga\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">A Diretoria do Sindicato dos Jornalistas Profissionais do Estado de Sergipe (SINDIJOR-SE) vem a p\u00fablico manifestar solidariedade aos jornalistas demitidos, sem justa causa, pelo Jornal da Cidade e TV Cidade e ao mesmo tempo repudiar a a\u00e7\u00e3o dos dois ve\u00edculos, pois ela aterroriza o mercado de trabalho e prejudica n\u00e3o somente os profissionais atingidos, mas todos os jornalistas de Sergipe.<\/p>\n<p style=\"text-align: justify;\">Os profissionais demitidos pelos respectivos ve\u00edculos de comunica\u00e7\u00e3o, al\u00e9m de exercerem a profiss\u00e3o com \u00e9tica e responsabilidade social, foram os pilares de sustenta\u00e7\u00e3o do JC e da TV Cidade nos momentos de &#8220;crise&#8221; vivenciados pelas empresas e est\u00e3o pagando pelas desastrosas gest\u00f5es, principalmente na TV Cidade.<\/p>\n<p style=\"text-align: justify;\">O SINDIJOR-SE repudia de p\u00fablico as a\u00e7\u00f5es dos dois ve\u00edculos de imprensa em punir os profissionais, que ao longo da hist\u00f3ria das empresas, agiram com dec\u00eancia, n\u00e3o tendo em nenhum momento, contribu\u00eddo com os desmandos que levaram a esta situa\u00e7\u00e3o. Os jornalistas sempre foram os pilares da empresa e merecem respeito.<\/p>\n<p style=\"text-align: justify;\">Tal pr\u00e1tica de demiss\u00f5es e ass\u00e9dio para disseminar o medo e inibir as manifesta\u00e7\u00f5es leg\u00edtimas dos profissionais da imprensa n\u00e3o intimidar\u00e1 nossa disposi\u00e7\u00e3o de lutar por um Jornalismo qualificado, por dignidade e melhores sal\u00e1rios e condi\u00e7\u00f5es de trabalho.<\/p>\n<p style=\"text-align: justify;\">O Sindicato est\u00e1 acompanhando todas as demiss\u00f5es e, caso seja necess\u00e1rio, acionar\u00e1 a Justi\u00e7a para que os direitos dos jornalistas sejam respeitados, inclusive, os profissionais que s\u00e3o detentores de estabilidade sindical. O SINDIJOR se mant\u00e9m firme na defesa e amplia\u00e7\u00e3o dos direitos dos trabalhadores jornalistas.<\/p>\n<p style=\"text-align: justify;\">Sendo assim, conclamamos a categoria a somar for\u00e7as na defesa da nossa profiss\u00e3o com a devida valoriza\u00e7\u00e3o e respeito aos direitos trabalhistas, bem como do Jornalismo \u00e9tico, respons\u00e1vel, a servi\u00e7o da sociedade, e a resistir a toda forma de intimida\u00e7\u00e3o, explora\u00e7\u00e3o e opress\u00e3o.<\/p>\n<p><strong>\u00a0Acompanhe o SE Not\u00edcias pelo<a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\"> Twitter<\/a> e no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<p align=\"center\"><b>SINDIJOR &#8211; Sindicato dos Jornalistas Profissionais do Estado de Sergipe<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 &nbsp; A Diretoria do Sindicato dos Jornalistas Profissionais do Estado de Sergipe (SINDIJOR-SE) vem a p\u00fablico manifestar solidariedade aos jornalistas demitidos, sem justa causa, pelo Jornal da Cidade e TV Cidade e ao mesmo tempo repudiar a a\u00e7\u00e3o dos dois ve\u00edculos, pois ela aterroriza o mercado de trabalho e prejudica n\u00e3o somente os profissionais [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":49767,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[310],"tags":[],"class_list":{"0":"post-76727","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques-da-semana"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/76727"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=76727"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/76727\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/49767"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=76727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=76727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=76727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}