{"id":76583,"date":"2015-02-26T21:46:56","date_gmt":"2015-02-27T00:46:56","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=76583"},"modified":"2015-02-28T13:52:27","modified_gmt":"2015-02-28T16:52:27","slug":"eleito-em-colegiado-de-secretarios-mendonca-prado-cobra-imediata-mudanca-legislativa","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/eleito-em-colegiado-de-secretarios-mendonca-prado-cobra-imediata-mudanca-legislativa\/","title":{"rendered":"Eleito em colegiado de secret\u00e1rios, Mendon\u00e7a Prado cobra imediata mudan\u00e7a legislativa"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: tahoma, sans-serif;\">O secret\u00e1rio de Seguran\u00e7a P\u00fablica de Sergipe, Mendon\u00e7a Prado, foi eleito nesta quinta-feira (26) como segundo vice-presidente do Col\u00e9gio Nacional de Secret\u00e1rios de Seguran\u00e7a P\u00fablica (Consesp). A elei\u00e7\u00e3o foi realizada na abertura da 57\u00ba reuni\u00e3o do Colegiado. Mendon\u00e7a cobrou uma imediata mudan\u00e7a legislativa para reduzir a taxa de crimes, sobretudo no Nordeste.<\/span><\/p>\n<div id=\"attachment_76584\" style=\"width: 567px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/b3bb2c3a-7a51-a7bb.jpeg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-76584\" class=\"size-full wp-image-76584\" alt=\"Mendon\u00e7a Prado cobra imediata mudan\u00e7a legislativa. (Foto: Isaac Amorim)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/b3bb2c3a-7a51-a7bb.jpeg\" width=\"557\" height=\"380\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/b3bb2c3a-7a51-a7bb.jpeg 557w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/b3bb2c3a-7a51-a7bb-300x204.jpeg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/b3bb2c3a-7a51-a7bb-342x233.jpeg 342w\" sizes=\"(max-width: 557px) 100vw, 557px\" \/><\/a><p id=\"caption-attachment-76584\" class=\"wp-caption-text\">Mendon\u00e7a Prado cobra imediata mudan\u00e7a legislativa. (Foto: Isaac Amorim)<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-family: tahoma, sans-serif;\">A chapa na qual o secret\u00e1rio sergipano foi eleito \u00e9 encabe\u00e7ada pelo secret\u00e1rio de Seguran\u00e7a P\u00fablica de Minas Gerais, Bernardo Santana, eleito presidente do Col\u00e9gio Nacional de Secret\u00e1rios de Seguran\u00e7a P\u00fablica para o bi\u00eanio 2015\/2016. No encontro, o ministro da Justi\u00e7a, Jos\u00e9 Eduardo Cardoso foi apresentado aos novos secret\u00e1rios estaduais.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: tahoma, sans-serif;\">A chapa de Mendon\u00e7a Prado recebeu 14 votos de secret\u00e1rios de Seguran\u00e7a P\u00fablica. A outra chapa, liderada pelo secret\u00e1rio Jos\u00e9 Mariano Beltrame, do Rio de Janeiro, teve oito votos. A nova dire\u00e7\u00e3o do Consesp disse que pretende intensificar as atividades do colegiado. Um dos caminhos para isso \u00e9 o fortalecimento da rela\u00e7\u00e3o com o Congresso Nacional.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: tahoma, sans-serif;\">Segundo Mendon\u00e7a Prado, a ideia \u00e9 cobrar medidas efetivas para reduzir a taxa de criminalidade, sobretudo os homic\u00eddios. Para isso, \u00e9 necess\u00e1ria a articula\u00e7\u00e3o com o Governo Federal e medidas junto ao Congresso Nacional para a mudan\u00e7a da legisla\u00e7\u00e3o penal no Brasil. \u201c\u00c9 necess\u00e1rio um pacto nacional, baseado na integra\u00e7\u00e3o, medidas operacionais imediatas e na reflex\u00e3o legislativa e dos \u00f3rg\u00e3os de Justi\u00e7a para que o trabalho da pol\u00edcia gere resultados mais eficientes\u201d, explicou.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: tahoma, sans-serif;\">Os debates entre os integrantes do Consesp costumam ser realizados quatro vezes por ano. O encontro desta quinta-feira (26.02) foi o primeiro de 2015. Durante as reuni\u00f5es, os secret\u00e1rios apresentam as pol\u00edticas de seguran\u00e7a de seus estados e buscam alternativas conjuntas de combate \u00e0 viol\u00eancia e \u00e0 criminalidade.<\/span><\/p>\n<p><span style=\"font-family: tahoma, sans-serif;\">\u00a0<\/span><\/p>\n<p><b><span style=\"text-decoration: underline;\"><span style=\"font-family: tahoma, sans-serif;\">Sobre o Consesp<\/span><\/span><\/b><\/p>\n<p><span style=\"font-family: tahoma, sans-serif;\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: tahoma, sans-serif;\">O Col\u00e9gio Nacional de Secret\u00e1rios de Seguran\u00e7a P\u00fablica foi formado em abril de 2003, durante a realiza\u00e7\u00e3o do Encontro Nacional de Secret\u00e1rios de Seguran\u00e7a P\u00fablica. O Consesp oferece \u00e0s secretarias estaduais informa\u00e7\u00f5es que possam servir de base na formula\u00e7\u00e3o de diretrizes e metas em Seguran\u00e7a P\u00fablica e divulga a\u00e7\u00f5es de sucesso dos estados que possam ser aplicadas por outras unidades da federa\u00e7\u00e3o.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: tahoma, sans-serif;\">O Consesp \u00e9 um \u00f3rg\u00e3o colegiado com fun\u00e7\u00f5es planejadoras, executoras, consultivas, deliberativas e representativas. Tem por finalidade b\u00e1sica, o assessoramento especial aos Secret\u00e1rios Estaduais de Seguran\u00e7a P\u00fablica no acompanhamento e avalia\u00e7\u00e3o das a\u00e7\u00f5es de seguran\u00e7a p\u00fablica em todas as esferas governamentais.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias no <a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n<div><em><strong><span style=\"color: #3366ff;\">Vanessa Franco<\/span><\/strong><\/em><\/div>\n<div><em><span style=\"color: #3366ff;\">Assessora de Imprensa\u00a0<\/span><\/em><\/div>\n<div><em><span style=\"color: #3366ff;\">Mendon\u00e7a Prado &#8211; Secret\u00e1rio de Seguran\u00e7a P\u00fablica<\/span><\/em><\/div>\n<p><span style=\"font-family: tahoma, sans-serif;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: tahoma, sans-serif;\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O secret\u00e1rio de Seguran\u00e7a P\u00fablica de Sergipe, Mendon\u00e7a Prado, foi eleito nesta quinta-feira (26) como segundo vice-presidente do Col\u00e9gio Nacional de Secret\u00e1rios de Seguran\u00e7a P\u00fablica (Consesp). A elei\u00e7\u00e3o foi realizada na abertura da 57\u00ba reuni\u00e3o do Colegiado. Mendon\u00e7a cobrou uma imediata mudan\u00e7a legislativa para reduzir a taxa de crimes, sobretudo no Nordeste. A chapa na [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":76584,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-76583","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/76583"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=76583"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/76583\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/76584"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=76583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=76583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=76583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}