{"id":76570,"date":"2015-02-26T18:14:27","date_gmt":"2015-02-26T21:14:27","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=76570"},"modified":"2015-02-26T18:14:27","modified_gmt":"2015-02-26T21:14:27","slug":"carteira-de-motorista-ficara-mais-cara-a-partir-de-marco-em-sergipe","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/carteira-de-motorista-ficara-mais-cara-a-partir-de-marco-em-sergipe\/","title":{"rendered":"Carteira de motorista ficar\u00e1 mais cara a partir de mar\u00e7o em Sergipe"},"content":{"rendered":"<div id=\"attachment_76571\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/grande-auto_escola_30_12.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-76571\" class=\"size-medium wp-image-76571\" alt=\"Foto: Reprodu\u00e7\u00e3o \" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/grande-auto_escola_30_12-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/grande-auto_escola_30_12-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/grande-auto_escola_30_12-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/grande-auto_escola_30_12-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/grande-auto_escola_30_12-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/grande-auto_escola_30_12-269x201.jpg 269w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/grande-auto_escola_30_12.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-76571\" class=\"wp-caption-text\">Foto: Reprodu\u00e7\u00e3o<\/p><\/div>\n<p style=\"text-align: justify;\">Quem vai tirar a Carteira Nacional de Habilita\u00e7\u00e3o (CNH), a partir da segunda quinzena de mar\u00e7o, em Sergipe, ter\u00e1 que pagar mais caro. O reajuste no valor do curso para formar motorista nas autoescolas sergipanas ser\u00e1 entre 10 e 20%, segundo o Sindicato dos Propriet\u00e1rios de Autoescolas e Centro de Forma\u00e7\u00e3o de Condutores do Estado de Sergipe (Sinpase).<\/p>\n<p style=\"text-align: justify;\">\u201cTeremos uma reuni\u00e3o na primeira semana de mar\u00e7o para decidir em quanto ficar\u00e1 o reajuste, a nossa inten\u00e7\u00e3o \u00e9 que o valor n\u00e3o seja elevado para o consumidor e nem prejudique as autoescolas\u201d, explicou o presidente do Sinpase, Humberto Nunes. A alta no valor dos combust\u00edveis e o aumento do sal\u00e1rio m\u00ednimo impulsionaram a decis\u00e3o pelo reajuste. \u201cTivemos o aumento no pre\u00e7o do litro da gasolina e em janeiro o sal\u00e1rio m\u00ednimo aumentou tamb\u00e9m, por isso tivemos que reavaliar nossos valores para n\u00e3o haver perdas\u201d, contou o presidente.<\/p>\n<p>O curso para formar motorista j\u00e1 tinha sido reajustado no final do ano passado por conta da resolu\u00e7\u00e3o 493\/2014 do Conselho Nacional de Tr\u00e2nsito em aumentar a carga hor\u00e1ria da categoria B (carros), que passou de 20 para 25horas\/aulas e o valor que antes era de at\u00e9 670 reais, chegou a custar at\u00e9 900 reais.<\/p>\n<p>Com o novo reajuste, o valor das aulas pr\u00e1ticas para categoria B (carros) pode chegar at\u00e9 1100 reais.<\/p>\n<p style=\"text-align: justify;\"><em>Com informa\u00e7\u00f5es do A8SE<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e no <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quem vai tirar a Carteira Nacional de Habilita\u00e7\u00e3o (CNH), a partir da segunda quinzena de mar\u00e7o, em Sergipe, ter\u00e1 que pagar mais caro. O reajuste no valor do curso para formar motorista nas autoescolas sergipanas ser\u00e1 entre 10 e 20%, segundo o Sindicato dos Propriet\u00e1rios de Autoescolas e Centro de Forma\u00e7\u00e3o de Condutores do Estado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":76571,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-76570","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/76570"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=76570"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/76570\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/76571"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=76570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=76570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=76570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}