{"id":76536,"date":"2015-02-25T21:59:25","date_gmt":"2015-02-26T00:59:25","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=76536"},"modified":"2015-02-25T22:08:14","modified_gmt":"2015-02-26T01:08:14","slug":"prf-prende-em-flagrante-dupla-armada-com-cocaina-em-areia-branca","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/prf-prende-em-flagrante-dupla-armada-com-cocaina-em-areia-branca\/","title":{"rendered":"PRF prende em flagrante dupla armada com coca\u00edna em Areia Branca"},"content":{"rendered":"<p style=\"text-align: justify;\">Na tarde de hoje (25), em Areia Branca (SE), policiais rodovi\u00e1rios federais do Grupo de Policiamento T\u00e1tico detiveram uma dupla com arma e coca\u00edna.<\/p>\n<p style=\"text-align: justify;\">\n<div style=\"text-align: justify;\">Durante fiscaliza\u00e7\u00e3o de enfrentamento a criminalidade, os agentes federais abordaram o ve\u00edculo VW\/Gol, com placas da Bahia, ocupado por dois homens, um baiano de 27 anos e outro sergipano de 22 anos, e, em revista interna ao ve\u00edculo, foram encontrados cerca de 0,5 kg de coca\u00edna e um rev\u00f3lver inox calibre 38 com quatro muni\u00e7\u00f5es.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Os policiais descobriram ainda, em consulta ao Sistema Infoseg, que um dos homens tinha passagem por roubo e o outro por tr\u00e1fico e drogas. Durante a entrevista eles informaram que adquiriram a droga em Aracaju (SE) por cerca de R$ 3 mil e pretendiam trafic\u00e1-la em Itabaiana (SE) em pequenas quantidades, totalizando um montante de R$ 10 mil. Ocorr\u00eancia encaminhada a delegacia do munic\u00edpio.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><em>Acompanhe o SE Not\u00edcias no <a href=\" https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e no <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a><\/em><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div><\/div>\n<div>\n<p><em>N\u00facleo de Comunica\u00e7\u00e3o Social<\/em><br \/>\n<em> Pol\u00edcia Rodovi\u00e1ria Federal \u2013 Sergipe<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Na tarde de hoje (25), em Areia Branca (SE), policiais rodovi\u00e1rios federais do Grupo de Policiamento T\u00e1tico detiveram uma dupla com arma e coca\u00edna. Durante fiscaliza\u00e7\u00e3o de enfrentamento a criminalidade, os agentes federais abordaram o ve\u00edculo VW\/Gol, com placas da Bahia, ocupado por dois homens, um baiano de 27 anos e outro sergipano de 22 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-76536","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-sem-categoria"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/76536"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=76536"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/76536\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=76536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=76536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=76536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}