{"id":76430,"date":"2015-02-23T09:51:59","date_gmt":"2015-02-23T12:51:59","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=76430"},"modified":"2015-02-23T09:51:59","modified_gmt":"2015-02-23T12:51:59","slug":"acidente-deixa-trafego-da-avenida-beira-mar-lento-no-inicio-da-manha","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/acidente-deixa-trafego-da-avenida-beira-mar-lento-no-inicio-da-manha\/","title":{"rendered":"Acidente deixa tr\u00e1fego da Avenida Beira Mar lento no in\u00edcio da manh\u00e3"},"content":{"rendered":"<p style=\"text-align: justify;\">Por volta das 6h desta segunda-feira (23), um acidente envolvendo um carro de passeio e um t\u00e1xi foi registrado na Avenida Beira Bar com a rot\u00e1ria que d\u00e1 acesso ao Bairro Coroa do Meio, na Zona Sul da capital. O tr\u00e1fego de ve\u00edculos ficou lento no sentido Atalaia &#8211; Centro.<br \/>\nO carro de passeio ficou atravessado na Avenida Beira Mar e o t\u00e1xi, com o impacto subiu a cal\u00e7ada.<\/p>\n<div id=\"attachment_76432\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/acidente1-e1424695843261.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-76432\" class=\"size-full wp-image-76432\" alt=\"Acidente deixa tr\u00e1fego da Avenida Beira Mar lento no in\u00edcio da manh\u00e3 (Foto: Emerson Em\u00eddio \/ G1)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/acidente1-e1424695843261.jpg\" width=\"600\" height=\"450\" \/><\/a><p id=\"caption-attachment-76432\" class=\"wp-caption-text\">Acidente deixa tr\u00e1fego da Avenida Beira Mar lento no in\u00edcio da manh\u00e3 (Foto: Emerson Em\u00eddio \/ G1)<\/p><\/div>\n<p style=\"text-align: justify;\">\u00a0<strong>Acompanhe o SE Not\u00edcias pelo <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a> e no <a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a><\/strong>.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Informa\u00e7\u00f5es do Portal G1 SE.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por volta das 6h desta segunda-feira (23), um acidente envolvendo um carro de passeio e um t\u00e1xi foi registrado na Avenida Beira Bar com a rot\u00e1ria que d\u00e1 acesso ao Bairro Coroa do Meio, na Zona Sul da capital. O tr\u00e1fego de ve\u00edculos ficou lento no sentido Atalaia &#8211; Centro. O carro de passeio ficou [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":76432,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":{"0":"post-76430","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/76430"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=76430"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/76430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/76432"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=76430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=76430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=76430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}