{"id":75942,"date":"2015-02-08T12:56:23","date_gmt":"2015-02-08T15:56:23","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=75942"},"modified":"2015-02-10T11:28:40","modified_gmt":"2015-02-10T14:28:40","slug":"prf-prende-04-elementos-com-municao-drogas-e-animais-silvestres-em-um-ponto-de-onibus-em-aracaju","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/prf-prende-04-elementos-com-municao-drogas-e-animais-silvestres-em-um-ponto-de-onibus-em-aracaju\/","title":{"rendered":"PRF prende suspeitos com drogas, muni\u00e7\u00f5es e p\u00e1ssaros silvestres"},"content":{"rendered":"<div id=\"attachment_75943\" style=\"width: 306px\" class=\"wp-caption alignright\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/prf.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-75943\" class=\"size-full wp-image-75943\" alt=\"Foto: Facebook da PRF\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/prf.jpg\" width=\"296\" height=\"394\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/prf.jpg 296w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/prf-225x300.jpg 225w\" sizes=\"(max-width: 296px) 100vw, 296px\" \/><\/a><p id=\"caption-attachment-75943\" class=\"wp-caption-text\">Foto: Facebook da PRF<\/p><\/div>\n<p style=\"text-align: justify;\">Na noite de ontem (07), em Aracaju, policiais rodovi\u00e1rios federais do Grupo de Policiamento T\u00e1tico, detiveram quatro elementos com muni\u00e7\u00e3o, drogas e animais silvestres em ponto de \u00f4nibus.<\/p>\n<p style=\"text-align: justify;\">Em fiscaliza\u00e7\u00e3o de enfrentamento a assaltos a \u00f4nibus na regi\u00e3o metropolitana de Aracaju, os agentes federais realizaram abordagem a pedestres que aguardavam o transporte coletivo em um ponto de \u00f4nibus. (1) Durante a revista pessoal, na mochila de um adolescente, de 15 anos, foram encontrados cerca de 1 kg de maconha.<\/p>\n<p style=\"text-align: justify;\">Em entrevista o adolescente afirmou ter comprado o entorpecente por R$ 1 mil nas proximidades do Atacad\u00e3o na sa\u00edda da capital. (2) J\u00e1 na sacola de um jovem adulto, foram encontrados cerca de 10g de coca\u00edna e dois p\u00e1ssaros silvestres, um azul\u00e3o e um tico-tico. Em entrevista, o homem informou que adquiriu a droga e os animais no Mercado Central de Aracaju. (3 e 4) J\u00e1 na mala de outro jovem adulto, foram encontradas 20 muni\u00e7\u00f5es calibre 38.<\/p>\n<p style=\"text-align: justify;\">Em entrevista, o homem informou que j\u00e1 havia cumprido pena no CENAM por homic\u00eddio e que havia comprado a muni\u00e7\u00e3o no Rio de Janeiro. Segundo informou, estava jurado de morte e pretendia adquirir um rev\u00f3lver em Aracaju para se defender durante o Carnaval de Ne\u00f3polis. Com ele estava ainda outro jovem adulto que portava pequena quantidade de maconha. Todos os adultos foram detidos, o adolescente apreendido e as ocorr\u00eancias encaminhadas \u00e0 delegacia plantonista em Aracaju.<\/p>\n<p style=\"text-align: justify;\"><b>Informa\u00e7\u00f5es<\/b><strong>\u00a0da PRF\/SE.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Noticias no <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e pelo <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook.<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na noite de ontem (07), em Aracaju, policiais rodovi\u00e1rios federais do Grupo de Policiamento T\u00e1tico, detiveram quatro elementos com muni\u00e7\u00e3o, drogas e animais silvestres em ponto de \u00f4nibus. Em fiscaliza\u00e7\u00e3o de enfrentamento a assaltos a \u00f4nibus na regi\u00e3o metropolitana de Aracaju, os agentes federais realizaram abordagem a pedestres que aguardavam o transporte coletivo em um [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":75943,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[310,7],"tags":[],"class_list":{"0":"post-75942","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques-da-semana","8":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/75942"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=75942"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/75942\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/75943"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=75942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=75942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=75942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}