{"id":75921,"date":"2015-02-08T10:16:24","date_gmt":"2015-02-08T13:16:24","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=75921"},"modified":"2015-02-08T10:40:16","modified_gmt":"2015-02-08T13:40:16","slug":"uau-carla-prata-ousa-em-look-para-ensaio-tecnico-em-sao-paulo","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/uau-carla-prata-ousa-em-look-para-ensaio-tecnico-em-sao-paulo\/","title":{"rendered":"Uau! Carla Prata ousa em look para ensaio t\u00e9cnico em S\u00e3o Paulo"},"content":{"rendered":"<div id=\"attachment_75926\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/carla-prata-01-e1423400815568.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-75926\" class=\"size-full wp-image-75926\" alt=\"Carla Prata (Foto: Leo Franco\/Agnews)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/carla-prata-01-e1423400815568.jpg\" width=\"600\" height=\"899\" \/><\/a><p id=\"caption-attachment-75926\" class=\"wp-caption-text\">Carla Prata (Foto: Leo Franco\/Agnews)<\/p><\/div>\n<p style=\"text-align: justify;\">Depois de gastar R$ 25 mil em fantasia para ensaio t\u00e9cnico da Uni\u00e3o da Ilha no Rio, Carla Prata desta vez resolveu ir al\u00e9m. Com um mai\u00f4 transparente, que deixava o corpo sarad\u00edssimo da rep\u00f3rter em evid\u00eancia, Carla chamou aten\u00e7\u00e3o na madrugada deste domingo, 8, no samb\u00f3dromo do Anhembi em S\u00e3o Paulo. Com brilhos estrategiamente localizados para n\u00e3o mostrar demais, a fantasia de m\u00e1gica ajudou na performance da musa da Gavi\u00f5es da Fiel.<\/p>\n<div id=\"attachment_75928\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/carla-prata-03-e1423400913328.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-75928\" class=\"size-full wp-image-75928\" alt=\"Carla Prata (Foto: Leo Franco\/Agnews)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/carla-prata-03-e1423400913328.jpg\" width=\"600\" height=\"899\" \/><\/a><p id=\"caption-attachment-75928\" class=\"wp-caption-text\">Carla Prata (Foto: Leo Franco\/Agnews)<\/p><\/div>\n<div id=\"attachment_75930\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/carla-prata-04-e1423401049116.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-75930\" class=\"size-full wp-image-75930\" alt=\"Carla Prata (Foto: Leo Franco\/Agnews)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/carla-prata-04-e1423401049116.jpg\" width=\"600\" height=\"1035\" \/><\/a><p id=\"caption-attachment-75930\" class=\"wp-caption-text\">Carla Prata (Foto: Leo Franco\/Agnews)<\/p><\/div>\n<p style=\"text-align: justify;\">Em recente entrevista ao EGO, Carla Prata contou a sua rela\u00e7\u00e3o com o carnaval. \u201cO bichinho do carnaval me picou desde pequenininha. Quando eu era crian\u00e7a, participei de um concurso de fantasia e minha m\u00e3e me perguntou que fantasia eu queria usar. Eu pedi para usar a da Globeleza. Todo mundo estava com fantasia de princesa, cigana, Branca de Neve. Quando eu era crian\u00e7a, eu queria ser a Globeleza\u201d, contou a rep\u00f3rter, que este ano tamb\u00e9m estar\u00e1 na Marqu\u00eas de Sapuca\u00ed como musa da Uni\u00e3o da Ilha.<\/p>\n<div id=\"attachment_75931\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/carla-prata-11-e1423401142707.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-75931\" class=\"size-full wp-image-75931\" alt=\"Carla Prata (Foto: Leo Franco\/Agnews)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/carla-prata-11-e1423401142707.jpg\" width=\"600\" height=\"899\" \/><\/a><p id=\"caption-attachment-75931\" class=\"wp-caption-text\">Carla Prata (Foto: Leo Franco\/Agnews)<\/p><\/div>\n<div id=\"attachment_75932\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/carla-prata-10-e1423401235251.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-75932\" class=\"size-full wp-image-75932\" alt=\"Carla Prata (Foto: Leo Franco\/Agnews)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2015\/02\/carla-prata-10-e1423401235251.jpg\" width=\"600\" height=\"899\" \/><\/a><p id=\"caption-attachment-75932\" class=\"wp-caption-text\">Carla Prata (Foto: Leo Franco\/Agnews)<\/p><\/div>\n<p style=\"text-align: justify;\"><b>Informa\u00e7\u00f5es<\/b><strong>\u00a0do Portal ego.globo.com<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe o SE Noticias no <a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter <\/a>e pelo <a href=\" https:\/\/www.facebook.com\/PortalSENoticias\" target=\"_blank\">Facebook<\/a>.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depois de gastar R$ 25 mil em fantasia para ensaio t\u00e9cnico da Uni\u00e3o da Ilha no Rio, Carla Prata desta vez resolveu ir al\u00e9m. Com um mai\u00f4 transparente, que deixava o corpo sarad\u00edssimo da rep\u00f3rter em evid\u00eancia, Carla chamou aten\u00e7\u00e3o na madrugada deste domingo, 8, no samb\u00f3dromo do Anhembi em S\u00e3o Paulo. Com brilhos estrategiamente [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":75926,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[310,22],"tags":[],"class_list":{"0":"post-75921","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques-da-semana","8":"category-famosos"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/75921"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=75921"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/75921\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/75926"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=75921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=75921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=75921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}